{"id":7101,"date":"2020-07-10T08:23:07","date_gmt":"2020-07-10T06:23:07","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=7101"},"modified":"2020-08-28T17:20:52","modified_gmt":"2020-08-28T15:20:52","slug":"aac-balisages-penser-les-donnees-par-le-territoire","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/","title":{"rendered":"Penser les donn\u00e9es par le territoire ?"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> <time class=\"pubdate-time\" pubdate datetime=\"2020-07-10T08:23:07+02:00\">10 juillet 2020<\/time>\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-information-documents-ecritures\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/information-documents-ecritures\/\" title=\"Information, documents et \u00e9critures\"><span class=\"termslist-itemname\">Information, documents et \u00e9critures<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-numerique-strategies-dispositifs-usages\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/numerique-strategies-dispositifs-usages\/\" title=\"Num\u00e9rique : strat\u00e9gies, dispositifs et usages\"><span class=\"termslist-itemname\">Num\u00e9rique : strat\u00e9gies, dispositifs et usages<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>01\/09\/2020<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>R\u00e9sum\u00e9<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Balisages<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-coordinators\">\n<h3 class=\"zn-singledetail-section-title\">Coordinateurs<\/h3>\n<ul class=\"zn-singledetail-coordinators-list\">\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Emmanuel<\/span> <span>Brandl<\/span>, <span>Enssib, Max Weber \u2013 UDL<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:emmanuel.brandl@enssib.fr\">emmanuel.brandl@enssib.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Geoffroy<\/span> <span>Gawin<\/span>, <span>Enssib, Elico \u2013 UDL<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:geoffroy.gawin@enssib.fr\">geoffroy.gawin@enssib.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Val\u00e9rie<\/span> <span>Larroche<\/span>, <span>Enssib, Elico \u2013 UDL<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:valerie.larroche@enssib.fr\">valerie.larroche@enssib.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-contacts\">\n<h3 class=\"zn-singledetail-section-title\">Contacts<\/h3>\n<ul class=\"zn-singledetail-contacts-list\">\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">test<\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:test@test.com\">test@test.com<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/publications-prairial.fr\/balisages\/\" title=\"Site de la revue\" target=\"_blank\" rel=\"noopener noreferrer\">Site de la revue<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<p>La notion de territoire num\u00e9rique est surtout employ\u00e9e pour d\u00e9signer des projets d\u2019am\u00e9nagement du territoire par des r\u00e9seaux num\u00e9riques et des projets de collecte et de traitement de donn\u00e9es li\u00e9s un espace g\u00e9ographique (ville, m\u00e9tropole, etc.). En d\u2019autres termes, le territoire num\u00e9rique se r\u00e9duit souvent \u00e0 un territoire num\u00e9riquement accompagn\u00e9 (Pag\u00e8s, 2010). Cet appel vise \u00e0 \u00e9largir le champ en consid\u00e9rant le territoire du point de vue du cyberespace d\u00e9fini comme un espace num\u00e9rique constitu\u00e9 de l\u2019ensemble des syst\u00e8mes d\u2019information plan\u00e9taires (Musso, 2008), ces diff\u00e9rents syst\u00e8mes \u00e9tant constitu\u00e9s de donn\u00e9es. Mobiliser la notion de territoire avec l\u2019emploi de l\u2019expression territoire num\u00e9rique pour caract\u00e9riser le cyberespace, qui \u00e9voque pour la plupart des internautes tout \u00e0 la fois \u00ab&#160;un \u201cmonde\u201d virtuel, d\u00e9mat\u00e9rialis\u00e9, sans fronti\u00e8res, anonyme, de libert\u00e9s, de partage et de communication&#160;\u00bb (Desforges, 2014, p. 67), repose sur trois hypoth\u00e8ses. La premi\u00e8re souligne la possibilit\u00e9 de rattacher au cyberespace quelques caract\u00e9ristiques territoriales comme la population (les internautes) et son mode de gouvernance (l\u2019autor\u00e9gulation) (Desforges, 2014, p. 74)&#160;; la deuxi\u00e8me suppose l\u2019existence d\u2019un rapprochement entre les donn\u00e9es, leurs agencements (Callon, 2013&#160;; Soulier, 2014) et la notion de territoire num\u00e9rique. Enfin la derni\u00e8re suppose que les donn\u00e9es sont constitutives des informations, des connaissances et des savoirs construits et circulant dans le cyberespace.<\/p>\n<p>Les interrogations que ce dossier vise \u00e0 soulever portent sur les trois axes suivants&#160;: le territoire num\u00e9rique a-t-il un potentiel heuristique pour \u00e9tudier le cyberespace comme syst\u00e8me de donn\u00e9es&#160;? Quels seraient les savoirs constitutifs du ou des territoires num\u00e9riques&#160;? Enfin, l\u2019exp\u00e9rience du cyberespace, telle qu\u2019elle est v\u00e9cue par les cybernautes, structure-t-elle et d\u00e9termine-t-elle la notion de territoire num\u00e9rique&#160;?<\/p>\n<p>Ces trois axes sont un moyen de pr\u00e9ciser le contour de cet appel et de sugg\u00e9rer des interrogations ou des discussions sans toutefois avoir la pr\u00e9tention d\u2019\u00eatre exhaustif. Les auteurs peuvent donc proposer d\u2019autres pistes de r\u00e9flexion, dans les limites du p\u00e9rim\u00e8tre de ce num\u00e9ro. Des descriptions pr\u00e9cises des cadres th\u00e9oriques, des concepts et des d\u00e9marches m\u00e9thodologiques seront particuli\u00e8rement appr\u00e9ci\u00e9es.<\/p>\n<h3>Axe 1. Le territoire num\u00e9rique&#160;: un potentiel heuristique&#160;?<\/h3>\n<p>Le lien territoire-donn\u00e9e nourrit ce premier axe en consid\u00e9rant le territoire comme une notion heuristique qui permet de penser les activit\u00e9s, les pratiques, les valeurs, voire les objets li\u00e9s aux donn\u00e9es num\u00e9riques.<\/p>\n<p>Il nous semble donc int\u00e9ressant dans cet appel d\u2019employer la notion de territoire num\u00e9rique dont les contours peuvent \u00eatre dessin\u00e9s en r\u00e9interrogeant les principales caract\u00e9ristiques du territoire \u00e0 l\u2019aune des donn\u00e9es&#160;: les dimensions spatiale, culturelle ou historique&#160;; les autorit\u00e9s qui s\u2019y exercent (Le Roux, Th\u00e9bault, 2018, p. 58)&#160;; les types de distances qu\u2019il met en jeu \u2013 physique, sociale ou symbolique&#160;; les fronti\u00e8res qui s\u2019y dessinent (L\u00e9vy, Lussault, 2013)&#160;; les lieux qu\u2019il relie&#160;; les rapports au temps qui s\u2019y d\u00e9ploient, tant en termes d\u2019\u00e9paisseurs que de r\u00e9gimes (Dupont, 2019). Certains aspects propres aux donn\u00e9es devraient de m\u00eame \u00eatre pris en consid\u00e9ration comme les possibilit\u00e9s d\u2019interop\u00e9rabilit\u00e9 qu\u2019elles offrent, les fonctions assur\u00e9es par les m\u00e9tadonn\u00e9es ou encore l\u2019importance de leur documentation (Jacquemin et al., 2018).<\/p>\n<p>Les contributions de cet axe sont invit\u00e9es \u00e0 v\u00e9rifier si les dispositifs socionum\u00e9riques traitant des donn\u00e9es d\u00e9finissent un contexte particulier que la notion de territoire num\u00e9rique appr\u00e9hende de mani\u00e8re originale. D\u2019un point de vue culturel, est-ce que la m\u00e9diation de plateformes comme Facebook ou YouTube, ou celle de dispositifs num\u00e9riques de visioconf\u00e9rence r\u00e9unissent les conditions d\u2019un vivre-ensemble (Caune, 2017), de rencontres (Le Bourlot, 2011) ou au contraire ne permettent pas d\u2019aller au-del\u00e0 d\u2019un c\u00f4toiement&#160;? D\u00e8s lors, serait-il possible de voir en leur sein l\u2019\u00e9laboration de modalit\u00e9s sp\u00e9cifiques d&rsquo;interpr\u00e9tation des donn\u00e9es qui en feraient de v\u00e9ritables territoires avec leurs propres valeurs, des rapports aux autres typiques et une conscience historique originale&#160;?<\/p>\n<p>De fa\u00e7on plus fondamentale, il conviendrait d\u2019interroger le statut de territoire num\u00e9rique, de comprendre s\u2019il s\u2019apparente davantage \u00e0 une figure discursive (Bonhomme, 2014) ou \u00e0 un concept \u00e9volutif des sciences de l\u2019information et de la communication, comme le concept d\u2019information (Gardi\u00e8s, 2012).<\/p>\n<h3>Axe 2. Les savoirs constitutifs du territoire num\u00e9rique<\/h3>\n<p>L\u2019association de territoire et de donn\u00e9e propos\u00e9e dans cet appel ouvre aussi sur une perspective se r\u00e9clamant de l\u2019anthropologie des savoirs (Maury, Kovacs, Marteleto, 2014), car elle invite \u00e0 s\u2019int\u00e9resser \u00e0 la production, \u00e0 l\u2019\u00e9change et \u00e0 la circulation d\u2019informations et de savoirs. Nous supposons dans cet axe que les espaces virtuels ne sont pas uniquement des lieux de savoir (Jacob, 2014) mais des territoires num\u00e9riques. En effet, les savoirs produits par des activit\u00e9s collaboratives dans un contexte num\u00e9rique dessinent des espaces (De Certeau, 1990) dot\u00e9s de fronti\u00e8res souples o\u00f9 les humains, les savoirs, les \u00e9crits d\u2019\u00e9cran (Souchier, 1996&#160;; Jeanneret, 2000) et les objets techniques sont en interaction. \u00c0 titre d\u2019illustration, une th\u00e9matique pr\u00e9sente dans la plateforme Wikipedia (Levrel, 2006) peut \u00eatre le point de d\u00e9part de l\u2019exploration d\u2019un territoire num\u00e9rique. Une m\u00e9thode possible pour caract\u00e9riser ce dernier reposerait \u00e0 la fois sur le suivi des liens internes et externes, et sur l\u2019analyse des activit\u00e9s et des interactions (Dujarier, 2016) li\u00e9es au processus d\u2019\u00e9criture num\u00e9rique collaborative. Les contributeurs pourront ainsi analyser la nature des savoirs constitutifs des territoires num\u00e9riques (savoirs techniques, savoirs culturels, savoirs d\u2019experts, savoirs na\u00effs, savoir-faire, etc.) et la mani\u00e8re dont ils participent \u00e0 une territorialisation.<\/p>\n<p>Dans une autre perspective, les relations entre savoir et donn\u00e9es pourront \u00eatre approfondies en mobilisant par exemple les notions de territoire num\u00e9rique de marques (Le B\u00e9chec, Alloing, 2018), de fiction circulante (Ibid.) et d\u2019\u00eatre culturel (Jeanneret, 2008). Les auteurs pourront ainsi se demander si les modalit\u00e9s de transmission des connaissances et des savoirs contribuent \u00e0 l\u2019\u00e9closion d\u2019identit\u00e9s collectives singuli\u00e8res et participent \u00e0 l\u2019\u00e9volution des interpr\u00e9tations, faisant des outils num\u00e9riques de v\u00e9ritables creusets.<\/p>\n<p>En d\u2019autres termes, interroger la relation entre savoir et territoire pour aborder les donn\u00e9es, les m\u00e9tadonn\u00e9es, les traces et l\u2019information dans un contexte d\u2019\u00e9criture num\u00e9rique collective ouvre de nombreuses perspectives d\u2019exploration.<\/p>\n<h3>Axe 3. L&rsquo;exp\u00e9rience du cyberespace comme territoire num\u00e9rique<\/h3>\n<p>Les savoirs, les connaissances, les territoires, qu\u2019ils soient g\u00e9ographiques ou num\u00e9riques, ne seraient rien sans des individus en interaction directe ou \u00ab&#160;\u00e0 distance&#160;\u00bb (Flichy, 2005) les uns avec les autres. Ainsi, les humains eux-m\u00eames et les communaut\u00e9s qu\u2019ils forment participent aussi des ressources pr\u00e9sentes et \u00e0 venir d\u2019un territoire.<\/p>\n<p>Cet axe place au c\u0153ur de son interrogation l\u2019exp\u00e9rience sociale (Dubet, 2016) individuelle et collective du cyberespace, entendu comme l\u2019ensemble de dispositifs socionum\u00e9riques (Larroche, 2018). Toutefois, notre approche de l\u2019exp\u00e9rience sociale r\u00e9int\u00e8gre le poids de la socialisation comme variable explicative des exp\u00e9riences et des comportements. Il s\u2019agit de comprendre les conditions sociales \u00e0 partir desquelles les exp\u00e9riences des acteurs font territoire. Les individus eux-m\u00eames, simples usagers d\u2019Internet ou professionnels de l&rsquo;informatique, ont-ils le sentiment explicite ou diffus d\u2019\u00e9voluer sur un territoire&#160;? Au-del\u00e0 des affects, les savoirs incorpor\u00e9s propres \u00e0 l\u2019exp\u00e9rience sociale, culturelle ou politique du territoire (g\u00e9ographique, urbain, politico-administratif\u2026), et qui fonctionnent comme des habitus (Elias, 2003), structurent-ils notre rapport aux dispositifs socionum\u00e9riques&#160;? C\u2019est-\u00e0-dire en quoi d\u00e9terminent-ils aussi bien les usages, les pratiques que les repr\u00e9sentations que l\u2019on a et que l\u2019on se fait des dispositifs socionum\u00e9riques&#160;? En un mot, l\u2019impens\u00e9 (Robert, 2012) territorial ne structure-t-il pas notre rapport au cyberespace&#160;?<\/p>\n<p>Les auteurs pourront ainsi revenir sur les processus exp\u00e9rientiels de territorialisation num\u00e9rique. Ils pourront par exemple s\u2019appuyer sur l\u2019analyse des r\u00e9cits que les individus livrent de leurs exp\u00e9riences du cyberespace pour montrer qu\u2019elles r\u00e9f\u00e8rent implicitement, voire explicitement, au territoire, aussi bien au niveau du champ s\u00e9mantique qu\u2019au niveau des \u00ab&#160;mani\u00e8res de faire&#160;\u00bb (Becker, 1988) elles-m\u00eames.<\/p>\n<h2>Calendrier<\/h2>\n<p>4 mai 2020&#160;: diffusion de l\u2019appel \u00e0 article<\/p>\n<p>1er septembre 2020&#160;: soumission des propositions d\u2019articles (entre 3000 et 5000 signes espaces compris, hors bibliographie) (report)<\/p>\n<p>21 septembre 2020&#160;: r\u00e9ponse d\u2019acceptation ou de rejet des propositions (report)<\/p>\n<p>4 janvier 2021&#160;: date limite de r\u00e9ception des articles complets pour \u00e9valuation (report)<\/p>\n<p>8 f\u00e9vrier 2021&#160;: retour des commentaires des \u00e9valuations aux auteur.e.s (report)<\/p>\n<p>22 mars 2021&#160;: date limite de r\u00e9ception des versions finales (report)<\/p>\n<p>Juin 2021&#160;: parution du n\u00b0 3 de la revue Balisages (report)<\/p>\n<h2>Modalit\u00e9s de soumission et d\u2019\u00e9valuation<\/h2>\n<p>Les contributions peuvent \u00eatre soumises au choix en fran\u00e7ais ou en anglais.<\/p>\n<p>Les propositions de soumission doivent comprendre entre 3000 et 5000 caract\u00e8res (espaces compris, hors bibliographie) et \u00eatre anonymis\u00e9es.<\/p>\n<p>Les articles totaliseront quant \u00e0 eux entre 30 000 et 40 000 caract\u00e8res (espaces et bibliographie compris) et \u00eatre anonymis\u00e9s.<\/p>\n<p>Les auteurs sont invit\u00e9s \u00e0 respecter <a href=\"https:\/\/publications-prairial.fr\/balisages\/index.php?id=415\">les recommandations aux auteurs<\/a> concernant la qualit\u00e9 de formalisation scientifique, la mise en forme du texte et la normalisation des r\u00e9f\u00e9rences bibliographiques.<\/p>\n<p>Les propositions doivent \u00eatre envoy\u00e9es au format de leur choix&#160;: doc, odt ou md aux trois coordinateurs de ce num\u00e9ro th\u00e9matique, Val\u00e9rie Larroche (<a href=\"mailto:valerie.larroche@enssib.fr\">valerie.larroche@enssib.fr<\/a>), Geoffroy Gawin (<a href=\"mailto:geoffroy.gawin@enssib.fr\">geoffroy.gawin@enssib.fr<\/a>), Emmanuel Brandl (<a href=\"mailto:emmanuel.brandl@enssib.fr\">emmanuel.brandl@enssib.fr<\/a>).<\/p>\n<p>Les textes feront l\u2019objet de deux \u00e9valuations, selon une double proc\u00e9dure d\u2019\u00e9valuation anonyme, par un comit\u00e9 de lecture, dont les membres seront s\u00e9lectionn\u00e9s en fonction de leur domaine d\u2019expertise, \u00e0 r\u00e9ception des articles.<\/p>\n<h2>Comit\u00e9 de lecture<\/h2>\n<p>Ses membres sont charg\u00e9s de la proc\u00e9dure d\u2019\u00e9valuation en double aveugle. Le comit\u00e9 est renouvel\u00e9 \u00e0 chaque num\u00e9ro th\u00e9matique en fonction du domaine d\u2019expertise sollicit\u00e9.<\/p>\n<h2>Bibliographie<\/h2>\n<p>Becker H.S. (1988), Les mondes de l\u2019art, Paris, Flammarion.<\/p>\n<p>Bonhomme M. (2014), Pragmatique des figures du discours, Paris, H. Champion.<\/p>\n<p>Callon M. (2013), Qu\u2019est-ce qu\u2019un agencement marchand&#160;? in Callon Michel et al., Sociologie des agencements marchands, Paris, Presses des Mines, p. 325-440.<\/p>\n<p>Caune J. (2017), La m\u00e9diation culturelle. Exp\u00e9rience esth\u00e9tique et construction du Vivre-ensemble, Fontaine, Presses Universitaire de Grenoble.<\/p>\n<p>Certeau M. (de) (1990), L\u2019invention du quotidien. 1. Arts de faire, Paris, \u00c9ditions Gallimard.<\/p>\n<p>Desforges A. (2014), Les repr\u00e9sentations du cyberespace&#160;: un outil g\u00e9opolitique, H\u00e9rodote, 152-153, 67-81.<\/p>\n<p>Dubet F. (1995), Sociologie de l\u2019exp\u00e9rience, Paris, Seuil.<\/p>\n<p>Dujarier M.-A. (dir.) (2016), L\u2019activit\u00e9 en th\u00e9ories &#8211; Regards crois\u00e9s sur le travail, Tome I, Toulouse, Octar\u00e8s.<\/p>\n<p>Dupont O. (2019), Distance, proximit\u00e9, \u00e9paisseur et acc\u00e9l\u00e9ration&#160;: reconfigurations temporelles et lien social&#160;\u00bb, Kairos [En ligne], 3, URL&#160;: <a href=\"http:\/\/revues-msh.uca.fr\/kairos\/index.php?id=202\">http:\/\/revues-msh.uca.fr\/kairos\/index.php?id=202<\/a>.<\/p>\n<p>Gardi\u00e8s C. (dir.) (2012), Approche de l&rsquo;information-documentation. Concepts fondateurs, Toulouse, C\u00e9padu\u00e8s.<\/p>\n<p>Elias N. (1991), La Civilisation des m\u0153urs, Paris, Calmann-L\u00e9vy, coll. \u00ab&#160;Libert\u00e9 de l\u2019esprit&#160;\u00bb.<\/p>\n<p>Flichy P. (2005), \u00ab&#160;Les r\u00e9seaux de t\u00e9l\u00e9communications instruments et outils de mesure de la sociabilit\u00e9&#160;\u00bb, Flux, 62, 31-37.<\/p>\n<p>Jacquemin B., Sch\u00f6pfel J., Chaudiron S., Kergosien E. (2018), L\u2019\u00e9thique des donn\u00e9es de la recherche en sciences humaines et sociales. Une introduction. In&#160;: 6e conf\u00e9rence \u201dDocument num\u00e9rique Soci\u00e9t\u00e9\u201d. \u00c9chirolles, France&#160;: s.n. septembre 2018. p. 71\u201186.<\/p>\n<p>Jacob C. (2014), Qu\u2019est-ce qu\u2019un lieu de savoir&#160;? Marseille, OpenEdition Press.<\/p>\n<p>Jeanneret Y. (2000), Y-a-t-il (vraiment) des technologies de l\u2019information&#160;? Villeneuve d&rsquo;Ascq, Presses universitaires du Septentrion.<\/p>\n<p>Jeanneret Y. (2008), Penser la trivialit\u00e9. Volume 1&#160;: La vie triviale des \u00eatres culturels, Paris, \u00c9d. Herm\u00e8s-Lavoisier, coll. Communication, m\u00e9diation et construits sociaux.<\/p>\n<p>Larroche V. (2018), Le dispositif. Un concept pour les sciences de l&rsquo;information et de la communication, Iste editions, Londres.<\/p>\n<p>Le B\u00e9chec M., Alloing C. (2018), Les territoires num\u00e9riques de marques pour repenser les cadres d\u2019analyse du web. Questions de communication, 34, 7-20.<\/p>\n<p>Le Bourlot M. (2011), Du passage possible de l&rsquo;objet virtuel \u00e0 l&rsquo;objet sujet. \u00c9tude sur la relation par internet, Perspectives Psy, 50, 133-138.<\/p>\n<p>Le Roux A., Th\u00e9bault M. (2018), \u202aTerritoire et territoire num\u00e9rique de la r\u00e9sistance des consommateurs \u202a&#160;: Une \u00e9tude exploratoire, Questions de communication, 34, 55-74.<\/p>\n<p>Levrel, J. (2006), Wikipedia, un dispositif m\u00e9diatique de publics participants. R\u00e9seaux, 138, 185-218.<\/p>\n<p>L\u00e9vy J., Lussault M. (2013), Fronti\u00e8re, In Le dictionnaire de la g\u00e9ographie et de l&rsquo;espace des soci\u00e9t\u00e9s, Paris, Belin.<\/p>\n<p>Maury Y., Kovacs S., Marteleto R. (2014), \u00ab&#160;Introduction&#160;\u00bb, \u00c9tudes de communication, 42, 9-14.<\/p>\n<p>Musso P. (2008), Territoires num\u00e9riques, M\u00e9dium, 15, 25-38.<\/p>\n<p>Robert P. (2012), L\u2019impens\u00e9 informatique. Critique du mode d\u2019existence id\u00e9ologique des technologies de l\u2019information et de la communication, Volume\u202fI&#160;: les ann\u00e9es 1970-1980, Paris, \u00c9ditions des archives contemporaines.<\/p>\n<p>Souchier E. (1996), L&rsquo;\u00e9crit d&rsquo;\u00e9cran, pratiques d&rsquo;\u00e9criture &amp; informatique, Communication &amp; Langages, 107, 105-119.<\/p>\n<p>Soulier E. (2014), Introduction. Les humanit\u00e9s num\u00e9riques sont-elles des agencements&#160;? Les cahiers du num\u00e9rique, 4, 9-40.<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-donnees\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/donnees\/\" title=\"donn\u00e9es\"><span class=\"termslist-itemname\">donn\u00e9es<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-territoire\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/territoire\/\" title=\"territoire\"><span class=\"termslist-itemname\">territoire<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 10 juillet 2020 Th\u00e9matiques Information, documents et \u00e9critures Num\u00e9rique : strat\u00e9gies, dispositifs et usages R\u00e9ponse attendue pour le 01\/09\/2020 Type de r\u00e9ponse R\u00e9sum\u00e9 Type de contribution [&hellip;]<\/p>\n","protected":false},"author":957,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[128,78],"thematique":[40,39],"sfsic":[],"class_list":["post-7101","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-donnees","tag-territoire","thematique-information-documents-et-ecritures","thematique-numerique-strategies-dispositifs-et-usages","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Penser les donn\u00e9es par le territoire ?<\/title>\n<meta name=\"description\" content=\"La revue de recherche de l&#039;Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l&#039;anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Penser les donn\u00e9es par le territoire ?\" \/>\n<meta property=\"og:description\" content=\"La revue de recherche de l&#039;Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l&#039;anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T06:23:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-28T15:20:52+00:00\" \/>\n<meta name=\"author\" content=\"Fabien Bonnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/\"},\"author\":{\"name\":\"Fabien Bonnet\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/9f83573bda33f40c68c7c826e9567df6\"},\"headline\":\"Penser les donn\u00e9es par le territoire ?\",\"datePublished\":\"2020-07-10T06:23:07+00:00\",\"dateModified\":\"2020-08-28T15:20:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/\"},\"wordCount\":2287,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Donn\u00e9es\",\"Territoire\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/\",\"name\":\"Penser les donn\u00e9es par le territoire ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2020-07-10T06:23:07+00:00\",\"dateModified\":\"2020-08-28T15:20:52+00:00\",\"description\":\"La revue de recherche de l'Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l'anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/aac-balisages-penser-les-donnees-par-le-territoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Penser les donn\u00e9es par le territoire&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/9f83573bda33f40c68c7c826e9567df6\",\"name\":\"Fabien Bonnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g\",\"caption\":\"Fabien Bonnet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Penser les donn\u00e9es par le territoire ?","description":"La revue de recherche de l'Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l'anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/","og_locale":"en_US","og_type":"article","og_title":"Penser les donn\u00e9es par le territoire ?","og_description":"La revue de recherche de l'Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l'anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/","og_site_name":"SFSIC","article_published_time":"2020-07-10T06:23:07+00:00","article_modified_time":"2020-08-28T15:20:52+00:00","author":"Fabien Bonnet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/"},"author":{"name":"Fabien Bonnet","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/9f83573bda33f40c68c7c826e9567df6"},"headline":"Penser les donn\u00e9es par le territoire ?","datePublished":"2020-07-10T06:23:07+00:00","dateModified":"2020-08-28T15:20:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/"},"wordCount":2287,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Donn\u00e9es","Territoire"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/","name":"Penser les donn\u00e9es par le territoire ?","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2020-07-10T06:23:07+00:00","dateModified":"2020-08-28T15:20:52+00:00","description":"La revue de recherche de l'Enssib Balisages, situ\u00e9e \u00e0 la crois\u00e9e des SIC et de l'anthropologie des savoirs, lance un appel \u00e0 articles pour le dossier du num\u00e9ro 3 \u00ab Penser les donn\u00e9es par le territoire ? \u00bb, coordonn\u00e9 par Emmanuel Brandl (Enssib, Max Weber), Geoffroy Gawin (Enssib, Elico) et Val\u00e9rie Larroche (Enssib, Elico ).","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/aac-balisages-penser-les-donnees-par-le-territoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"Penser les donn\u00e9es par le territoire&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/9f83573bda33f40c68c7c826e9567df6","name":"Fabien Bonnet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88a9288fc13369cb9e30359afa340f8adace82098c18ff09415c6dacd710ddc4?s=96&d=mm&r=g","caption":"Fabien Bonnet"}}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/7101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/957"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=7101"}],"version-history":[{"count":3,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/7101\/revisions"}],"predecessor-version":[{"id":7189,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/7101\/revisions\/7189"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=7101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=7101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=7101"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=7101"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=7101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}