{"id":34101,"date":"2025-05-29T21:25:22","date_gmt":"2025-05-29T19:25:22","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=34101"},"modified":"2025-06-05T10:57:48","modified_gmt":"2025-06-05T08:57:48","slug":"corps-stigmatises-en-contexte-numerique","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/","title":{"rendered":"Corps stigmatis\u00e9s en contexte num\u00e9rique"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> <time class=\"pubdate-time\" pubdate datetime=\"2025-05-29T21:25:22+02:00\">29 mai 2025<\/time>\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-numerique-strategies-dispositifs-et-usages\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/numerique-strategies-dispositifs-et-usages\/\" title=\"Num\u00e9rique : strat\u00e9gies, dispositifs et usages\"><span class=\"termslist-itemname\">Num\u00e9rique : strat\u00e9gies, dispositifs et usages<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>03\/02\/2026<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>R\u00e9sum\u00e9<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Questions de communication<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/37851\" title=\"Site de la revue\" target=\"_blank\">Site de la revue<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<div class=\"textandnotes\">\n<p>La revue \u00ab&#160;Questions de communication&#160;\u00bb lance un appel \u00e0 articles intitul\u00e9 \u00ab&#160;Corps stigmatis\u00e9s en contexte num\u00e9rique&#160;\u00bb. le dossier est coordonn\u00e9 par H\u00e9l\u00e8ne Bourdeloie (LabSIC, Universit\u00e9 Sorbonne Paris Nord), Yann Bruna (Sophiapol, Universit\u00e9 Paris-Nanterre) et Dimitra Laurence Larochelle (Irm\u00e9ccen, Universit\u00e9 Sorbonne Nouvelle)<\/p>\n<h2>Pr\u00e9sentation<\/h2>\n<p class=\"texte\">Appareil physique et symbolique caract\u00e9risant l\u2019\u00eatre humain (Le Breton, 2008), le corps est soumis \u00e0 des normes et injonctions permanentes qui d\u00e9terminent sa l\u00e9gitimit\u00e9. Ces normes variables selon des cat\u00e9gories telles que le genre, la classe, la race<a id=\"bodyftn1\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/37851#ftn1\">1<\/a>, la sexualit\u00e9 ou encore l\u2019\u00e2ge, construisent un id\u00e9al corporel fond\u00e9 sur l\u2019accumulation de crit\u00e8res multiples, auxquels le corps est cens\u00e9 se conformer. Historiquement ancr\u00e9e, cette codification du corps s\u2019est s\u2019accompagn\u00e9e de processus de stigmatisation et de domination engendr\u00e9s par les imaginaires imp\u00e9rialistes et postcoloniaux (Tonda, 2015), et les syst\u00e8mes de classements sociaux (Bourdieu, 1979) ont contribu\u00e9 \u00e0 construire des corps socialement diff\u00e9renci\u00e9s et \u00e0 \u00e9tablir une hi\u00e9rarchie de l\u00e9gitimit\u00e9 entre eux. D\u00e8s lors, le corps est devenu un enjeu central dans la reproduction des rapports de pouvoir et des in\u00e9galit\u00e9s sociales.<br \/>\nCe faisant, les corps les plus h\u00e9g\u00e9moniques \u2013 \u00e0 la mani\u00e8re des corps blancs, minces, valides, pr\u00e9sum\u00e9s h\u00e9t\u00e9rosexuels ou cisgenres vus comme standards (Carof, 2021) dans les soci\u00e9t\u00e9s occidentales contemporaines \u2013 peuvent \u00eatre pens\u00e9s comme <em>major\u00e9s<\/em>, car gratifi\u00e9s d\u2019une valeur ajout\u00e9e qui contribue \u00e0 les situer socialement et \u00e0 fa\u00e7onner positivement les discours et les regards qui sont port\u00e9s sur eux. Au contraire, les corps auxquels nous nous int\u00e9resserons ici, <em>minor\u00e9s<\/em><a id=\"bodyftn2\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/37851#ftn2\">2<\/a> car priv\u00e9s des fonctions, attributs, traits ou formes qui caract\u00e9risent les corps dominants ou pr\u00e9tendus \u00ab&#160;normaux&#160;\u00bb par la soci\u00e9t\u00e9, sont \u00e9loign\u00e9s de ces standards. De fait, toute marque corporelle de diff\u00e9rence, qu\u2019elle soit ostensiblement visible ou qu\u2019elle fasse l\u2019objet d\u2019une tentative de dissimulation, est souvent per\u00e7ue comme une d\u00e9viance&#160;; cela pu \u00eatre observ\u00e9 dans le cas de certaines orientations sexuelles ou identifications de genre (Mac\u00e9, 2010).<br \/>\nCette diff\u00e9rence op\u00e8re comme un stigmate au sens goffmanien du terme (Goffman, 1975)<a id=\"bodyftn3\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/37851#ftn3\">3<\/a>, engendrant des processus de discrimination, voire de pathologisation \u00e0 l\u2019encontre des corps handicap\u00e9s, trans, gros, maigres, malades ou racis\u00e9s. Cette stigmatisation se traduit par des difficult\u00e9s \u00e0 exposer ces corps dans l\u2019espace public et \u00e0 les y faire pleinement accepter (H\u00e9as et Darg\u00e8re, 2014), le risque de sanctions sociales y \u00e9tant plus \u00e9lev\u00e9. En t\u00e9moignent les cas de personnes m\u00e9dicalement d\u00e9sign\u00e9es comme ob\u00e8ses ou en surpoids (Burford et Orchard, 2014), ou encore de femmes homosexuelles (Nicaise, 2017). Toutefois, dans une logique de r\u00e9sistance, le corps peut \u00eatre expos\u00e9 selon des strat\u00e9gies de r\u00e9appropriation ou de dissimulation, \u00e0 l\u2019exemple de femmes se d\u00e9finissant comme \u00ab&#160;gouines&#160;\u00bb<a id=\"bodyftn4\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/37851#ftn4\">4<\/a> et qui, pour \u00e9chapper au stigmate dans l\u2019espace urbain, surinvestissent des actes de f\u00e9minit\u00e9 pour \u00eatre identifi\u00e9es comme h\u00e9t\u00e9rosexuelles et se conformer \u00e0 la norme dominante (<em>ibid.<\/em>).<\/p>\n<\/div>\n<p class=\"texte\">\u00c0 cette th\u00e9matique abondamment trait\u00e9e dans le champ de la sociologie du corps, s\u2019ajoute d\u00e9sormais une variable d\u00e9terminante qui influence les discours et regards port\u00e9s sur les corps&#160;: les dispositifs socio-num\u00e9riques. Ax\u00e9s sur le partage de contenus visuels, ces dispositifs pourraient jouer un r\u00f4le cl\u00e9 dans la reconfiguration des repr\u00e9sentations corporelles, quelles qu\u2019elles soient. C\u2019est autour de cette probl\u00e9matique que ce dossier entend s\u2019articuler, en interrogeant la mani\u00e8re dont ces dispositifs red\u00e9finissent les normes et imaginaires associ\u00e9s aux corps. En ligne, l\u2019exposition corporelle n\u2019est effectivement pas sujette aux m\u00eames normes ou injonctions. Pour reprendre le vocabulaire de Sherry Turkle (1995), l\u2019identit\u00e9 s\u2019y d\u00e9plie et la pluralit\u00e9 des subjectivit\u00e9s s\u2019exprime. Encourag\u00e9s par une forme d\u2019impudeur corporelle propre aux RSN (Denou\u00ebl et Granjon, 2011), les corps et les communaut\u00e9s stigmatis\u00e9s sont davantage repr\u00e9sent\u00e9s (Yeshua-Katz et H\u00e5rd af Segerstad, 2020).<br \/>\nDes individus atteints de pathologies dermatologiques rares ou en situation de handicap physique choisissent de \u00ab&#160;se raconter en ligne en d\u00e9ployant des strat\u00e9gies de repr\u00e9sentation de soi et de gestion, du regard des impressions d\u2019autrui&#160;\u00bb (Husson et Sedda, 2022). Ainsi des recherches conduites au cours des deux derni\u00e8res d\u00e9cennies tendent-elles \u00e0 montrer que, en ligne, le stigmate pourrait constituer un \u00e9l\u00e9ment de valorisation (Sedda et Botero, 2022), une marque de fabrique (Bourdeloie, 2021), une marchandise (Illouz, 2006), voire une arme pour faire valoir un droit ou un statut (Fassin et Rechtman, 2007).<br \/>\nDe fait, les formes pr\u00e9liminaires de r\u00e9sistance au stigmate (\u00ab&#160;oui je suis ainsi et alors&#160;?&#160;\u00bb) pourraient plus facilement aboutir \u00e0 son retournement, tel que th\u00e9oris\u00e9 par Louis Gruel (1985) dans sa sociologie des quartiers d\u00e9favoris\u00e9s. La propagation d\u2019images de corps peut conduire \u00e0 leur acceptation (Cohen <em>et al<\/em>., 2019). \u00c0 cet \u00e9gard, divers mouvements en ligne, reposant souvent sur des socles f\u00e9ministes historiques, cherchent \u00e0 poser un regard \u00ab&#160;positif&#160;\u00bb sur les corps hors normes (Afful et Ricciardelli, 2015). On pense, entre autres courants, au <em>body positivisme<\/em>, au <em>fat acceptance movement<\/em> (Cwynar-Horta, 2016&#160;; Cohen <em>et al<\/em>., 2019&#160;; Kelly et Daneshjoo, 2019), au <em>skin positivisme<\/em>, au <em>hair positivisme <\/em>ou encore au <em>trans positivisme,<\/em> etc., qui concentrent leur attention sur l\u2019acceptation de tout corps (Sastre, 2014), type de peau ou de cheveu. L\u2019\u00e9mancipation des standards de beaut\u00e9 est encourag\u00e9e au moyen de hashtags comme <em>#theysaid,<\/em> qui recense les exp\u00e9riences d\u2019harc\u00e8lement grossophobe, ou de <em>#celebratemysize<\/em>.<\/p>\n<p class=\"texte\">Cependant, les RSN repr\u00e9senteraient une arme \u00e0 double tranchant (Bourdeloie, 2021). En raison de leurs caract\u00e9ristiques techniques, ils fonctionnent comme une caisse de r\u00e9sonance \u00e0 g\u00e9om\u00e9trie variable (<em>ibid<\/em>.) et, l\u00e0 o\u00f9 ils permettent de contrer les normes h\u00e9g\u00e9moniques, ils peuvent aussi participer \u00e0 l\u2019amplification des discours stigmatisant les diff\u00e9rences ou les \u00ab&#160;d\u00e9viances&#160;\u00bb. Comme dans d\u2019autres m\u00e9dias, l\u2019image corporelle y est conditionn\u00e9e par des strat\u00e9gies d\u2019\u00e9rotisation (Sedda et Botero, 2022) et de mise en valeur d\u2019id\u00e9aux corporels conduisant les individus, en particulier les plus minor\u00e9s, \u00e0 \u00eatre insatisfaits de leur corps (Grabe <em>et<\/em> <em>al<\/em>., 2008&#160;; Lewallen et Behm-Morawitz, 2016&#160;; Tiggeman <em>et al<\/em>., 2018&#160;; Tiggemann et Anderberg, 2020&#160;; Mahon et Hevey, 2021&#160;; Albermann, 2022). Sur Instagram, cela se manifeste par l\u2019utilisation de hashtags du type \u00ab&#160;<em>#bodygoals<\/em>, <em>#selfesteem<\/em>, <em>#noexcuses<\/em>, <em>#lovingmydots<\/em>, <em>#thisinspiration<\/em>, <em>#fitsinspiration<\/em>&#160;\u00bb. Les cons\u00e9quences de cette exposition sur les individus (Tiggeman et Zaccardo, 2015) s\u2019\u00e9tendent du d\u00e9veloppement de troubles alimentaires (Frederick <em>et al<\/em>., 2017) aux dangers pour la sant\u00e9 physique et mentale. Par exemple, la mise en visibilit\u00e9 des corps handicap\u00e9s interroge cette ambivalence des RSN dans la reproduction ou l\u2019\u00e9mancipation des normes corporelles. Le fauteuil roulant peut autant \u00eatre inclus dans une image en ligne pour confronter le regard validiste \u00e0 ce \u00ab&#160;partenaire de vie&#160;\u00bb (Tua, 2022), qu\u2019\u00eatre volontairement exclu de cette image en raison du \u00ab&#160;besoin d\u2019assistance&#160;\u00bb (<em>ibid<\/em>.) qu\u2019il incarne et des discours infantilisants et paternalistes qu\u2019il engendre.<br \/>\nIl en va de m\u00eame pour les individus pr\u00e9sentant des pathologies dermatologiques qui, en \u00ab&#160;sublimant les stigmates [non sans garder] un contr\u00f4le sur les images partag\u00e9es&#160;\u00bb (Husson et Sedda, 2022), promeuvent la diversit\u00e9 corporelle. N\u00e9anmoins, pr\u00e9senter ces corps sous des angles avantageux et similaires aux corps h\u00e9g\u00e9moniques r\u00e9v\u00e8le paradoxalement un repli vers les normes en vigueur (<em>ibid<\/em>.). Par la r\u00e9appropriation de l\u2019espace public de la ville, l\u00e0 o\u00f9 la <em>Gay Pride <\/em>vise une contestation de la norme h\u00e9t\u00e9rosexuelle (Leroy, 2009), la diffusion d\u2019images, de <em>hashtags<\/em> ou d\u2019\u00e9motic\u00f4nes mettant en sc\u00e8ne des individus homosexuels \u00e0 l\u2019apparence genr\u00e9e parfois tr\u00e8s affirm\u00e9e, ne constitue-t-elle pas une fa\u00e7on de s\u2019approprier les espaces publics num\u00e9riques&#160;?<\/p>\n<p class=\"texte\">Dans ce contexte, il appara\u00eet \u00e9vident que les plateformes num\u00e9riques ne sont pas neutres et contribuent \u00e0 (re)produire des normes, puisque \u00ab&#160;chaque plateforme propose une politique de la visibilit\u00e9 sp\u00e9cifique&#160;\u00bb (Cardon, 2008&#160;:\u00a0124) \u00e0 ses utilisateurs et utilisatrices qui peuvent s\u2019en saisir pour \u00ab&#160;jouer leur identit\u00e9 sur des registres diff\u00e9rents&#160;\u00bb (<em>ibid<\/em>.). Dans le m\u00eame temps, ces plateformes peuvent constituer des territoires de repr\u00e9sentations stigmatisantes et des lieux de r\u00e9sistance, o\u00f9 il est possible de se r\u00e9approprier et de resignifier diff\u00e9rentes formes de minoration des corps et proposer des repr\u00e9sentations allant \u00e0 l\u2019encontre des pr\u00e9jug\u00e9s (Bazin <em>et al<\/em>., 2020). L\u2019exposition num\u00e9rique des corps minor\u00e9s pourrait donc aussi conduire aux repr\u00e9sentations et l\u00e9gitimations de cat\u00e9gories subalternes (Quet, 2021). Encore peu trait\u00e9e dans la litt\u00e9rature, une telle ambivalence gagnerait \u00e0 \u00eatre davantage explor\u00e9e dans ce dossier th\u00e9matique dont l\u2019ambition est d\u2019interroger ce que le num\u00e9rique fait aux corps minor\u00e9s. Autrement dit, l\u2019objectif est de comprendre comment le num\u00e9rique, appr\u00e9hend\u00e9 comme un territoire, une plateforme, un syst\u00e8me d\u2019intelligence artificielle, etc., agit sur les corps&#160;: constitue-t-il une ar\u00e8ne de contestation et de r\u00e9sistance aux normes corporelles h\u00e9g\u00e9moniques, un territoire de visibilit\u00e9 des corps stigmatis\u00e9s ou un lieu de reproduction de la domination&#160;?<\/p>\n<h3 class=\"texte\">Axe 1. Ce que les dispositifs num\u00e9riques font aux corps minor\u00e9s<\/h3>\n<p class=\"texte\">Il s\u2019agit d\u2019examiner la fa\u00e7on dont le design des dispositifs num\u00e9riques (Badouard, 2014) contribue \u00e0 fa\u00e7onner des corps plus ou moins l\u00e9gitimes et \u00e0 participer, ou non, de la reproduction de certaines normes corporelles. Ce faisant, l\u2019analyse porte sur le r\u00f4le du dispositif dans le rapport au corps qui \u00e9chappe aux normes corporelles dominantes.<\/p>\n<p class=\"texte\">Le dispositif est appr\u00e9hend\u00e9 au sens de Giorgio Agamben (2007), selon lequel il s\u2019agit d\u2019un ensemble h\u00e9t\u00e9rog\u00e8ne de pratiques, savoirs et techniques au service du pouvoir (voir aussi Appel, Boulanger, Massou, 2010). L\u2019analyse mat\u00e9rielle du dispositif pourra ici \u00eatre prise en compte. Les dispositifs num\u00e9riques \u00e9tant d\u00e8s lors envisag\u00e9s \u00e0 la fois comme des espaces \u00e9ditoriaux discursifs dans lequel s\u2019inscrivent et s\u2019organisent symboliquement des signes (Julliard, 2013), comme une industrie r\u00e9gie par des logiques \u00e9conomiques et industrielles, ou encore comme une plateforme qui capitalise la valeur sur la base de l\u2019exploitation des donn\u00e9es personnelles (Bigot <em>et al<\/em>., 2021). Il s\u2019agit alors de faire cas des caract\u00e9ristiques techniques, algorithmiques, fonctionnelles, ergonomiques, esth\u00e9tiques, etc., de ces diff\u00e9rents dispositifs et de la fa\u00e7on dont ils fa\u00e7onnent les (contre)discours et (co-)produisent de potentiels rapports d\u2019oppression. Il est ainsi question d\u2019\u00e9tudier leur r\u00f4le dans la construction et la circulation de discours qui valorisent ou d\u00e9valorisent les corps stigmatis\u00e9s, dans l\u2019activit\u00e9 de cr\u00e9ation de contenus et d\u2019influence, mais aussi dans la mon\u00e9tisation du stigmate susceptible de constituer une source de revenus. On pourra porter l&rsquo;attention sur les biais de la plateforme s&rsquo;agissant de l\u2019affichage, du r\u00e9f\u00e9rencement et, ce faisant, de la hi\u00e9rarchisation des corps assign\u00e9s ou non comme minor\u00e9s. D\u2019un point de vue des usages, on pourra se demander comment ces biais sont contourn\u00e9s pour contester les normes h\u00e9g\u00e9moniques concernant le rapport au corps.<\/p>\n<h3 class=\"texte\">Axe 2. Investiguer les enjeux de l\u2019exposition du stigmate corporel en ligne<\/h3>\n<p class=\"texte\">Cet axe a pour objectif d\u2019investiguer les motivations qui conduisent \u00e0 exposer des corps <em>atypiques<\/em> en ligne, ainsi que la fa\u00e7on dont les discours qui circulent sur l\u2019acceptation, ou non, de ces corps sont re\u00e7us et appropri\u00e9s. D\u2019une part, il est important d\u2019examiner les m\u00e9canismes \u00e0 l\u2019origine de l\u2019exposition des stigmates en ligne, que ce soit dans une perspective militante (Ronti, 2018) et revendicative, ou dans une perspective ayant trait \u00e0 un enjeu de reconnaissance (Botero <em>et al<\/em>., 2023). Il est question des enjeux de visibilit\u00e9 et d\u2019\u00e9mancipation sous-jacents \u00e0 la production de ces espaces. D\u2019autre part, il serait pertinent d\u2019\u00e9tudier de fa\u00e7on compl\u00e9mentaire les m\u00e9canismes qui conduisent des personnes stigmatis\u00e9es, embrassant un statut d\u2019influenceur\u00b7euse, de cr\u00e9ateur\u00b7ice de contenus ou d\u2019activiste, \u00e0 exposer leur corps en ligne voire, dans certains cas, \u00e0 mon\u00e9tiser le stigmate qui le caract\u00e9rise. En effet, les discriminations peuvent \u00eatre \u00e0 l\u2019origine de la cr\u00e9ation d\u2019un contenu, d\u2019un podcast ou d\u2019un profil en ligne \u0153uvrant pour d\u00e9fendre une cause. Les propositions pourraient ici se concentrer sur le cas des personnes subalternis\u00e9es par les industries en raison de leur apparence physique, \u00e0 l\u2019exemple de travaux dans la continuit\u00e9 de ceux de Laurence Allard (2019) relatifs aux Youtubeuses discrimin\u00e9es parce que voil\u00e9es. Parall\u00e8lement, cet axe propose de questionner les discours contre-h\u00e9g\u00e9moniques ou alternatifs que permettent de produire certaines de ces plateformes, dont se sont empar\u00e9es des personnes militantes ou influenceuses, invisibilis\u00e9es dans les espaces publics \u00ab&#160;traditionnels&#160;\u00bb (Jou\u00ebt, 2022). Militantes, influenceuses ou \u00ab&#160;ordinaires&#160;\u00bb, ces personnes d\u00e9fendent-elles un champ d\u2019expertise (sur la grosseur, le handicap, une maladie de peau, etc.) sp\u00e9cifique qui, scientifique ou non, pourrait \u00e9chapper aux personnes \u00ab&#160;ordinaires&#160;\u00bb ou \u00ab&#160;neurotypiques&#160;\u00bb&#160;? \u00c0 ce titre, il sera int\u00e9ressant d\u2019explorer dans quelle mesure la revendication d\u2019un stigmate corporel participe de l\u2019acquisition d\u2019une l\u00e9gitimit\u00e9 \u00e0 s\u2019exprimer sur une pathologie, ou de l\u2019extension d\u2019une sph\u00e8re d\u2019influence qui, appuy\u00e9e par des m\u00e9triques inh\u00e9rentes aux RSN, contribue \u00e0 renforcer cette l\u00e9gitimation.<\/p>\n<h3 class=\"texte\">Axe 3. Penser les repr\u00e9sentations des corps minor\u00e9s en ligne et leurs appropriations par les individus<\/h3>\n<p class=\"texte\">Il s\u2019agit d\u2019analyser la fa\u00e7on dont les corps minor\u00e9s et stigmatis\u00e9s sont repr\u00e9sent\u00e9s et per\u00e7us dans diff\u00e9rents espaces en ligne, et le r\u00f4le de ces derniers dans la d\u00e9construction des discours et repr\u00e9sentations li\u00e9s aux stigmates corporels. Comment les usager\u00b7\u00e8re\u00b7s s\u2019approprient-elles les discours handiphobes, dysmorphobes, homophobes, n\u00e9grophobes, ethnophobes, g\u00e9rontophobes, psychophobes, capacitistes, etc., et de quelles mani\u00e8res ces discours participent \u00e0 la perception de leurs corps tout comme de leur rapport aux autres corps&#160;? On cherchera \u00e0 comprendre les motivations des publics dispos\u00e9s \u00e0 participer \u00e0 des \u00e9changes autour des corpor\u00e9it\u00e9s en ligne, ainsi que leurs caract\u00e9ristiques. On se demandera ce qui les conduit ou non \u00e0 s\u2019exposer en ligne et dans quelle mesure ils investissent ces lieux comme des espaces de soutien (Galibert et Cordelier, 2023), voire de communaut\u00e9s d\u2019entraide qui partagent des exp\u00e9riences. Pour des sujets sociaux minoris\u00e9s et victimis\u00e9s dans l\u2019espace public traditionnel, on explorera la fa\u00e7on dont ces environnements num\u00e9riques, propices \u00e0 l\u2019expression et \u00e0 la r\u00e9alisation de soi, tiennent lieu ou non de territoire pour s\u2019\u00e9manciper des normes corporelles h\u00e9g\u00e9moniques qui ceignent les soci\u00e9t\u00e9s occidentales (Larochelle et Bourdeloie, \u00e0 para\u00eetre).<\/p>\n<h2 class=\"texte\">Propositions d\u2019articles<\/h2>\n<p class=\"texte\">Les propositions d\u2019articles (entre 4\u00a0000 et 6\u00a0000 signes, r\u00e9f\u00e9rences bibliographiques incluses) sont \u00e0 envoyer d\u2019ici le <strong>3\u00a0f\u00e9vrier 2026<\/strong> \u00e0&#160;:<\/p>\n<ul>\n<li class=\"texte\">H\u00e9l\u00e8ne Bourdeloie (helene.bourdeloie@univ-paris13.fr)<\/li>\n<li class=\"texte\">Yann Bruna (ybruna@parisnanterre.fr)<\/li>\n<li class=\"texte\">Dimitra Laurence Larochelle (dimitra.larochelle@sorbonne-nouvelle.fr)<\/li>\n<li class=\"texte\">B\u00e9atrice Fleury (beatrice.fleury@univ-lorraine.fr)<\/li>\n<li class=\"texte\">Jacques Walter (jacques.walter@univ-lorraine.fr)<\/li>\n<\/ul>\n<h2>Calendrier<\/h2>\n<ul>\n<li class=\"texte\">Date limite de r\u00e9ception des propositions&#160;: 3\u00a0f\u00e9vrier 2026 (entre 4\u00a0000 et 6\u00a0000 signes, r\u00e9f\u00e9rences bibliographiques incluses)<\/li>\n<li class=\"texte\">Retour des d\u00e9cisions aux auteur\u00b7ices des propositions&#160;: 24\u00a0mars 2026<\/li>\n<li class=\"texte\">Remise des articles&#160;: 15\u00a0septembre 2026<\/li>\n<li class=\"texte\">Expertise&#160;: 16\u00a0septembre-12\u00a0novembre 2026<\/li>\n<li class=\"texte\">Remise des articles finaux&#160;: 15\u00a0janvier 2027<\/li>\n<li class=\"texte\">Parution&#160;: 1<sup>er<\/sup>\u00a0semestre\u00a02027<\/li>\n<\/ul>\n<h2 class=\"texte\">Recommandations r\u00e9dactionnelles<\/h2>\n<p class=\"texte\"><a href=\"https:\/\/journals.openedition.org\/questionsdecommunication\/3074\">https:\/\/journals.openedition.org\/questionsdecommunication\/3074<\/a><\/p>\n<h2 class=\"texte\">Appel permanent<\/h2>\n<p class=\"texte\">Questions de communication publie aussi des Notes de recherche.<\/p>\n<p class=\"texte\"><strong>Recommandations aux auteurs et autrices<\/strong><\/p>\n<p class=\"texte\">Voir sur le site de la revue&#160;:<br \/>\nhttps:\/\/journals.openedition.org\/questionsdecommunication\/22297<\/p>\n<p class=\"texte\">Les propositions d\u2019articles sont \u00e0 envoyer conjointement \u00e0&#160;:<\/p>\n<ul>\n<li class=\"texte\">C\u00e9line S\u00e9gur&#160;: <a href=\"mailto:celine.segur@univ-lorraine.fr7\">celine.segur@univ-lorraine.fr<\/a><\/li>\n<li class=\"texte\">Sylvie Thieblemont-Dollet&#160;: <a href=\"mailto:sylvie.thieblemont@univ-lorraine.fr\">sylvie.thieblemont@univ-lorraine.fr<\/a><\/li>\n<li class=\"texte\">B\u00e9atrice Fleury&#160;: <a href=\"mailto:beatrice.fleury@univ-lorraine.fr\">beatrice.fleury@univ-lorraine.fr<\/a><\/li>\n<li class=\"texte\">Jacques Walter&#160;: <a href=\"mailto:jacques.walter@univ-lorraine.fr\">jacques.walter@univ-lorraine.fr<\/a><\/li>\n<\/ul>\n<h2 class=\"texte\">Questions de communication<\/h2>\n<p class=\"texte\">Revue semestrielle \u00e0 comit\u00e9 de lecture, publi\u00e9e en acc\u00e8s ouvert int\u00e9gral, soutenue par le Centre de recherche sur les m\u00e9diations de l\u2019Universit\u00e9 de Lorraine et l\u2019Institut des sciences humaines et sociales du CNRS. Dans le cadre du projet Ques2ComSO, la revue est aussi financ\u00e9e avec le soutien du Fonds national pour la science ouverte et le <a href=\"https:\/\/scienceouverte.univ-lorraine.fr\/a-lul\/fonds-de-soutien-a-la-science-ouverte\/\">fonds de soutien \u00e0 la science ouverte<\/a> de l&rsquo;Universit\u00e9 de Lorraine.<\/p>\n<p class=\"texte\"><em>Questions de communication<\/em> favorise l\u2019approfondissement ou le renouvellement des approches sur un th\u00e8me \u2013\u00a0objet d\u2019un dossier\u00a0\u2013, gr\u00e2ce au croisement de contributions faisant r\u00e9f\u00e9rence \u00e0 diff\u00e9rentes traditions scientifiques. Fond\u00e9e sur le pluralisme, elle suscite des d\u00e9bats sur des concepts ou des m\u00e9thodes utilis\u00e9s dans les travaux traitant de l\u2019information-communication (\u00c9changes, Notes de recherche). Enfin, par l\u2019attention \u00e0 une dimension internationale, elle vise un accroissement de la circulation des connaissances et de la dynamique comparative, notamment par les rubriques En VO, Focus et les recensions d\u2019ouvrages fran\u00e7ais et \u00e9trangers.<\/p>\n<p class=\"texte\">Indexation\/r\u00e9f\u00e9rencement&#160;: Biblio SHS (Inist, CNRS), Bielefeld Academic Search Engine, Conseil national des universit\u00e9s (71<sup>e<\/sup>\u00a0section), Directory of Research Journals Indexing, Elektronische Zeitschriftenbibliothek, Erih Plus (European Science Foundation), Francis (Inist), Google Scholar, Haut Conseil de l\u2019\u00e9valuation de la recherche et de l\u2019enseignement sup\u00e9rieur, H\u00e9lo\u00efse (CCSD, CNRS), International Bibliography of the Social Sciences (IBSS, Proquest-CSA), Isidore, Miar (Information Matrix for the Analysis of Journals, Universitat de Barcelona), Road (ISSN International Centre, Unesco), Sherpa\/Romeo (University of Nottingham), Sudoc, WorldCat (OCLC), Zora (Zurich Open Repository and Archive Journal Database).<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-corps\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/corps\/\" title=\"Corps\"><span class=\"termslist-itemname\">Corps<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-dispositifs\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/dispositifs\/\" title=\"Dispositifs\"><span class=\"termslist-itemname\">Dispositifs<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-numerique\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/numerique\/\" title=\"Num\u00e9rique\"><span class=\"termslist-itemname\">Num\u00e9rique<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 29 mai 2025 Th\u00e9matiques Num\u00e9rique : strat\u00e9gies, dispositifs et usages R\u00e9ponse attendue pour le 03\/02\/2026 Type de r\u00e9ponse R\u00e9sum\u00e9 Type de contribution attendue Article Nom de [&hellip;]<\/p>\n","protected":false},"author":781,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[373,315,90],"thematique":[39],"sfsic":[],"class_list":["post-34101","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-corps","tag-dispositifs","tag-numerique","thematique-numerique-strategies-dispositifs-et-usages","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corps stigmatis\u00e9s en contexte num\u00e9rique<\/title>\n<meta name=\"description\" content=\"La revue Questions de communication lance un AAA intitul\u00e9 &quot;Corps stigmatis\u00e9s en contexte num\u00e9rique&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corps stigmatis\u00e9s en contexte num\u00e9rique\" \/>\n<meta property=\"og:description\" content=\"La revue Questions de communication lance un AAA intitul\u00e9 &quot;Corps stigmatis\u00e9s en contexte num\u00e9rique&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-29T19:25:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T08:57:48+00:00\" \/>\n<meta name=\"author\" content=\"Axelle Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/\"},\"author\":{\"name\":\"Axelle Martin\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\"},\"headline\":\"Corps stigmatis\u00e9s en contexte num\u00e9rique\",\"datePublished\":\"2025-05-29T19:25:22+00:00\",\"dateModified\":\"2025-06-05T08:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/\"},\"wordCount\":2971,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Corps\",\"Dispositifs\",\"Num\u00e9rique\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/\",\"name\":\"Corps stigmatis\u00e9s en contexte num\u00e9rique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2025-05-29T19:25:22+00:00\",\"dateModified\":\"2025-06-05T08:57:48+00:00\",\"description\":\"La revue Questions de communication lance un AAA intitul\u00e9 \\\"Corps stigmatis\u00e9s en contexte num\u00e9rique\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/corps-stigmatises-en-contexte-numerique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Corps stigmatis\u00e9s en contexte num\u00e9rique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\",\"name\":\"Axelle Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"caption\":\"Axelle Martin\"},\"sameAs\":[\"@antropocominside\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corps stigmatis\u00e9s en contexte num\u00e9rique","description":"La revue Questions de communication lance un AAA intitul\u00e9 \"Corps stigmatis\u00e9s en contexte num\u00e9rique\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/","og_locale":"en_US","og_type":"article","og_title":"Corps stigmatis\u00e9s en contexte num\u00e9rique","og_description":"La revue Questions de communication lance un AAA intitul\u00e9 \"Corps stigmatis\u00e9s en contexte num\u00e9rique\".","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/","og_site_name":"SFSIC","article_published_time":"2025-05-29T19:25:22+00:00","article_modified_time":"2025-06-05T08:57:48+00:00","author":"Axelle Martin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/"},"author":{"name":"Axelle Martin","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b"},"headline":"Corps stigmatis\u00e9s en contexte num\u00e9rique","datePublished":"2025-05-29T19:25:22+00:00","dateModified":"2025-06-05T08:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/"},"wordCount":2971,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Corps","Dispositifs","Num\u00e9rique"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/","name":"Corps stigmatis\u00e9s en contexte num\u00e9rique","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2025-05-29T19:25:22+00:00","dateModified":"2025-06-05T08:57:48+00:00","description":"La revue Questions de communication lance un AAA intitul\u00e9 \"Corps stigmatis\u00e9s en contexte num\u00e9rique\".","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/corps-stigmatises-en-contexte-numerique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"Corps stigmatis\u00e9s en contexte num\u00e9rique"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b","name":"Axelle Martin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","caption":"Axelle Martin"},"sameAs":["@antropocominside"]}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/34101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/781"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=34101"}],"version-history":[{"count":3,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/34101\/revisions"}],"predecessor-version":[{"id":34181,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/34101\/revisions\/34181"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=34101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=34101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=34101"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=34101"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=34101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}