{"id":24561,"date":"2022-05-18T17:44:13","date_gmt":"2022-05-18T15:44:13","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=24561"},"modified":"2022-05-19T10:10:02","modified_gmt":"2022-05-19T08:10:02","slug":"semiotique-plastique-limites-et-expansions","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/","title":{"rendered":"S\u00e9miotique plastique : limites et expansions"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> <time class=\"pubdate-time\" pubdate datetime=\"2022-05-18T17:44:13+02:00\">18 mai 2022<\/time>\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-design\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/design\/\" title=\"Design\"><span class=\"termslist-itemname\">Design<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-images-cinema-medias-audiovisuels-et-industries-culturelles\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/images-cinema-medias-audiovisuels-et-industries-culturelles\/\" title=\"Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles\"><span class=\"termslist-itemname\">Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-numerique-strategies-dispositifs-et-usages\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/numerique-strategies-dispositifs-et-usages\/\" title=\"Num\u00e9rique : strat\u00e9gies, dispositifs et usages\"><span class=\"termslist-itemname\">Num\u00e9rique : strat\u00e9gies, dispositifs et usages<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>31\/07\/2022<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>R\u00e9sum\u00e9<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Estudos Semioticos<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/www.revistas.usp.br\/esse\/19_2_dossier_floch_call\" title=\"Estudos Semioticos\" target=\"_blank\" rel=\"noopener\">Estudos Semioticos<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<blockquote>\n<p><em>La s\u00e9miotique tient \u00e0 se d\u00e9finir comme une entreprise \u00e0 vocation scientifique&#160;: elle vise \u00e0 construire une th\u00e9orie g\u00e9n\u00e9rale de la signification et des langages. Mais on peut aussi la d\u00e9finir, et la vivre, comme une certaine disposition d\u2019esprit, faite de curiosit\u00e9 pour tout ce qui a, ou peut avoir du sens<\/em>. (FLOCH, 1985, p. 139).<\/p>\n<p><em>[\u2026] j&rsquo;ai le sentiment que, de nos jours, c&rsquo;est presque faire acte de r\u00e9sistance que de s&rsquo;en tenir \u00e0 regarder longuement quelques \u0153uvres, de ne pas se laisser transporter par ces flots d&rsquo;images que charrient non seulement les programmes de t\u00e9l\u00e9vision et les r\u00e9seaux d&rsquo;affichage mais aussi les \u201cgrandes expositions\u201d<\/em>. (FLOCH, 2002, p. 4)<\/p>\n<\/blockquote>\n<p>Dans son ouvrage classique <em>Petites mythologies de l&rsquo;\u0153il et de l&rsquo;esprit<\/em> (1985), Jean-Marie Floch fonde le champ d\u2019\u00e9tude de la s\u00e9miotique plastique, en d\u00e9finit les limites et laisse entrevoir ses prolongements. Le sous-titre du livre, \u201cPour une s\u00e9miotique plastique\u201d, n&rsquo;est certes pas anodin&#160;: il s\u2019affirme ainsi comme le jalon inaugural d\u2019un projet que le s\u00e9mioticien consolidera et \u00e9largira lui-m\u00eame dans ses ouvrages ult\u00e9rieurs. Alors que, dans les sept \u00e9tudes qui composent <em>Petites mythologies<\/em>\u2026, Floch analyse la peinture, la photographie, la relation entre l\u2019\u00e9criture et le dessin, l\u2019architecture et la publicit\u00e9, d\u00e9signant ainsi les objets privil\u00e9gi\u00e9s par une s\u00e9miotique des manifestations visuelles, il \u00e9largit plus tard ces centres d\u2019int\u00e9r\u00eat, y associant tour \u00e0 tour les marques et le marketing (1990), le design (1995), et la bande dessin\u00e9e (2002). D\u2019un ouvrage \u00e0 l\u2019autre, il \u00e9labore une m\u00e9thode qui d\u00e9finit des crit\u00e8res et des proc\u00e9dures d\u2019analyse bien pr\u00e9cis tout en proposant une ouverture de la th\u00e9orie s\u00e9miotique \u00e0 l\u2019univers des cr\u00e9ateurs, des sp\u00e9cialistes des arts visuels et des strat\u00e9gies de marketing et de publicit\u00e9 et des amateurs d&rsquo;art en g\u00e9n\u00e9ral. Floch n\u2019est pas seulement rigoureux dans ses approches, judicieux dans ses analyses et exhaustif dans l\u2019examen des possibilit\u00e9s de d\u00e9veloppement de chacune de ses conclusions, il s\u2019est aussi pr\u00e9occup\u00e9 d\u2019\u00eatre lu par un public de non-sp\u00e9cialistes et s\u2019est demand\u00e9 comment faire lire la s\u00e9miotique.<\/p>\n<p>Soucieux d\u2019expliquer la th\u00e9orie de fa\u00e7on simple, didactique et concise, Floch d\u00e9butait chacun de ses livres par des scripts de lecture o\u00f9 il sugg\u00e9rait des sauts de chapitre, des retours et des \u201c\u00e9chapp\u00e9es\u201d. C\u2019\u00e9tait un s\u00e9mioticien qui croyait en la s\u00e9miotique, en sa capacit\u00e9 \u00e0 d\u00e9crire et, au-del\u00e0, \u00e0 cr\u00e9er des significations pour le monde et la vie sociale, et non un penseur uniquement pr\u00e9occup\u00e9 par la rigueur m\u00e9thodologique ou la d\u00e9finition terminologique. C&rsquo;est pourquoi, dans la premi\u00e8re \u00e9pigraphe que nous avons choisie, il \u00e9voque une s\u00e9miotique \u00ab&#160;vivante&#160;\u00bb, avant d\u2019ajouter&#160;:<\/p>\n<blockquote>\n<p>On a trop souvent reproch\u00e9 \u00e0 la s\u00e9miotique d\u2019\u00eatre r\u00e9ductrice, de traiter les rapports de l\u2019homme au monde et de l\u2019homme \u00e0 l\u2019homme en termes de structures s\u00e8ches, froides. Pour qui sait que cet aspect r\u00e9ducteur n&rsquo;est qu&rsquo;une des conditions de la rigueur, il ne s&rsquo;agit l\u00e0 que de connotations. L&rsquo;exp\u00e9rience de la recherche s\u00e9miotique montre plut\u00f4t qu&rsquo;elle est un exercice fructueux de la curiosit\u00e9 intellectuelle et que cette curiosit\u00e9 peut ne pas \u00eatre uniquement celle d&rsquo;un observateur, distant et souverain, face aux actes et aux discours qui lui sont contemporains&#160;; la dimension sociale de la s\u00e9miotique peut ne pas se limiter \u00e0 une pure fonction didactique, de simple \u00e9veil \u00e0 des domaines exclus de la culture classique, qui sont pourtant charg\u00e9s de sens et qui, en m\u00eame temps, en produisent. La s\u00e9miotique peut aussi aider \u00e0 <em>produire<\/em> du sens. (FLOCH, 1985, p. 139).<\/p>\n<\/blockquote>\n<p>Si la rigueur se laisse appr\u00e9cier \u00e0 partir d\u2019un souci de la m\u00e9thode, Floch doit \u00eatre consid\u00e9r\u00e9 comme un ma\u00eetre rigoureux&#160;: les \u00e9l\u00e9ments cl\u00e9s de la th\u00e9orie, tels le concept de semi-symbolisme et l\u2019articulation entre les sch\u00e9mas narratifs et les m\u00e9canismes s\u00e9mantico-discursifs, lui ont permis de circonscrire les crit\u00e8res de description des contrastes chromatiques, eid\u00e9tiques et topologiques dans les \u0153uvres d\u2019expression visuelle et d\u2019\u00e9tendre le champ de la s\u00e9miotique aux pratiques sociales (avec l\u2019analyse c\u00e9l\u00e8bre des voyageurs du m\u00e9tro, 1985) et aux interactions entre sujets et entre sujets et objets (l\u2019\u00e9tude des marques, du marketing et des identit\u00e9s visuelles, 1990 et 1995). Ces outils ont en outre permis d\u2019aborder des questions li\u00e9es \u00e0 l\u2019aspectualisation de l\u2019espace (voir l\u2019analyse de <em>Tintin au Tibet<\/em>, 2002) ou les relations entre les modalit\u00e9s sensibles, en particulier le tactile et le visuel (voir l&rsquo;\u00e9tude du logo de la cuisine de Michel Bras, 1995).<\/p>\n<p>Le num\u00e9ro 19.2 de la revue <strong>Estudos Semi\u00f3ticos<\/strong> entend revenir sur le programme initi\u00e9 par le sous-titre de l&rsquo;ouvrage <em>Petites mythologies de l&rsquo;\u0153il et de l&rsquo;esprit<\/em> et dresser une sorte de bilan provisoire. Comment la post\u00e9rit\u00e9 de Floch a-t-elle compris cette s\u00e9miotique plastique&#160;? Comment a-t-elle \u00e9t\u00e9 appropri\u00e9e&#160;? Quel statut la post\u00e9rit\u00e9 a-t-elle donn\u00e9 \u00e0 cette \u201cdimension\u201d plastique&#160;? Appliqu\u00e9e \u00e0 la photographie aussi bien qu&rsquo;\u00e0 la peinture, la s\u00e9miotique plastique n&rsquo;a pu \u00eatre exploit\u00e9e pour l&rsquo;\u00e9tude d&rsquo;\u0153uvres num\u00e9riques. Cette application est-elle envisageable et sous quelles conditions&#160;?<\/p>\n<p>Les propositions de Floch, et en particulier la notion centrale de syst\u00e8me semi-symbolique, n\u2019ont pas \u00e9chapp\u00e9 \u00e0 la critique, celle-ci soulignant le r\u00e9ductionnisme de l&rsquo;approche binaire. Loin de l&rsquo;ignorer, le dossier entend interroger cette critique afin de montrer la vitalit\u00e9 des propositions de Floch, de cerner la zone critique o\u00f9 elles perdent leur efficience et celle, au contraire, o\u00f9 elles r\u00e9v\u00e8lent toute leur pertinence. Faudrait-il limiter l&rsquo;application du syst\u00e8me semi-symbolique \u00e0 certains supports d&rsquo;inscription, \u00e0 certaines conceptions de la signification&#160;? Que \u201cdit\u201d pr\u00e9cis\u00e9ment le semi-symbolisme et quelles sont ses \u201climites d&rsquo;applicabilit\u00e9\u201d&#160;? Pourrait-on circonscrire l&#8217;empan de la s\u00e9miotique plastique de Floch et, les s\u00e9mioticiens ayant pu la mettre \u00e0 l&rsquo;\u00e9preuve de nombreux corpus, repr\u00e9ciser son champ d&rsquo;application quelque trente-sept ann\u00e9es apr\u00e8s&#160;?<\/p>\n<p>Sur la base de ces consid\u00e9rations, le num\u00e9ro 19.2 de la revue recevra des articles d\u2019analyse suivant plusieurs axes de r\u00e9flexion&#160;:<\/p>\n<ul>\n<li class=\"show\">\n<p align=\"justify\">D\u00e9veloppements de la s\u00e9miotique plastique \u00e0 partir de l\u2019\u0153uvre de Jean-Marie Floch&#160;: expansions th\u00e9oriques et m\u00e9thodologiques, mais aussi examen de sa \u201czone critique d\u2019application\u201d..<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">Retour critique sur les analyses des diff\u00e9rents \u201cobjets de sens visuels&#160;\u00bb men\u00e9es par Floch.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">Les relations entre la s\u00e9miotique plastique et la s\u00e9miotique de l\u2019espace.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">La relation entre le semi-symbolisme et l\u2019exp\u00e9rience esth\u00e9tique.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">La culture num\u00e9rique et ses implications th\u00e9oriques et analytiques pour l\u2019approche s\u00e9miotique.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">Le design des objets.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">Le design, la communication et le marketing.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">L&rsquo;impact du num\u00e9rique dans le champ de la publicit\u00e9 et des m\u00e9dias.<\/p>\n<\/li>\n<li class=\"show\">\n<p align=\"justify\">La multimodalit\u00e9 et le syncr\u00e9tisme des langues.<\/p>\n<\/li>\n<\/ul>\n<h2><strong>Renseignements pratiques<\/strong><\/h2>\n<h3>\u00c9ch\u00e9ancier&#160;:<\/h3>\n<ul>\n<li class=\"show\">Soumission des propositions (une page) jusqu&rsquo;au <strong>31 juillet 2022<\/strong>. Envoyer \u00e0&#160;: rev.esse@usp.br . Objet&#160;: \u00ab&#160;Dossier Floch 2023 &#8211; proposition d&rsquo;article&#160;\u00bb<\/li>\n<li class=\"show\">Confirmation des propositions retenues&#160;: <strong>le 20 ao\u00fbt 2022<\/strong>.<\/li>\n<li class=\"show\">Remise \u00e0 la revue des articles dont les propositions auront \u00e9t\u00e9 retenues&#160;: <strong>du 1er septembre au 31 d\u00e9cembre 2022<\/strong>. La remise doit se faire sur&#160;: <a href=\"https:\/\/www.revistas.usp.br\/esse\/about\/submissions\">https:\/\/www.revistas.usp.br\/esse\/about\/submissions<\/a><\/li>\n<li class=\"show\">Publication en ligne pr\u00e9vue&#160;:<strong> ao\u00fbt 2023.<\/strong><\/li>\n<\/ul>\n<h3>Normes \u00e9ditoriales&#160;:<\/h3>\n<ul>\n<li class=\"show\">Langues de travail&#160;: portugais, fran\u00e7ais, anglais, italien, espagnol.<\/li>\n<li class=\"show\">L&rsquo;Abstract doit \u00eatre compos\u00e9 en anglais + une langue choisie parmi celles accept\u00e9es.<\/li>\n<li class=\"show\">Les articles soumis \u00e0 la revue doivent compter de 25.000 \u00e0 50.000 caract\u00e8res, espaces compris.<\/li>\n<li class=\"show\">Pri\u00e8re de v\u00e9rifier les <a href=\"https:\/\/www.revistas.usp.br\/esse\/about\/submissions\">directives aux auteurs<\/a> de la revue.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 class=\"western\" align=\"justify\"><strong>R\u00e9f\u00e9rences&#160;:<\/strong><\/h2>\n<ul>\n<li class=\"western\">FLOCH, Jean-Marie. <em>Petites mythologies de l\u2019\u0153il et de l\u2019esprit<\/em>. Paris-Amsterdam&#160;: Had\u00e8s-Benjamins, 1985.<\/li>\n<li class=\"western\"><span style=\"font-size: inherit;\">FLOCH, Jean-Marie. <\/span><em style=\"font-size: inherit;\">S\u00e9miotique, marketing et communication <\/em><span style=\"font-size: inherit;\">&#160;: sous les signes, les strat\u00e9gies. Paris&#160;: PUF, 1990.<\/span><\/li>\n<li class=\"western\"><span style=\"font-size: inherit;\">FLOCH, Jean-Marie. <\/span><em style=\"font-size: inherit;\">Identit\u00e9s visuelles<\/em><span style=\"font-size: inherit;\">. Paris&#160;: PUF, 1995.<\/span><\/li>\n<li class=\"western\"><span style=\"font-size: inherit;\">FLOCH, Jean-Marie. <\/span><em style=\"font-size: inherit;\">Une lecture de Tintin au Tibet<\/em><span style=\"font-size: inherit;\">. Paris&#160;: PUF, 2002.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-culture-numerique\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/culture-numerique\/\" title=\"Culture num\u00e9rique\"><span class=\"termslist-itemname\">Culture num\u00e9rique<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-design\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/design\/\" title=\"Design\"><span class=\"termslist-itemname\">Design<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-semiotique\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/semiotique\/\" title=\"S\u00e9miotique\"><span class=\"termslist-itemname\">S\u00e9miotique<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 18 mai 2022 Th\u00e9matiques Design Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles Num\u00e9rique : strat\u00e9gies, dispositifs et usages R\u00e9ponse attendue pour le 31\/07\/2022 Type de r\u00e9ponse [&hellip;]<\/p>\n","protected":false},"author":1229,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[87,173,77],"thematique":[41,35,39],"sfsic":[],"class_list":["post-24561","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-culture-numerique","tag-design","tag-semiotique","thematique-design","thematique-images-cinema-medias-audiovisuels-et-industries-culturelles","thematique-numerique-strategies-dispositifs-et-usages","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9miotique plastique : limites et expansions<\/title>\n<meta name=\"description\" content=\"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 &quot;S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch&quot; coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9miotique plastique : limites et expansions\" \/>\n<meta property=\"og:description\" content=\"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 &quot;S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch&quot; coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-18T15:44:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T08:10:02+00:00\" \/>\n<meta name=\"author\" content=\"Mossane Trinquelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/\"},\"author\":{\"name\":\"Mossane Trinquelle\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/c6f2a716fe8dd2b6706312f0e53129b8\"},\"headline\":\"S\u00e9miotique plastique : limites et expansions\",\"datePublished\":\"2022-05-18T15:44:13+00:00\",\"dateModified\":\"2022-05-19T08:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/\"},\"wordCount\":1468,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Culture num\u00e9rique\",\"Design\",\"S\u00e9miotique\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/\",\"name\":\"S\u00e9miotique plastique : limites et expansions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2022-05-18T15:44:13+00:00\",\"dateModified\":\"2022-05-19T08:10:02+00:00\",\"description\":\"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 \\\"S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch\\\" coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/semiotique-plastique-limites-et-expansions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"S\u00e9miotique plastique&#160;: limites et expansions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/c6f2a716fe8dd2b6706312f0e53129b8\",\"name\":\"Mossane Trinquelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"caption\":\"Mossane Trinquelle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9miotique plastique : limites et expansions","description":"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 \"S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch\" coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e9miotique plastique : limites et expansions","og_description":"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 \"S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch\" coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/","og_site_name":"SFSIC","article_published_time":"2022-05-18T15:44:13+00:00","article_modified_time":"2022-05-19T08:10:02+00:00","author":"Mossane Trinquelle","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/"},"author":{"name":"Mossane Trinquelle","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/c6f2a716fe8dd2b6706312f0e53129b8"},"headline":"S\u00e9miotique plastique : limites et expansions","datePublished":"2022-05-18T15:44:13+00:00","dateModified":"2022-05-19T08:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/"},"wordCount":1468,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Culture num\u00e9rique","Design","S\u00e9miotique"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/","name":"S\u00e9miotique plastique : limites et expansions","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2022-05-18T15:44:13+00:00","dateModified":"2022-05-19T08:10:02+00:00","description":"La revue br\u00e9silienne Estudos Semioticos lance un appel \u00e0 contributions intitul\u00e9 \"S\u00e9miotique plastique : limites et expansions. Hommage \u00e0 Jean-Marie Floch\" coordonn\u00e9 par Lucia Teixeira et Anne Beyaert-Geslin.","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/semiotique-plastique-limites-et-expansions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"S\u00e9miotique plastique&#160;: limites et expansions"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/c6f2a716fe8dd2b6706312f0e53129b8","name":"Mossane Trinquelle","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","caption":"Mossane Trinquelle"}}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/24561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/1229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=24561"}],"version-history":[{"count":6,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/24561\/revisions"}],"predecessor-version":[{"id":24652,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/24561\/revisions\/24652"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=24561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=24561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=24561"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=24561"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=24561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}