{"id":23289,"date":"2022-03-11T12:20:35","date_gmt":"2022-03-11T11:20:35","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=23289"},"modified":"2022-03-12T18:58:20","modified_gmt":"2022-03-12T17:58:20","slug":"__trashed-8","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/","title":{"rendered":"Innovation et travail"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> 11 mars 2022\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-communication-organisations\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/communication-organisations\/\" title=\"Communication et organisations\"><span class=\"termslist-itemname\">Communication et organisations<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-numerique-strategies-dispositifs-et-usages\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/numerique-strategies-dispositifs-et-usages\/\" title=\"Num\u00e9rique : strat\u00e9gies, dispositifs et usages\"><span class=\"termslist-itemname\">Num\u00e9rique : strat\u00e9gies, dispositifs et usages<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>10\/06\/2022<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>Contribution compl\u00e8te<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Nouvelle Revue du Travail <\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-coordinators\">\n<h3 class=\"zn-singledetail-section-title\">Coordinateurs<\/h3>\n<ul class=\"zn-singledetail-coordinators-list\">\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Samir <\/span> <span>Bedreddine<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>J\u00e9r\u00f4me<\/span> <span>Cihuelo<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-contacts\">\n<h3 class=\"zn-singledetail-section-title\">Contacts<\/h3>\n<ul class=\"zn-singledetail-contacts-list\">\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">Envoi des propositions<\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:nrtravail@gmail.com\">nrtravail@gmail.com<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/journals.openedition.org\/nrt\/\" title=\"Page de la revue\" target=\"_blank\" rel=\"noopener\">Page de la revue<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<p>La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d&rsquo;un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique \u00ab&#160;Innovation et travail&#160;\u00bb sous la direction de\u00a0Samir Bedreddine et J\u00e9r\u00f4me Cihuelo.<\/p>\n<h2>Argumentaire<\/h2>\n<p>Les sciences de gestion se sont tr\u00e8s t\u00f4t int\u00e9ress\u00e9es \u00e0 l\u2019innovation dans ses formes et ses processus, essentiellement dans une perspective prescriptrice. Elles cherchent de mani\u00e8re convergente \u00e0 mod\u00e9liser l\u2019innovation \u00e0 travers la d\u00e9finition de principes organisationnels et de m\u00e9thodes de conception consid\u00e9r\u00e9s comme efficients. Cette orientation normative des travaux men\u00e9s dans le champ de la gestion conduit \u00e0 n\u00e9gliger les effets des dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation sur les salari\u00e9s et sur leur travail. Il s\u2019agit ici de se demander comment l\u2019innovation \u2013 non pens\u00e9e comme une variable de performance, mais saisie dans ses vis\u00e9es manag\u00e9riales \u2013 se voit diff\u00e9remment investie dans les organisations et participe d\u2019une red\u00e9finition des conditions d\u2019activit\u00e9. Elle est pr\u00e9sent\u00e9e par les directions d\u2019entreprises et d\u2019institutions publiques comme un imp\u00e9ratif et une n\u00e9cessit\u00e9 s\u2019imposant de l\u2019ext\u00e9rieur. Elle donne lieu au sein des entreprises \u00e0 l\u2019introduction de dispositifs mettant en avant ces derni\u00e8res ann\u00e9es l\u2019absence de pr\u00e9sence et de r\u00e9gulation hi\u00e9rarchiques. Or, les fins poursuivies en font des dispositifs de management de l\u2019innovation.<\/p>\n<p>Depuis les ann\u00e9es 2010, on assiste \u00e0 une multiplication des lieux d\u00e9di\u00e9s \u00e0 l\u2019innovation, s\u2019\u00e9quipant de diff\u00e9rents dispositifs et utilisant des m\u00e9thodes de conception empruntant au monde du design \u2013 le\u00a0<em>design thinking<\/em>\u00a0en constituant une figure embl\u00e9matique. Bien que ces dispositifs soient orient\u00e9s de mani\u00e8re privil\u00e9gi\u00e9e vers les cadres, l\u2019ambition affich\u00e9e appara\u00eet bien plus large. En effet, les discours et la communication officielle autour de l\u2019innovation s\u2019adressent \u00e0 l\u2019int\u00e9gralit\u00e9 des salari\u00e9s, notamment parce que ces campagnes de sensibilisation et d\u2019enr\u00f4lement revendiquent des dimensions inclusive et participative.\u00a0<em>L\u2019innovation n\u2019est ainsi plus convoqu\u00e9e pour ses perspectives productives, mais devient un mot d\u2019ordre cens\u00e9 irriguer l\u2019int\u00e9gralit\u00e9 des organisations.<\/em><\/p>\n<p>Ce corpus de\u00a0<em>la NRT<\/em>\u00a0se propose ici d\u2019explorer et de questionner cet appel g\u00e9n\u00e9ral(is\u00e9) des organisations \u00e0 l\u2019innovation. La traduction gestionnaire de cette injonction (pressante) \u00e0 l\u2019innovation demande de s\u2019int\u00e9resser \u00e0 des formes de rationalisation privil\u00e9giant l\u2019acc\u00e9l\u00e9ration et \u00e0 ses effets produits sur le travail. La diffusion significative de dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation dans de multiples structures interroge parall\u00e8lement l\u2019\u00e9tendue des formes de r\u00e9appropriation (contournement, d\u00e9tournement, retournement\u2026) dont ils sont l\u2019objet. L\u2019incarnation de cette injonction implique \u00e9galement d\u2019appr\u00e9hender le r\u00f4le jou\u00e9 par les promoteurs de ces dispositifs \u00e0 travers les processus de production et de l\u00e9gitimation \u00e0 l\u2019\u0153uvre et, dans le m\u00eame temps, la conflictualit\u00e9 induite par les diff\u00e9rentes formes de captation et de rivalit\u00e9. Ainsi, le corpus s\u2019attachera \u00e0 interroger l\u2019appel \u00e0 l\u2019innovation \u2013 saisi dans ses discours et dans ses dispositifs \u2013 sous un triple questionnement&#160;: a) comment et jusqu\u2019o\u00f9 participe-t-il d\u2019une recomposition du travail et d\u2019une transformation des organisations&#160;? (<em>ce que l\u2019innovation fait au travail<\/em>)&#160;; b) comment les salari\u00e9s accueillent-ils, s\u2019approprient-ils ou r\u00e9sistent-ils \u00e0 cette injonction outill\u00e9e \u00e0 innover&#160;?\u00a0(<em>ce que les salari\u00e9s font \u00e0 l\u2019innovation<\/em>)&#160;; c) de quelle mani\u00e8re la mise en mot et en dispositif de cet appel \u00e0 l\u2019innovation r\u00e9v\u00e8le-t-elle\u00a0 \u00a0des conflits et des luttes de pouvoir&#160;? (<em>ce que l\u2019innovation l\u00e9gitime et conflictualise<\/em>).<\/p>\n<p>Dans la perspective d\u2019\u00e9clairer les enjeux soulev\u00e9s par l\u2019usage manag\u00e9rial de l\u2019innovation, le corpus s\u2019int\u00e9ressera plus particuli\u00e8rement aux acteurs directement impliqu\u00e9s \u2013 concepteurs, animateurs et participants \u2013 dans les dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation (incubateur, lab, atelier de cr\u00e9ativit\u00e9, acc\u00e9l\u00e9rateur de projet\u2026) et mis en place dans les organisations (entreprises et institutions publiques, y compris les universit\u00e9s). De plus, l\u2019entr\u00e9e notamment par les discours et les mots de l\u2019innovation conduit dans le cadre de cet appel \u00e0 retenir une approche nominaliste. Ainsi, toute activit\u00e9 individuelle et collective appel\u00e9e\u00a0<em>innovation<\/em>\u00a0dans une organisation pourra servir \u00e0 exemplifier le ph\u00e9nom\u00e8ne social actuel de l\u2019innovation.<\/p>\n<p>Les articles propos\u00e9s dans le cadre de ce num\u00e9ro pourront s\u2019inscrire dans une ou plusieurs des perspectives suivantes&#160;:<\/p>\n<h3>L\u2019innovation \u00e0 travers ses dispositifs&#160;: mobilisation des salari\u00e9s et cadrage de l\u2019activit\u00e9<\/h3>\n<p>Les promesses port\u00e9es et les formes de rationalisation privil\u00e9gi\u00e9es par les dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation interrogent sur ce qu\u2019elles font durablement au travail et aux organisations.<\/p>\n<p>La diffusion au sein des organisations de ces dispositifs (incubateur, acc\u00e9l\u00e9rateur, espace de cr\u00e9ativit\u00e9, ateliers collaboratifs\u2026) interroge \u00e0 double titre sur les effets produits sur l\u2019activit\u00e9 de travail. D\u2019une part, les m\u00e9thodes introduites et les formes d\u2019engagement valoris\u00e9es demandent d\u2019appr\u00e9cier la nature et la profondeur des \u00e9volutions dans les pratiques professionnelles. Il s\u2019agira ici d\u2019analyser ce qu\u2019elles font au travail, \u00e0 la fois dans les espaces d\u00e9di\u00e9s \u00e0 l\u2019innovation et dans les environnements quotidiens de travail. D\u2019autre part, les dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation r\u00e9pondent \u00e0 un r\u00e9gime temporel privil\u00e9giant la r\u00e9versibilit\u00e9 des activit\u00e9s dans des horizons temporels rapproch\u00e9s. Ils participent d\u2019une recherche de compression et de flexibilisation des temps. Cette organisation temporelle du travail sur l\u2019innovation questionne sur la mani\u00e8re dont elle oriente et fa\u00e7onne l\u2019activit\u00e9 des salari\u00e9s.<\/p>\n<p>Par-del\u00e0 la promesse d\u2019une innovation permanente, l\u2019efficience revendiqu\u00e9e des m\u00e9thodes de cr\u00e9ativit\u00e9, intrins\u00e8quement li\u00e9es \u00e0 ces dispositifs, interroge dans le m\u00eame temps leur port\u00e9e effective et leur traduction concr\u00e8te. Quelle est la nature des productions r\u00e9alis\u00e9es&#160;? Dans le meilleur des cas, \u00e0 quel type d\u2019innovation aboutissent-elles et avec quelles temporalit\u00e9s&#160;? Jusqu\u2019o\u00f9 ces innovations parviennent-elles \u00e0 se diffuser et avec quels effets\u00a0sur les activit\u00e9s&#160;? De quelle mani\u00e8re les organisations s\u2019en saisissent-elles et en portent-elles la trace&#160;?<\/p>\n<h3>L\u2019innovation \u00e0 travers ses contributeurs&#160;: co\u00fbts de la participation et r\u00e9appropriation<\/h3>\n<p>L\u2019engagement attendu dans les dispositifs et les espaces d\u00e9di\u00e9s \u00e0 l\u2019innovation interroge, du point de vue des contributeurs, la teneur de l\u2019implication demand\u00e9e et le co\u00fbt de la participation. En contrepoint de l\u2019implication recherch\u00e9e par les organisateurs et les promoteurs de ces dispositifs, l\u2019analyse des dynamiques de participation conduit \u00e9galement \u00e0 porter la r\u00e9flexion sur les modes de r\u00e9investissement. Elle demande \u00e0 s\u2019int\u00e9resser aux diff\u00e9rentes strat\u00e9gies de contournement et de d\u00e9tournement mises en \u0153uvre par les salari\u00e9s mobilis\u00e9s. Elle am\u00e8ne aussi \u00e0 se questionner sur les formes de r\u00e9appropriation sous l\u2019angle des profits symboliques pouvant \u00eatre retir\u00e9s par les participants.<\/p>\n<p>Subs\u00e9quemment, ce sont les dispositions des agents qui participent et s\u2019investissent dans ces dispositifs d\u2019innovation qui pourront \u00eatre explicit\u00e9es dans cet axe de l\u2019appel. Les effets de socialisation pourront \u00e9galement \u00eatre abord\u00e9s afin de montrer comment certaines de ces dispositions permettent \u00e0 des agents d\u2019alimenter la fonction de rep\u00e9rage salarial que constituent les diff\u00e9rents ateliers, formations ou groupes de projet d\u00e9di\u00e9s \u00e0 l\u2019innovation.<\/p>\n<h3>L\u2019innovation \u00e0 travers ses promoteurs&#160;: l\u00e9gitimation et confrontation<\/h3>\n<p>L\u2019analyse des ressorts de la mobilisation recherch\u00e9e par ces dispositifs demande \u00e9galement de porter une attention aux acteurs quant \u00e0 leur organisation, \u00e0 leur trajectoire et \u00e0 leur promotion. Elle conduit ici \u00e0 interroger la dimension politique de l\u2019innovation sous le prisme de sa l\u00e9gitimation et de ses confrontations.<\/p>\n<p>Il s\u2019agit de s\u2019int\u00e9resser au profil et aux trajectoires socio-professionnelles des organisateurs et des animateurs de ces dispositifs, notamment en rendant compte de la mani\u00e8re dont ils contribuent \u00e0 favoriser l\u2019implication recherch\u00e9e. Quels types de dispositions et de modes d\u2019engagement encouragent-ils et valorisent-ils&#160;? Quels sont les techniques utilis\u00e9es, les postures retenues et les discours produits pour susciter l\u2019engagement recherch\u00e9 et parvenir \u00e0 l\u2019int\u00e9riorisation de conceptions souvent associ\u00e9es \u00e0 l\u2019univers des\u00a0<em>start-up<\/em>&#160;? Comment parviennent-ils \u00e0 l\u00e9gitimer les dispositifs et \u00e0 se l\u00e9gitimer dans un r\u00f4le reconnu d\u2019animateur&#160;?<\/p>\n<p>Au-del\u00e0 de la vision d\u2019apparence consensuelle de l\u2019innovation, cette derni\u00e8re requiert d\u2019\u00eatre saisie dans la conflictualit\u00e9 entourant ses dispositifs. \u00c0 l\u2019\u00e9chelle d\u2019entit\u00e9s d\u2019organisations (directions R&amp;D, de l\u2019innovation, financi\u00e8re, op\u00e9rationnelle\u2026), l\u2019analyse pourra se porter sur les rapports de force intervenant dans les conditions de production, de captation ou de contestation des dispositifs en jeu. D\u2019une autre mani\u00e8re et \u00e0 la hauteur de groupes d\u2019acteurs plus ou moins constitu\u00e9s, elle pourra rendre compte des luttes autour de la d\u00e9finition de l\u2019innovation et de territoires professionnels visant \u00e0 l\u2019accaparer.<\/p>\n<h3>L\u2019innovation \u00e0 travers ses sc\u00e8nes&#160;: circulation et articulation des lieux d\u2019activit\u00e9<\/h3>\n<p>La multiplication des dispositifs d\u00e9di\u00e9s demande de s\u2019int\u00e9resser aux circulations et aux articulations entre les diff\u00e9rents lieux de l\u2019activit\u00e9. D\u00e8s lors, comment ces dispositifs prennent-ils place dans l\u2019activit\u00e9 globale de leurs participants alors que leur articulation avec le reste de l\u2019organisation appara\u00eet souvent comme impens\u00e9e&#160;? Dans quelle mesure l\u2019autonomie spatio-temporelle de ces dispositifs peut-elle venir alimenter des conflits de temporalit\u00e9 et\/ou de rationalit\u00e9 avec des modes d\u2019organisation durablement install\u00e9s (gestion par processus et par projet)&#160;? Jusqu\u2019o\u00f9 et \u00e0 quel prix les salari\u00e9s parviennent-ils \u00e0 relier les diff\u00e9rents lieux et temps de leur activit\u00e9&#160;?<\/p>\n<p>La circulation (r\u00e9p\u00e9t\u00e9e) entre les espaces d\u00e9di\u00e9s \u00e0 l\u2019innovation et les environnements quotidiens de travail place les salari\u00e9s \u00e0 la fronti\u00e8re d\u2019univers organisationnels aux modes de fonctionnement sp\u00e9cifiques, sinon \u00e9loign\u00e9s. Cette situation de double insertion interroge sur la r\u00e9ceptivit\u00e9 et l\u2019appui trouv\u00e9s dans l\u2019environnement quotidien de travail (hi\u00e9rarchie de proximit\u00e9 et coll\u00e8gues de travail). Comment les salari\u00e9s parviennent-ils \u00e0 se l\u00e9gitimer et \u00e0 faire reconna\u00eetre leur investissement sur plusieurs sc\u00e8nes de travail&#160;? La place occup\u00e9e et les relations de travail dans le collectif de travail se trouvent-elles dans le m\u00eame temps modifi\u00e9es&#160;? Assiste-t-on \u00e0 l\u2019installation de clivages et de rapports de rivalit\u00e9 entre salari\u00e9s&#160;?<\/p>\n<p>Les articles attendus mobiliseront des recherches fond\u00e9es sur des analyses empiriques et critiques de dispositifs d\u00e9di\u00e9s \u00e0 l\u2019innovation au sein d\u2019entreprises ou d\u2019organisations publiques ou priv\u00e9es. Cet appel s\u2019adresse autant aux chercheurs en sciences sociales et humaines (sciences de gestion, sociologie, anthropologie, \u00e9conomie, histoire, philosophie, psychologie\u2026) qu\u2019aux praticiens en g\u00e9n\u00e9ral.<\/p>\n<h2>Modalit\u00e9s de soumission et calendrier<\/h2>\n<p>Les propositions d\u2019articles ne doivent pas d\u00e9passer les\u00a0<strong>45 000 signes<\/strong>\u00a0(espaces et bibliographie compris), les m\u00e9tadonn\u00e9es (noms, r\u00e9sum\u00e9s et mots cl\u00e9s en fran\u00e7ais et anglais) figurant dans un fichier \u00e0 part.<\/p>\n<p>Elles doivent \u00eatre adress\u00e9es, en format Word ou odt, avant le\u00a0<strong>10 juin 2022<\/strong>\u00a0\u00e0\u00a0<strong>nrtravail@gmail.com<\/strong>\u00a0(exclusivement) en suivant les modalit\u00e9s et les normes de pr\u00e9sentation pr\u00e9cis\u00e9es \u00e0 la rubrique \u00ab&#160;<a href=\"https:\/\/journals.openedition.org\/nrt\/531\" target=\"_blank\" rel=\"noopener\">Soumission et \u00e9valuation<\/a>&#160;\u00bb du site de\u00a0<em>La NRT.<\/em><\/p>\n<p>Le num\u00e9ro 22 para\u00eetra au printemps 2023<\/p>\n<h2>Modalit\u00e9s de s\u00e9lection<\/h2>\n<p class=\"texte\">Les articles, anonymis\u00e9s par les auteur\u00b7es ou rendus anonymes par le secr\u00e9tariat de r\u00e9daction, sont distribu\u00e9s par le\u00a0<a href=\"https:\/\/journals.openedition.org\/nrt\/528\" target=\"_blank\" rel=\"noopener\">comit\u00e9 de r\u00e9daction<\/a>\u00a0(via le secr\u00e9taire de r\u00e9daction) \u00e0 deux experts internes au comit\u00e9 de r\u00e9daction et \u00e0 un expert ext\u00e9rieur (appartenant au comit\u00e9 de lecture ou sp\u00e9cialiste ext\u00e9rieur). Les trois \u00e9valuateurs rendent un rapport \u00e9crit (et anonyme) avec une conclusion claire sur le caract\u00e8re publiable ou non de l\u2019article. Ces rapports sont d\u00e9battus en comit\u00e9 de r\u00e9daction pour pr\u00e9parer la synth\u00e8se adress\u00e9e \u00e0 l\u2019auteur (toujours de fa\u00e7on anonyme), avec les recommandations d\u2019am\u00e9lioration de l\u2019article dans une nouvelle version si celui-ci n\u2019a pas \u00e9t\u00e9 refus\u00e9.<\/p>\n<p class=\"texte\">La politique de la revue consiste \u00e0 encourager les auteurs, dont les papiers ne sont pas jug\u00e9s publiables en l\u2019\u00e9tat, \u00e0 les reprendre \u00e0 partir des pistes sugg\u00e9r\u00e9es par les relecteurs de la revue.<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-dispositifs\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/dispositifs\/\" title=\"Dispositifs\"><span class=\"termslist-itemname\">Dispositifs<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-innovation\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/innovation\/\" title=\"Innovation\"><span class=\"termslist-itemname\">Innovation<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-travail\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/travail\/\" title=\"Travail\"><span class=\"termslist-itemname\">Travail<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 11 mars 2022 Th\u00e9matiques Communication et organisations Num\u00e9rique : strat\u00e9gies, dispositifs et usages R\u00e9ponse attendue pour le 10\/06\/2022 Type de r\u00e9ponse Contribution compl\u00e8te Type de contribution [&hellip;]<\/p>\n","protected":false},"author":1229,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[315,92,109],"thematique":[37,39],"sfsic":[],"class_list":["post-23289","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-dispositifs","tag-innovation","tag-travail","thematique-communication-organisations","thematique-numerique-strategies-dispositifs-et-usages","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovation et travail<\/title>\n<meta name=\"description\" content=\"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d&#039;un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique &quot;Innovation et travail&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovation et travail\" \/>\n<meta property=\"og:description\" content=\"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d&#039;un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique &quot;Innovation et travail&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T11:20:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-12T17:58:20+00:00\" \/>\n<meta name=\"author\" content=\"Mossane Trinquelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/\"},\"author\":{\"name\":\"Mossane Trinquelle\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/c6f2a716fe8dd2b6706312f0e53129b8\"},\"headline\":\"Innovation et travail\",\"datePublished\":\"2022-03-11T11:20:35+00:00\",\"dateModified\":\"2022-03-12T17:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/\"},\"wordCount\":2149,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Dispositifs\",\"Innovation\",\"Travail\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/\",\"name\":\"Innovation et travail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2022-03-11T11:20:35+00:00\",\"dateModified\":\"2022-03-12T17:58:20+00:00\",\"description\":\"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d'un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique \\\"Innovation et travail\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/__trashed-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Innovation et travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/c6f2a716fe8dd2b6706312f0e53129b8\",\"name\":\"Mossane Trinquelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g\",\"caption\":\"Mossane Trinquelle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovation et travail","description":"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d'un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique \"Innovation et travail\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/","og_locale":"en_US","og_type":"article","og_title":"Innovation et travail","og_description":"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d'un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique \"Innovation et travail\".","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/","og_site_name":"SFSIC","article_published_time":"2022-03-11T11:20:35+00:00","article_modified_time":"2022-03-12T17:58:20+00:00","author":"Mossane Trinquelle","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/"},"author":{"name":"Mossane Trinquelle","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/c6f2a716fe8dd2b6706312f0e53129b8"},"headline":"Innovation et travail","datePublished":"2022-03-11T11:20:35+00:00","dateModified":"2022-03-12T17:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/"},"wordCount":2149,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Dispositifs","Innovation","Travail"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/","name":"Innovation et travail","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2022-03-11T11:20:35+00:00","dateModified":"2022-03-12T17:58:20+00:00","description":"La revue Nouvelle Revue du travail lance un appel \u00e0 contribution pour un article en vue d'un num\u00e9ro d\u00e9di\u00e9 \u00e0 la th\u00e9matique \"Innovation et travail\".","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/__trashed-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"Innovation et travail"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/c6f2a716fe8dd2b6706312f0e53129b8","name":"Mossane Trinquelle","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c790e85c72ef19ed5ee42f0009e741b68d9667b859edc1612b917407dc469d2?s=96&d=mm&r=g","caption":"Mossane Trinquelle"}}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/23289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/1229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=23289"}],"version-history":[{"count":5,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/23289\/revisions"}],"predecessor-version":[{"id":23390,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/23289\/revisions\/23390"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=23289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=23289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=23289"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=23289"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=23289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}