{"id":20495,"date":"2021-11-30T14:46:13","date_gmt":"2021-11-30T13:46:13","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=20495"},"modified":"2021-11-29T17:46:51","modified_gmt":"2021-11-29T16:46:51","slug":"pour-une-nouvelle-hermeneutique-des-formes-symboliques","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/","title":{"rendered":"Pour une nouvelle herm\u00e9neutique des formes symboliques."},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> 29 novembre 2021\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-mediations-memorielles-culturelles-et-patrimoniales\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/thematiques\/memorial-cultural-and-heritage-mediation\/\" title=\"M\u00e9diations m\u00e9morielles, culturelles et patrimoniales\"><span class=\"termslist-itemname\">M\u00e9diations m\u00e9morielles, culturelles et patrimoniales<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-numerique-strategies-dispositifs-et-usages\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/thematiques\/digital-strategies-devices-and-uses-en\/\" title=\"Num\u00e9rique : strat\u00e9gies, dispositifs et usages\"><span class=\"termslist-itemname\">Num\u00e9rique : strat\u00e9gies, dispositifs et usages<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>15\/05\/2022<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>Contribution compl\u00e8te<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Signata. Annales des s\u00e9miotiques<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-coordinators\">\n<h3 class=\"zn-singledetail-section-title\">Coordinateurs<\/h3>\n<ul class=\"zn-singledetail-coordinators-list\">\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Pierluigi <\/span> <span>Basso Fossali<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:pierluigi.basso@univ-lyon2.fr\">pierluigi.basso@univ-lyon2.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Ralph <\/span> <span>Dekoninck<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:ralph.dekoninck@uclouvain.be\">ralph.dekoninck@uclouvain.be<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Maria Giulia <\/span> <span>Dondero<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:mariagiulia.dondero@uliege.be\">mariagiulia.dondero@uliege.be<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Sophie <\/span> <span>Raux<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:sophie.raux@univ-lyon2.fr\">sophie.raux@univ-lyon2.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-contacts\">\n<h3 class=\"zn-singledetail-section-title\">Contacts<\/h3>\n<ul class=\"zn-singledetail-contacts-list\">\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">Maria Giulia Dondero<\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:mariagiulia.dondero@uliege.be\">mariagiulia.dondero@uliege.be<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/journals.openedition.org\/signata\/3422\" title=\"Site de l'appel\" target=\"_blank\" rel=\"noopener\">Site de l&#8217;appel<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<div class=\"textandnotes\">\n<p>La notion de \u00ab&#160;forme&#160;\u00bb a travers\u00e9 les th\u00e9ories de l\u2019art avec une ambigu\u00eft\u00e9 constitutive&#160;: d\u2019une part, elle a r\u00e9pondu \u00e0 l\u2019aspiration \u00e0 une sorte de matrice originaire des enjeux esth\u00e9tiques (d\u00e9rive id\u00e9aliste), d\u2019autre part elle a \u00e9t\u00e9 l\u2019atout pour proposer une version r\u00e9ductionniste du faire artistique au profit d\u2019une po\u00e9tique particuli\u00e8re (d\u00e9rive id\u00e9ologique). Le xx<sup>e<\/sup> si\u00e8cle nous laisse en h\u00e9ritage un cadre th\u00e9orique controvers\u00e9 pour essayer d\u2019\u00e9chapper \u00e0 ces d\u00e9rives. Certes, on a abandonn\u00e9 une s\u00e9paration nette entre la forme et le contenu, ce dernier ne pouvant pas s\u2019exprimer sans une forme et la forme ne pouvant pas se manifester sans solliciter des contenus perceptifs et une port\u00e9e diagrammatique \u00e0 m\u00eame de proposer une r\u00e9organisation des valeurs repr\u00e9sent\u00e9es. Pourtant, le tournant linguistique et, en particulier, la tradition structuraliste, qui a \u00e9tabli le principe d\u2019articulation entre expression et contenu, a continu\u00e9 \u00e0 proposer une r\u00e9actualisation de la notion de forme, notamment en tant que \u00ab&#160;forme symbolique&#160;\u00bb (Cassirer 1923-1929). Cette derni\u00e8re peut \u00eatre entendue comme la cl\u00e9 de la compr\u00e9hension diachronique de l\u2019\u00e9volution des g\u00e9n\u00e9alogies culturelles<a id=\"bodyftn1\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/signata\/3422#ftn1\">1<\/a>. Au-del\u00e0 du p\u00e9rim\u00e8tre strictement structuraliste et sans aucune intention de r\u00e9veiller la tradition d\u2019un formalisme id\u00e9aliste, on constate, au d\u00e9but du si\u00e8cle dernier, une reprise constante de la notion de forme&#160;: les <em>Pathosformeln<\/em> de Warburg, la proposition d\u2019une histoire des formes (de Focillon \u00e0 Kubler), le projet iconologique de Panofsky, sans oublier la le\u00e7on de W\u00f6lfflin.<\/p>\n<\/div>\n<div class=\"textandnotes\">\n<p class=\"texte\">Ce num\u00e9ro de <em>Signata<\/em> vise \u00e0 faire le point sur le caract\u00e8re heuristique de cette notion de <em>forme<\/em> (ou de formule, chez Warburg<a id=\"bodyftn2\" class=\"footnotecall\" href=\"https:\/\/journals.openedition.org\/signata\/3422#ftn2\">2<\/a>) et de l\u2019\u00e9valuer \u00e0 partir des ambitions d\u2019une histoire de l\u2019art qui recourt de plus en plus aux nouvelles technologies. On s\u2019aper\u00e7oit imm\u00e9diatement de la pr\u00e9sence de plusieurs enjeux et fronts de recherche \u00e0 aborder&#160;: (i) une r\u00e9actualisation critique de la notion de <em>forme<\/em> \u00e0 partir du d\u00e9bat contemporain en histoire de l\u2019art, en l\u2019int\u00e9grant aux apports des \u00e9tudes visuelles et de la s\u00e9miotique&#160;; (ii) une d\u00e9finition op\u00e9rationnelle de la notion de <em>forme<\/em> afin qu\u2019elle puisse \u00eatre impl\u00e9ment\u00e9e dans des programmes de traitement automatique de l\u2019image&#160;; (iii) une \u00e9laboration effective d\u2019un programme d\u2019histoire des formes \u00e0 m\u00eame de construire une articulation, dans les \u00e9tudes diachroniques, entre l\u2019histoire (num\u00e9rique) de l\u2019art et la s\u00e9miotique de l\u2019art.<\/p>\n<\/div>\n<p class=\"texte\">Ce num\u00e9ro vise \u00e0 reconsid\u00e9rer les acquis et les cat\u00e9gorisations d\u00e9sormais tacites&#160;; en m\u00eame temps, il veut offrir une seconde chance \u00e0 des parcours d\u2019enqu\u00eate consid\u00e9r\u00e9s comme des impasses ou comme des approches st\u00e9riles. Pour favoriser la catalyse de ce r\u00e9examen, nous estimons qu\u2019il serait pertinent d\u2019articuler ce qui nous vient de l\u2019actualit\u00e9 \u2014 le tournant num\u00e9rique de nos \u00e9tudes en sciences humaines \u2014 avec la latence d\u2019une tradition \u2013 celle de l\u2019histoire des formes symboliques \u2014 qui n\u2019a pas pu exprimer son potentiel en l\u2019absence de moyens. En effet, sans le support du num\u00e9rique, on est face \u00e0 l\u2019impossibilit\u00e9 de travailler de mani\u00e8re comparative sur de larges corpus d\u2019images et donc d\u2019annoter et de r\u00e9pertorier traits et motifs plus ou moins r\u00e9currents et travers\u00e9s par des \u00e9volutions vari\u00e9es. Cela dit, le fait que des th\u00e9ories du pass\u00e9 sont rest\u00e9es, au moins en partie, programmatiques, voire \u00e0 l\u2019\u00e9tat d\u2019intuitions, ne doit pas \u00e0 pr\u00e9sent mener \u00e0 une \u00ab&#160;d\u00e9volution&#160;\u00bb du travail de l\u2019historien ou du s\u00e9mioticien aux machines et aux logiciels. Si l\u2019analyse assist\u00e9e par ordinateur a \u00e9t\u00e9 beaucoup discut\u00e9e, c\u2019est parce que le traitement automatique des donn\u00e9es ne peut rester qu\u2019un passage au sein d\u2019une pratique interpr\u00e9tative qui d\u00e9passe les horizons machiniques et qui englobe des moyens critiques suppl\u00e9mentaires pour parvenir \u00e0 ces objectifs. Au fond, nous pourrions renverser l\u2019expression rh\u00e9torique habituelle pour souligner la dimension compl\u00e9mentaire du \u00ab&#160;calcul assist\u00e9 par l\u2019interpr\u00e9tation&#160;\u00bb.<\/p>\n<p class=\"texte\">Cette version \u00ab&#160;chiasmatique&#160;\u00bb de l\u2019assistance mutuelle entre machine et interpr\u00e8te peut \u00eatre une bonne piste pour corriger certaines erreurs du pass\u00e9, mais il est possible qu\u2019elle n\u2019arrive pas encore \u00e0 tenir compte des avanc\u00e9es sur le plan des technologies disponibles. Quand on parle de <em>deep learning<\/em>, on renvoie \u00e0 un apprentissage de la machine structur\u00e9 sur des architectures \u00e0 divers niveaux de repr\u00e9sentation&#160;; ces niveaux sont hi\u00e9rarchis\u00e9s entre eux et susceptibles de prendre l\u2019un le relais de l\u2019autre et d\u2019accompagner ainsi des traitements non lin\u00e9aires et r\u00e9cursifs des donn\u00e9es. La plupart des calculs pourrait \u00eatre r\u00e9duite \u00e0 l\u2019extraction de l\u2019information et \u00e0 la reconnaissance des mod\u00e8les&#160;; mais d\u00e8s que le <em>deep learning<\/em> est assum\u00e9 comme une proth\u00e8se par un chercheur, il semble construire un nouveau regard sur les ph\u00e9nom\u00e8nes investigu\u00e9s et, bien que pas neutre, il apporte de la connaissance et donc une significativit\u00e9 des r\u00e9sultats qui d\u00e9passent la simple reconnaissance.<\/p>\n<p class=\"texte\">Pour aller jusqu\u2019au bout des r\u00e9flexions et des enqu\u00eates que notre num\u00e9ro voudrait promouvoir, il nous semble que, comme dans une boucle, les formes artistiques que l\u2019on veut faire \u00e9merger et \u00e9tudier deviennent non seulement des observables \u00e0 traverse des dispositifs num\u00e9riques, mais elles sont \u00e9clair\u00e9es aussi par la forme symbolique que ces derniers expriment, laquelle devient une autre modalit\u00e9 de compr\u00e9hension \u2014 ou, si l\u2019on pr\u00e9f\u00e8re \u2014 d\u2019autocompr\u00e9hension de notre culture. Mais le fait que l\u2019on trouve en m\u00eame temps des formes symboliques assum\u00e9es comme corpus d\u2019analyse, \u00e0 savoir comme s\u00e9miotique-objet, et un \u0153il num\u00e9rique qui apporte lui aussi sa forme symbolique sur le plan de l\u2019objectivation \u2014 s\u00e9miotique descriptive \u2014 n\u2019indique pas une hi\u00e9rarchisation et une construction unilat\u00e9rale. Dans les sciences humaines, l\u2019objet ne peut pas \u00eatre construit unilat\u00e9ralement par le regard, \u00e9tant donn\u00e9 que cet objet exerce des contraintes dues \u00e0 son statut d\u2019h\u00e9ritage culturel et \u00e0 ses propres vis\u00e9es \u00e9pist\u00e9miques. Bref, ce num\u00e9ro est aussi un dialogue critique entre art et science, une rencontre entre des formes symboliques qui affiche des homologies mais aussi des r\u00e9sistances, des reconnaissances mais aussi des points aveugles, des r\u00e9sultats significatifs et des insignifiances. C\u2019est \u00e0 partir de ce regard non innocent de la machine, mais tout de m\u00eame capable de sa propre \u201cprofondeur\u201d, que nous voudrions inviter \u00e0 ce d\u00e9bat s\u00e9mioticiens, historiens de l\u2019art, informaticiens ou d\u2019autres coll\u00e8gues encore qui travaillent dans le domaine des humanit\u00e9s num\u00e9riques.<\/p>\n<p class=\"texte\">L\u2019objectif est aussi de comprendre les enjeux de la <em>Digital Art History<\/em> en tant que \u201cnum\u00e9rique\u201d (donc, avec sa propre forme symbolique) et les perspectives d\u2019une histoire de l\u2019art qui pense pouvoir profiter du num\u00e9rique tout en objectivant son apport comme <em>une <\/em>mani\u00e8re d\u2019acc\u00e9der au patrimoine. Le fait de mettre en perspective les formes symboliques et de questionner leur m\u00e9diation demande l\u2019intervention d\u2019une r\u00e9flexion s\u00e9miotique, ce qui explique l\u2019accueil pertinent que <em>Signata<\/em> pourra assurer \u00e0 des contributions qui toucheront de mani\u00e8re implicite et explicite les n\u0153uds probl\u00e9matiques que nous avons essay\u00e9 d\u2019illustrer.<\/p>\n<p class=\"texte\">Il nous semble enfin que, pour faire dialoguer des images observ\u00e9es et des instances observatrices, la notion de <em>forme<\/em> peut fonctionner comme la mise en abyme, voire le syst\u00e8me de reflets le plus appropri\u00e9. La forme symbolique n\u2019est pas id\u00e9aliste, mais ancr\u00e9e dans des dispositifs techniques, li\u00e9es \u00e0 une tradition pratique et attest\u00e9e par une g\u00e9n\u00e9alogie de repr\u00e9sentations. Chaque image artistique r\u00e9pond \u00e0 d\u2019autres images&#160;; cette r\u00e9ponse peut relever d\u2019un projet mais elle peut \u00e9merger aussi de mani\u00e8re non intentionnelle comme r\u00e9v\u00e9lation progressive de l\u2019appartenance \u00e0 une famille d\u2019images.<\/p>\n<p class=\"texte\">L\u2019arch\u00e9ologie des formes artistiques travaille sur une ouverture indiciaire et donc sur des g\u00e9n\u00e9alogies possibles, le d\u00e9terminisme causal n\u2019\u00e9tant que le fruit d\u2019un r\u00e9ductionnisme. Milieu culturel d\u2019appartenance, \u00e9poque, techniques disponibles, rencontres artistiques, mouvements collectifs, etc. restent des facteurs multiples et copr\u00e9sents dont la forme artistique assum\u00e9e par l\u2019\u0153uvre n\u2019est qu\u2019une r\u00e9ponse synth\u00e9tique, lisible seulement dans une trame d\u2019intentionnalit\u00e9s convergentes ou divergentes (cf. Baxandall 1985). Mais justement on ne pourra d\u00e9crire cette trame qu\u2019<em>a posteriori<\/em> et \u00e0 partir d\u2019une position oblig\u00e9e \u00e0 expliciter, \u00e0 son tour, son point de d\u00e9part, par exemple la trame d\u2019intentionnalit\u00e9s qui est son propre courant disciplinaire.<\/p>\n<p class=\"texte\">En pr\u00e9sentant la forme symbolique comme l\u2019intersection d\u2019une trame d\u2019intentionnalit\u00e9 et d\u2019une g\u00e9n\u00e9alogie de repr\u00e9sentations, nous visons ainsi \u00e0 rapprocher les regards de l\u2019histoire de l\u2019art traditionnelle et sa version num\u00e9rique, des iconologues et des s\u00e9mioticiens, des humanistes et des informaticiens. Mais aux figures scientifiques il faudra ajouter enfin toutes les taxonomies et les histoires informelles des formes symboliques que l\u2019on trouve dans notre soci\u00e9t\u00e9 num\u00e9rique. Elles montrent en transparence un regard et des reconstructions g\u00e9n\u00e9alogiques, certes non scientifiques, parfois aberrantes, mais capables d\u2019exemplifier en tout cas une forme symbolique. Cette derni\u00e8re n\u2019est pas toujours \u00e0 patrimonialiser et, au fond, favoriser son analyse veut dire aussi promouvoir sa d\u00e9mythification, voire sa d\u00e9construction critique, si n\u00e9cessaire. En ce sens, ce num\u00e9ro veut promouvoir aussi des comparaisons entre des formes symboliques re\u00e7ues et reconstruites, en analysant les diff\u00e9rences de vocation (autoattribu\u00e9e) et de statut (artistique, scientifique, mythique, etc.).<\/p>\n<h2 class=\"section\"><span class=\"text\">Bibliographie<\/span><\/h2>\n<div id=\"bibliography\" class=\"section\">\n<div class=\"text\">\n<p class=\"bibliographie\">Arasse, Daniel (1999), <em>L\u2019Annonciation italienne. Une histoire de perspective<\/em>, Paris, Hazan, 1999.<\/p>\n<p class=\"bibliographie\">Basso Fossali Pierluigi (2013), <em>Il Trittico 1976 di Francis Bacon. Con note sulla semiotica della pittura<\/em>, Pisa, ETS.<\/p>\n<p class=\"bibliographie\">Basso Fossali Pierluigi (2014), \u00ab&#160;Histoire des formes entre diachronie et arch\u00e9ologie&#160;\u00bb, in D.\u00a0Bertrand <em>et al.<\/em> (dir.), <em>S\u00e9miotique et diachronie. Actes du Congr\u00e8s de l\u2019Association Fran\u00e7aise de S\u00e9miotique 2013<\/em>, Site de l\u2019AFS, pp.\u00a01-12. <a href=\"http:\/\/afsemio.fr\/wp-content\/uploads\/3.-Basso-Fossali-AFS-2013.pdf\">http:\/\/afsemio.fr\/wp-content\/uploads\/3.-Basso-Fossali-AFS-2013.pdf<\/a>.<\/p>\n<p class=\"bibliographie\">Basso Fossali Pierluigi (2019), \u00ab&#160;L\u2019image du devenir&#160;: le monde en chiffre et la passion du monitorage&#160;\u00bb, <em>Signata &#8211; Annals of Semiotics<\/em>, n<sup>o<\/sup>\u00a010, \u00ab&#160;Image et connaissance&#160;\u00bb. DOI&#160;: <a href=\"https:\/\/doi.org\/10.4000\/signata.2261\">https:\/\/doi.org\/10.4000\/signata.2261<\/a>.<br \/>\nDOI&#160;: <a class=\"doi\" href=\"http:\/\/dx.doi.org\/10.4000\/signata.2261\">10.4000\/signata.2261<\/a><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Baxandall Michael (1985), P<\/span><em><span lang=\"en\" xml:lang=\"en\">atterns of intention. On the Historical Explanation of Pictures<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, New Haven and London, Yale University Press&#160;; tr.\u00a0fr. <\/span><em>Formes de l\u2019intention. Sur l\u2019explication historique des tableaux<\/em>, N\u00eemes, Jacqueline Chambon, 1991.<\/p>\n<p class=\"bibliographie\">Cassirer, Ernst (1923\u20131929), <em>Philosophie der symbolischen Formen<\/em>, Berlin, Bruno Cassirer&#160;; tr.\u00a0fr. <em>La Philosophie des formes symboliques<\/em>, 3 tomes, Paris, \u00c9ditions de Minuit, 1972&#160;; eng. trans. <em>Philosophy of Symbolic Forms<\/em>, London, Routledge, 2020.<\/p>\n<p class=\"bibliographie\">Colas-Blaise Marion (2018), \u00ab&#160;La s\u00e9miotique visuelle naissante&#160;: Greimas et sa post\u00e9rit\u00e9&#160;\u00bb, <em>La Part de l\u2019\u0153il<\/em>, n<sup>o<\/sup>\u00a032, pp.\u00a0275-295.<\/p>\n<p class=\"bibliographie\">Damisch Hubert (1987), <em>L\u2019Origine de la perspective<\/em>, Paris, Flammarion&#160;; eng. trans. <em>The Origin of Perspective<\/em>, Cambridge (Mass.), the MIT Press, 1994.<\/p>\n<p class=\"bibliographie\">Dekoninck Ralph (2016), <em>La Vision incarnante et l\u2019image incarn\u00e9e. Santi di Tito et Caravage<\/em>, Paris, 1\u00a0:1 \u00e9ditions.<\/p>\n<p class=\"bibliographie\">Dekoninck Ralph et Guiderdoni Agn\u00e8s (dir. 2017), \u00ab&#160;Force de figures&#160;: le travail de la figurabilit\u00e9 entre texte et image&#160;\u00bb, <em>La Part de l\u2019\u0153il<\/em>, n<sup>o<\/sup>\u00a031 (2017-2018).<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Didi Huberman Georges (2002), <\/span><em><span lang=\"en\" xml:lang=\"en\">L\u2019Image survivante<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Paris, Seuil&#160;; eng. trans. <\/span><em><span lang=\"en\" xml:lang=\"en\">The Surviving Image&#160;: Phantoms of Time and Time of Phantoms<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, University Park, Penn State University Press, 2016.<\/span><\/p>\n<p class=\"bibliographie\">Didi Huberman Georges (2011), <em>Atlas ou le gai savoir inquiet. L\u2019\u0152il de l\u2019histoire<\/em>, Paris, \u00e9d. de Minuit&#160;; eng. trans. <em><span lang=\"en\" xml:lang=\"en\">Atlas, or the Anxious Gay Science<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Chicago, University of Chicago Press, 2018.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Di Lenardo Isabella, Seguin Benoit, &amp; Kaplan Fr\u00e9d\u00e9ric (2016), \u201cVisual Patterns Discovery in Large Databases of Paintings\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">Digital Humanities<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, DH 2016&#160;: Krakow, Poland, July 11-16, 2016, pp.\u00a0169-172. <\/span><a href=\"https:\/\/infoscience.epfl.ch\/record\/220638\/files\/diLenardo-Seguin-Kaplan-DH2016.pdf\">https:\/\/infoscience.epfl.ch\/record\/220638\/files\/diLenardo-Seguin-Kaplan-DH2016.pdf<\/a>.<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Dondero Maria Giulia (2016), \u201cUsing Images to Analyze Images. Semiotics meets Cultural Analytics\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">Proceedings of the Computer Art Congress 5&#160;: Archiving and Questioning Immateriality<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, in E.\u00a0Reyes-Garci\u0301a, P.\u00a0Cha\u0302tel-Innocenti &amp; K.\u00a0Zreik (dir), Paris, Europia Production, pp.\u00a091-107. <\/span><a href=\"https:\/\/orbi.uliege.be\/handle\/2268\/202967\">https:\/\/orbi.uliege.be\/handle\/2268\/202967<\/a>.<\/p>\n<p class=\"bibliographie\">Dondero Maria Giulia (2018), \u00ab&#160;La rem\u00e9diation d\u2019archives visuelles en vue de nouvelles iconographies&#160;: le cas de la Media Visualization de Lev Manovich&#160;\u00bb, <em>Interin<\/em>, 1\/23 (\u00ab&#160;Rem\u00e9diation, bricolage et innovation&#160;\u00bb), pp.\u00a085-107. <a href=\"https:\/\/seer.utp.br\/index.php\/i\/article\/view\/622\"><span lang=\"en\" xml:lang=\"en\">https:\/\/seer.utp.br\/index.php\/i\/article\/view\/622 (full text)<\/span><\/a><span lang=\"en\" xml:lang=\"en\">.<\/span><\/p>\n<div id=\"bibl_15\" class=\"formated_bibl_container\">\n<div class=\"open_bibl\"><\/div>\n<\/div>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Dondero Maria Giulia (2019), \u201cVisual semiotics and automatic analysis of images from the Cultural Analytics Lab&#160;: how can quantitative and qualitative analysis be combined&#160;?\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">Semiotica<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, in press.<\/span><br \/>\nDOI&#160;: <a class=\"doi\" href=\"http:\/\/dx.doi.org\/10.1515\/sem-2018-0104\">10.1515\/sem-2018-0104<\/a><\/p>\n<p class=\"bibliographie\">Dondero Maria Giulia (2020), <em>Les Langages de l\u2019image. De la peinture aux Big Visual Data<\/em>, Paris, Hermann&#160;; eng. trans. <em><span lang=\"en\" xml:lang=\"en\">The Language of Images&#160;: The Forms and the Forces<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Berlin-New-York, Springer, 2020.<\/span><\/p>\n<p class=\"bibliographie\">Dondero Maria Giulia, Beyaert-Geslin Anne &amp; Moutat Audrey (dirs. 2017), <em>Les Plis du visuel. R\u00e9flexivit\u00e9 et \u00e9nonciation dans l\u2019image<\/em>, Limoges, Lambert-Lucas.<\/p>\n<p class=\"bibliographie\">Dubuisson Daniel &amp; Raux Sophie (2012), \u00ab&#160;Entre l\u2019histoire de l\u2019art et les visual studies&#160;: mythe, science et id\u00e9ologie&#160;\u00bb, <em>Histoire de l\u2019art<\/em>, 70, pp.\u00a095-103.<br \/>\nDOI&#160;: <a class=\"doi\" href=\"http:\/\/dx.doi.org\/10.3406\/hista.2012.3393\">10.3406\/hista.2012.3393<\/a><\/p>\n<p class=\"bibliographie\">Dubuisson Daniel &amp; Raux Sophie (dir. 2015), <em>\u00c0 perte de vue. Les nouveaux paradigmes du visuel<\/em>, Paris, Les Presses du R\u00e9el.<\/p>\n<p class=\"bibliographie\">Focillon Henri (1934), \u00ab&#160;Vie des formes&#160;\u00bb, <em>Vie des formes<\/em> suivi de <em>\u00ab&#160;\u00c9loge de la main&#160;\u00bb<\/em>, Paris, Presses Universitaires de France, 1943&#160;; eng. trans. <em><span lang=\"en\" xml:lang=\"en\">The Life of Forms in Art<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, New York, Zone Books, 2002.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Ginzburg Carlo (1979), \u00ab&#160;Morelli, Freud, and Sherlock Holmes&#160;: Clues and Scientific Method&#160;\u00bb, in U.\u00a0Eco &amp; T.\u00a0Sebeok (eds. 1984), <\/span><em><span lang=\"en\" xml:lang=\"en\">The Sign of Three&#160;: Dupin, Holmes, Peirce<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Bloomington, Indiana University Press, pp.\u00a081\u2013118&#160;; tr.\u00a0fr. <\/span>\u00ab&#160;Signes, traces, pistes. Racines d\u2019un paradigme de l\u2019indice&#160;\u00bb, <em>Le De\u0301bat<\/em>, n<sup>o<\/sup>\u00a06, pp.\u00a03-44, 1980.<\/p>\n<p class=\"bibliographie\">Groupe \u00b5 (1992), <em>Trait\u00e9 du signe visuel<\/em>, Paris, Seuil.<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Kubler George (1962), The Shape of Time, New Haven-London, Yale University Press.<\/span><\/p>\n<div id=\"bibl_24\" class=\"formated_bibl_container\">\n<div class=\"open_bibl\"><\/div>\n<\/div>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Kuhn Virginia <\/span><em><span lang=\"en\" xml:lang=\"en\">et al.<\/span><\/em><span lang=\"en\" xml:lang=\"en\"> (2012), \u201cLarge Scale Video Analytics&#160;: On-demand, iterative inquiry for moving image research\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">eScience<\/span><\/em><span lang=\"en\" xml:lang=\"en\"> 2012, 8th IEEE International Conference on E-Science, Chicago, IL, 8-12 Oct 2012, pp.\u00a01-5. DOI&#160;: 10.1109\/eScience.2012.6404446.<\/span><br \/>\nDOI&#160;: <a class=\"doi\" href=\"http:\/\/dx.doi.org\/10.1109\/eScience.2012.6404446\">10.1109\/eScience.2012.6404446<\/a><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">LeCun Yann, Bengio Yoshua &amp; Hinton Geoffrey (2015), \u201cDeep learning\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">Nature<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, vol.\u00a0521, pp.\u00a0436\u2013444.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Manovich Lev, Douglass Jeremy &amp; Zepel Tara (2011), \u201cHow to Compare One Million Images&#160;?\u201d, in B.\u00a0David (dir.), <\/span><em><span lang=\"en\" xml:lang=\"en\">Understanding Digital Humanities<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, London, Palgrave Macmillan, pp.\u00a0249-278.<\/span><\/p>\n<p class=\"bibliographie\">Marin Louis (1994), <em>De la repr\u00e9sentation<\/em>, Paris, Seuil&#160;; eng. trans. <span lang=\"en\" xml:lang=\"en\">On Representation, Stanford, Stanford University Press, 2002.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Panofsky Erwin (1924), <\/span><em><span lang=\"en\" xml:lang=\"en\">Die Perspektive als \u201csymbolische Form\u201d<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, in Vortr\u00e4ge der Bibliothek Warburg 1924\/1925, Leipzig-Berlin, 1927&#160;; tr.\u00a0fr. <\/span><em>La Perspective comme forme symbolique<\/em>, Paris, \u00e9d. de Minuit, 1975&#160;; eng. trans. <em><span lang=\"en\" xml:lang=\"en\">Perspective as Symbolic Form<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, New York, Zone Books.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Raux Sophie (2018), \u201cVirtual Explorations of an 18th-Century Art Market Space&#160;: Gersaint, Watteau, and the Pont Notre-Dame\u201d, <\/span><em><span lang=\"en\" xml:lang=\"en\">Journal18<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Issue 5, \u201cCoordinates\u201d, Spring 2018. <\/span><a href=\"http:\/\/www.journal18.org\/issue5\/virtual-explorations-of-an-18th-century-art-market-space-gersaint-watteau-and-the-pont-notre-dame\/\">http:\/\/www.journal18.org\/issue5\/virtual-explorations-of-an-18th-century-art-market-space-gersaint-watteau-and-the-pont-notre-dame\/<\/a>.<\/p>\n<p class=\"bibliographie\">Rastier Fran\u00e7ois (2011), <em>La Mesure et le Grain<\/em>, Paris, Champion.<\/p>\n<p class=\"bibliographie\">Rieber Audrey (2008), \u00ab&#160;Le concept de forme symbolique dans l\u2019iconologie d\u2019E.\u00a0Panofsky. Reprise et d\u00e9placement d\u2019un concept cassir\u00e9rien&#160;\u00bb, <em>Appareil<\/em>, <a href=\"https:\/\/journals.openedition.org\/appareil\/436\">https:\/\/journals.openedition.org\/appareil\/436<\/a>.<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Riegl Alois (1899), <\/span><em><span lang=\"en\" xml:lang=\"en\">Historische Grammatick der bildenden K\u00fcnste<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Milan, Mimesis Verlag, 2017&#160;; tr.\u00a0fr. <\/span><em><span lang=\"en\" xml:lang=\"en\">Grammaire historique des arts plastiques<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Vanves, Hazan, 2015&#160;; eng. trans. <\/span><em><span lang=\"en\" xml:lang=\"en\">Historical grammar of the visual arts<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, New York, Zone Books, 2004.<\/span><\/p>\n<p class=\"bibliographie\">Tore Gian Maria (2018), \u00ab&#160;Limitations et illimitations d\u2019une s\u00e9miotique de l\u2019image&#160;: Figurativit\u00e9, r\u00e9flexivit\u00e9, multiplicit\u00e9&#160;\u00bb, <em>La Part de l\u2019\u0153il<\/em>, n<sup>o<\/sup>\u00a032, pp.\u00a0296-307.<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Warburg, Aby (1901), \u00ab&#160;Symbolismus als Umfangsbestimmung&#160;\u00bb, dans A.\u00a0Warburg, <\/span><em><span lang=\"en\" xml:lang=\"en\">Werke in einem Band, Berlin, Suhrkamp<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, 2010, pp.\u00a0615-28.<\/span><\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">Warburg, Aby (1924-1929), <\/span><em><span lang=\"en\" xml:lang=\"en\">Der Bilderatlas Mnemosyne<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, Berlin, Akademie Verlag, 2000&#160;; tr.\u00a0fr. <\/span><em>L\u2019Atlas mn\u00e9mosyne<\/em>, Paris, \u00c9ditions Atelier de l\u2019\u00e9carquill\u00e9, 2012&#160;; eng. trans. <em>Der Bilderatlas Mnemosyne \u2013 The Original<\/em>, Berlin, Hatje Cantz Verlag, 2020.<\/p>\n<p class=\"bibliographie\"><span lang=\"en\" xml:lang=\"en\">W\u00f6lfflin, Heinrich (1915), <\/span><em><span lang=\"en\" xml:lang=\"en\">Kunstgeschichtliche Grundbegriffe&#160;: Das Problem der Stilentwicklung in der neueren Kunst<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, M\u00fcnchen, Bruckmann&#160;; tr.\u00a0fr. <\/span><em>Principes fondamentaux de l\u2019histoire de l\u2019art<\/em>, Marseille, Parenth\u00e8ses \u00c9ditions, 2017&#160;; eng. trans. <em><span lang=\"en\" xml:lang=\"en\">Principles of Art History. The Problem of the Development of Style in Later Art<\/span><\/em><span lang=\"en\" xml:lang=\"en\">, New York, Dover Publications, 1932.<\/span><\/p>\n<\/div>\n<h2 class=\"section\"><span class=\"text\">Notes<\/span><\/h2>\n<p class=\"notesbaspage\"><a id=\"ftn1\" class=\"FootnoteSymbol\" href=\"https:\/\/journals.openedition.org\/signata\/3422#bodyftn1\">1<\/a> La formulation n\u2019est pas redondante car diachronie et g\u00e9n\u00e9alogie n\u2019op\u00e8rent pas sur le m\u00eame plan&#160;: d\u2019une part, il s\u2019agit d\u2019un regard \u00e9pist\u00e9mologique qui compare des \u00e9tats synchroniques, d\u2019autre part, d\u2019une reconstruction arch\u00e9ologique des continuit\u00e9s et des bifurcations des pratiques \u00e0 l\u2019int\u00e9rieur d\u2019un champ de possibilit\u00e9s (Basso Fossali 2013).<\/p>\n<p class=\"notesbaspage\"><a id=\"ftn2\" class=\"FootnoteSymbol\" href=\"https:\/\/journals.openedition.org\/signata\/3422#bodyftn2\">2<\/a> Voir \u00e0 ce propos les lettres \u00e9chang\u00e9es entre Warburg et Cassirer concernant la notion de forme symbolique, d\u00e9j\u00e0 utilis\u00e9e par le premier de mani\u00e8re autonome (Warburg 1901).<\/p>\n<\/div><\/div>\n<div class=\"zn-singledetail-attachedfiles\">\n<h3 class=\"zn-singledetail-section-title\">Fichier(s) attach\u00e9(s)<\/h3>\n<ul class=\"zn-singledetail-attachedfiles-list\">\n<li class=\"zn-singledetail-attachedfiles-item\">\n\t\t\t\t\t\t\t<a class=\"zn-singledetail-attachedfiles-link button outline for-download\" href=\"https:\/\/www.sfsic.org\/wp-inside\/uploads\/skp-membership\/demande_adh\/aaa_-pour-une-nouvelle-hermeneutique-des-formes-symboliques_signata-14-fr-angl-def_2021.pdf\" title=\"T\u00e9l\u00e9charger : \u00ab aaa_-pour-une-nouvelle-hermeneutique-des-formes-symboliques_signata-14-fr-angl-def_2021.pdf \u00bb\" target=\"_blank\" rel=\"noopener\"><br \/>\n\t\t\t\t\t\t\t\t<span class=\"button-txt\">AAA_ Pour une nouvelle herm\u00e9neutique des formes symboliques_Signata 14 FR ANGL DEF_2021<span class=\"button-txt-type\"> (pdf)<\/span><\/span><br \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-humanites-numeriques\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/digital-humanities\/\" title=\"Humanit\u00e9s num\u00e9riques\"><span class=\"termslist-itemname\">Humanit\u00e9s num\u00e9riques<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-semiotique\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/semiotics\/\" title=\"S\u00e9miotique\"><span class=\"termslist-itemname\">S\u00e9miotique<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 29 novembre 2021 Th\u00e9matiques M\u00e9diations m\u00e9morielles, culturelles et patrimoniales Num\u00e9rique : strat\u00e9gies, dispositifs et usages R\u00e9ponse attendue pour le 15\/05\/2022 Type de r\u00e9ponse Contribution compl\u00e8te Type [&hellip;]<\/p>\n","protected":false},"author":781,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[99,77],"thematique":[38,39],"sfsic":[],"class_list":["post-20495","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-humanites-numeriques","tag-semiotique","thematique-mediations-memorielles-culturelles-et-patrimoniales","thematique-numerique-strategies-dispositifs-et-usages","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pour une nouvelle herm\u00e9neutique des formes symboliques.<\/title>\n<meta name=\"description\" content=\"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique &quot;Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour une nouvelle herm\u00e9neutique des formes symboliques.\" \/>\n<meta property=\"og:description\" content=\"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique &quot;Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-30T13:46:13+00:00\" \/>\n<meta name=\"author\" content=\"Axelle Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/\"},\"author\":{\"name\":\"Axelle Martin\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\"},\"headline\":\"Pour une nouvelle herm\u00e9neutique des formes symboliques.\",\"datePublished\":\"2021-11-30T13:46:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/\"},\"wordCount\":2866,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Humanit\u00e9s num\u00e9riques\",\"S\u00e9miotique\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/\",\"name\":\"Pour une nouvelle herm\u00e9neutique des formes symboliques.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2021-11-30T13:46:13+00:00\",\"description\":\"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique \\\"Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pour une nouvelle herm\u00e9neutique des formes symboliques.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\",\"name\":\"Axelle Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"caption\":\"Axelle Martin\"},\"sameAs\":[\"@antropocominside\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour une nouvelle herm\u00e9neutique des formes symboliques.","description":"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique \"Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/","og_locale":"en_US","og_type":"article","og_title":"Pour une nouvelle herm\u00e9neutique des formes symboliques.","og_description":"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique \"Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.\"","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/","og_site_name":"SFSIC","article_published_time":"2021-11-30T13:46:13+00:00","author":"Axelle Martin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/"},"author":{"name":"Axelle Martin","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b"},"headline":"Pour une nouvelle herm\u00e9neutique des formes symboliques.","datePublished":"2021-11-30T13:46:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/"},"wordCount":2866,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Humanit\u00e9s num\u00e9riques","S\u00e9miotique"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/","name":"Pour une nouvelle herm\u00e9neutique des formes symboliques.","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2021-11-30T13:46:13+00:00","description":"La revue Signata. Annales des s\u00e9miotiques lance un appel \u00e0 contribution pour son num\u00e9ro 14 coordonn\u00e9 par Pierluigi Basso, Ralph Dekoninck, Sophie Raux et Maria Giulia Dondero. Ce num\u00e9ro traite de la th\u00e9matique \"Pour une nouvelle herm\u00e9neutique des formes symboliques. S\u00e9miotique, histoire de l\u2019art et humanit\u00e9s num\u00e9riques.\"","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/pour-une-nouvelle-hermeneutique-des-formes-symboliques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"Pour une nouvelle herm\u00e9neutique des formes symboliques."}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b","name":"Axelle Martin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","caption":"Axelle Martin"},"sameAs":["@antropocominside"]}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/20495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/781"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=20495"}],"version-history":[{"count":5,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/20495\/revisions"}],"predecessor-version":[{"id":20543,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/20495\/revisions\/20543"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=20495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=20495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=20495"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=20495"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=20495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}