{"id":19906,"date":"2021-10-21T09:40:41","date_gmt":"2021-10-21T07:40:41","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=19906"},"modified":"2021-10-20T21:41:37","modified_gmt":"2021-10-20T19:41:37","slug":"la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/","title":{"rendered":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> 20 octobre 2021\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-medias-et-journalisme\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/thematiques\/media-and-journalism\/\" title=\"M\u00e9dias et journalisme\"><span class=\"termslist-itemname\">M\u00e9dias et journalisme<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-mediations-memorielles-culturelles-et-patrimoniales\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/thematiques\/memorial-cultural-and-heritage-mediation\/\" title=\"M\u00e9diations m\u00e9morielles, culturelles et patrimoniales\"><span class=\"termslist-itemname\">M\u00e9diations m\u00e9morielles, culturelles et patrimoniales<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>20\/12\/2021<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>R\u00e9sum\u00e9<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type d\u2019\u00e9v\u00e9nement<\/span><span class=\"doubledot\"><\/span> <strong>Colloque<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-coordinators\">\n<h3 class=\"zn-singledetail-section-title\">Coordinateurs<\/h3>\n<ul class=\"zn-singledetail-coordinators-list\">\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Lucie <\/span> <span>Alexis<\/span>, <span>Ma\u00eetresse de conf\u00e9rences, Universit\u00e9 Grenoble Alpes, Institut de la Communication et des M\u00e9dias, GRESEC, chercheuse associ\u00e9e au CARISM et \u00e0 l\u2019Institut national de l\u2019audiovisuel<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Flore <\/span> <span>Di Sciullo<\/span>, <span>Docteure en Sciences de l\u2019information et de la communication, ATER, Universit\u00e9 Paris 2 Panth\u00e9on-Assas, Institut Fran\u00e7ais de Presse, chercheuse associ\u00e9e au CARISM<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-eventinfo\">\n<div class=\"zn-singledetail-eventinfo-inner\">\n<div class=\"zn-singledetail-eventdates\">\n\t\t\t\t\t\t<span class=\"zn-singledetail-label\">Dates de l\u2019\u00e9v\u00e9nement<span class=\"doubledot\"><\/span><\/span><\/p>\n<ul class=\"zn-singledetail-eventdates-list\">\n<li class=\"zn-singledetail-eventdates-item\">\n\t\t\t\t\t\t\t\tDu 09\/05\/2022 au 10\/05\/2022\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<p class=\"zn-singledetail-eventplace\">\n\t\t\t\t\t\t<span class=\"zn-singledetail-label\">Lieu de l\u2019\u00e9v\u00e9nement<span class=\"doubledot\"><\/span><\/span><br \/>\n\t\t\t\t\t\t<span class=\"zn-singledetail-eventplace-adr\"><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"adr-place\">Universit\u00e9 Paris II Panth\u00e9on-Assas<\/span>,<\/p>\n<p>\t\t\t\t\t\t<span class=\"adr-street\">391, rue de Vaugirard <\/span>, <span class=\"adr-city\">Paris<\/span>\t\t\t\t\t\t<span class=\"adr-cp\">75015<\/span>, <span class=\"adr-country\">France<\/span><br \/>\n\t\t\t\t\t\t<\/span>\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"zn-singledetail-annonce wig-content\">\n<p>La presse culturelle actuelle recouvre des formats extr\u00eamement divers&#160;: elle peut \u00eatre une revue de critique d\u2019art comme <em>May <\/em>ou d\u2019histoire de l\u2019art comme <em>La revue de l\u2019art<\/em>, une revue g\u00e9n\u00e9raliste comme <em>Connaissance des arts <\/em>ou plus pointue comme <em>Frog<\/em>, un guide culturel comme <em>T\u00e9l\u00e9rama <\/em>ou un magazine qui traite de l\u2019actualit\u00e9 par le prisme de l\u2019art comme <em>Mouvement <\/em>ou encore une revue consacr\u00e9e \u00e0 un art en particulier comme <em>Les Cahiers du cin\u00e9ma<\/em>. Tout ceci sans compter l\u2019incroyable vari\u00e9t\u00e9 de la presse culturelle en ligne, rassemblant des blogs amateurs, des <em>podcasts <\/em>mais aussi des revues num\u00e9riques, si l\u2019on pense par exemple \u00e0 <em>Point contemporain<\/em><sup>1<\/sup> o\u00f9 la version en ligne prime sur la version imprim\u00e9e, ou \u00e0 l\u2019invention de formats 100&#160;% num\u00e9rique sur le mod\u00e8le <em>pure player <\/em>comme anciennement <em>Fluctuat <\/em>ou aujourd\u2019hui <em>ParisArt <\/em>ou <em>ArtViewer.<\/em><\/p>\n<p>Ce colloque international a pour ambition d\u2019embrasser cette diversit\u00e9 et entend mettre en \u00e9vidence la mani\u00e8re dont les m\u00e9dias \u2013 traditionnels et en ligne \u2013 portent un regard sur les arts plastiques, les arts vivants, l\u2019architecture, le design graphique, le cin\u00e9ma, la litt\u00e9rature, la musique ou encore le patrimoine. De fa\u00e7on plus large, les communications pourront \u00e9galement porter sur les produits des industries culturelles (jeux vid\u00e9os, audiovisuel).<\/p>\n<p>Par ailleurs, le p\u00e9riodique artistique dont les tirages sont souvent faibles et le lectorat <em>a priori <\/em>r\u00e9duit m\u00e9rite d\u2019\u00eatre analys\u00e9 avec les outils info-communicationnels, il a beaucoup \u00e0 nous apprendre sur les repr\u00e9sentations collectives et les mani\u00e8res de d\u00e9battre en soci\u00e9t\u00e9 autour de l\u2019art contemporain et de l\u2019actualit\u00e9 culturelle.<\/p>\n<p>Aucune limite restrictive n\u2019est pos\u00e9e quant au champ artistique trait\u00e9. Les interventions pourront s\u2019appuyer sur un ou plusieurs des axes suivants&#160;; ceux-ci sont propos\u00e9s \u00e0 titre indicatif et ne prescrivent nullement le contenu des propositions. Nous souhaitons privil\u00e9gier une approche interdisciplinaire. Si le point de d\u00e9part est une approche communicationnelle, nous encourageons \u00e9galement les propositions venues de l\u2019histoire de l\u2019art, des arts plastiques, des \u00e9tudes litt\u00e9raires\u2026 Ce colloque entend favoriser les \u00e9changes entre chercheur.se.s et acteurs.trices culturel.le.s et m\u00e9diatiques et permettre les discussions au croisement de positionnements pratiques et th\u00e9oriques.<\/p>\n<h2>Axe 1 \u2013 Mod\u00e8les historiques et influences<\/h2>\n<p>Ce premier axe de recherche vise \u00e0 interroger la vari\u00e9t\u00e9 des formes \u00e9ditoriales que peut aujourd\u2019hui adopter la \u00ab&#160;revue d\u2019art&#160;\u00bb, le \u00ab&#160;magazine culturel&#160;\u00bb ou encore le \u00ab&#160;magazine d\u2019actualit\u00e9 culturelle&#160;\u00bb. Si une tr\u00e8s riche bibliographie est consacr\u00e9e aux p\u00e9riodiques artistiques et culturels du XIX<sup>e<\/sup> et de la premi\u00e8re moiti\u00e9 du XX<sup>e<\/sup> si\u00e8cles<sup>2<\/sup>, la p\u00e9riode la plus contemporaine est souvent exclue de ces \u00e9tudes qui privil\u00e9gient une approche chronologique et diachronique. Le p\u00e9riodique s\u2019attachant au monde artistique contemporain est ainsi un territoire \u00e0 explorer. Ce premier axe entend encourager des r\u00e9flexions sur la filiation de ce riche h\u00e9ritage \u00e9ditorial en insistant sur la p\u00e9riode contemporaine.<\/p>\n<p>Il convient alors de partir d\u2019exemples de revues en cours de publication pour se demander de quels mod\u00e8les ils d\u00e9coulent, de quelles filiations ils sont le fruit. Il s\u2019agit notamment d\u2019interroger l\u2019\u00e9ventuelle stabilit\u00e9 de formats qui perdurent, \u00e0 l\u2019instar d\u2019<em>art press <\/em>(fond\u00e9e en 1972) ou de <em>Cahiers d\u2019art<\/em>, r\u00e9cemment relanc\u00e9 apr\u00e8s une longue p\u00e9riode d\u2019inactivit\u00e9.<\/p>\n<p>Les communications pourront ici s\u2019inscrire dans une perspective monographique ou non, historique, et interroger la revue d\u2019art sur le temps long, consid\u00e9rant les titres m\u00e9morables qui ont pu \u00eatre d\u00e9terminants pour les revues les plus r\u00e9centes. Les \u00e9tudes engageant une perspective transnationale ou trans-m\u00e9diumnique sont \u00e9galement les bienvenues.<\/p>\n<p>&nbsp;<\/p>\n<h2>Axe 2 \u2013 Diversification des formes \u00e9ditoriales en ligne<\/h2>\n<p>Nous cherchons ici \u00e0 questionner les mani\u00e8res dont la revue d\u2019art parvient \u00e0 se d\u00e9placer du territoire du papier vers celui du num\u00e9rique. La revue culturelle se prolonge aujourd\u2019hui par les blogs, les webzines, les comptes sur les r\u00e9seaux sociaux, les plateformes collaboratives, les formats audiovisuels type <em>podcast <\/em>ou interview film\u00e9e. Elle s\u2019\u00e9loigne en effet de plus en plus du mod\u00e8le papier traditionnel pour \u00eatre d\u00e9ploy\u00e9e sous de nouvelles formes, \u00e0 commencer par l\u2019exploration d\u2019une compl\u00e9mentarit\u00e9 papier\/num\u00e9rique. \u00c9voquons par exemple le blog de l\u2019association \u00ab&#160;Jeunes Critiques d\u2019art&#160;\u00bb, les podcasts comme \u00ab&#160;Le bruit de l\u2019art&#160;\u00bb et les webzines comme l\u2019italien <em>Cur<\/em>a ou l\u2019am\u00e9ricain <em>Triple Canopy <\/em>ou encore les m\u00e9dias amateurs tels que <em>Sens critique <\/em>pour le cin\u00e9ma<em>. <\/em>Nous pensons enfin aux formats hybrides propos\u00e9s par les <em>podcasts<\/em>, par certains r\u00e9seaux sociaux et par les plateformes num\u00e9riques&#160;: les cha\u00eenes Twitch comme \u00ab&#160;The Blank Contemporary&#160;\u00bb, les comptes<\/p>\n<p>Instagram comme \u00ab&#160;J\u2019aime tout chez toi<sup>3<\/sup>&#160;\u00bb ou encore les cha\u00eenes YouTube de critiques culturelles comme \u00ab&#160;Le fossoyeur de films&#160;\u00bb ou \u00ab&#160;Bulldop&#160;\u00bb pour les livres.<\/p>\n<p>Dans quelle mesure les dispositifs num\u00e9riques sont-ils le fruit d\u2019exp\u00e9rimentations \u00e9ditoriales&#160;? Les communications pourront ici porter aussi bien sur des \u00e9tudes de cas que sur l\u2019analyse de dispositifs socio-techniques qui font exister l\u2019actualit\u00e9 culturelle et qui permettent d\u2019en diversifier les usages. Les interventions pourront \u00e9galement porter sur la reconfiguration des pratiques journalistiques de la critique culturelle et l\u2019adaptabilit\u00e9 des revues au num\u00e9rique, de leur ligne \u00e9ditoriale et des formes adopt\u00e9es.<\/p>\n<h2>Axe 3 \u2013 Normes \u00e9ditoriales et discursives&#160;: entre sp\u00e9cificit\u00e9 et adaptation<\/h2>\n<p>La sp\u00e9cificit\u00e9 des termes \u00ab&#160;revue&#160;\u00bb ou \u00ab&#160;magazine&#160;\u00bb, d\u00e8s lors qu\u2019on les envisage au prisme de la presse culturelle, restent \u00e0 pr\u00e9ciser, et ce dans un contexte o\u00f9 l\u2019obsolescence de la critique d\u2019art est de plus en plus souvent point\u00e9e. Pourtant, ce type de presse est d\u2019une remarquable vitalit\u00e9, et ce que l\u2019on adopte une focale fran\u00e7aise ou internationale. Alors m\u00eame que les mondes de l\u2019art font face \u00e0 d\u2019importantes restructurations (sp\u00e9culation financi\u00e8re, mondialisation, plus r\u00e9cemment crise sanitaire), les formats les plus consacr\u00e9s \u2013 \u00e0 commencer par le compte rendu d\u2019exposition, de spectacle ou l\u2019entretien avec un artiste \u2013 r\u00e9sistent et s\u2019adaptent \u00e0 ce contexte mouvant. Comment la presse artistique se positionne-t-elle vis-\u00e0-vis d\u2019autres genres journalistiques, et d\u2019autres types de discours sur l\u2019art (institutionnels, scientifiques)&#160;? Quels sont les genres de discours inh\u00e9rents \u00e0 la presse culturelle&#160;?<\/p>\n<p>Les communications pourront explorer les normes \u00e9ditoriales les plus couramment adopt\u00e9es par les revues d\u2019art, qu\u2019elles soient imprim\u00e9es ou en ligne, ainsi que leur \u00e9volution afin de questionner les valeurs qui les sous-tendent. Graphisme, mise en page, rubriquage, ligne \u00e9ditoriale\u2026 Quelles sont les formes \u00e9ditoriales les plus caract\u00e9ristiques de la revue d\u2019art&#160;? De quelles mani\u00e8res \u00e9voluent-elles face \u00e0 l\u2019adaptation des titres au format num\u00e9rique d\u2019une part, et \u00e0 des imp\u00e9ratifs \u00e9conomiques et sociaux d\u2019autre part&#160;? De quelles mani\u00e8res ces normes s\u2019adaptent- elles \u00e0 la diversification des supports&#160;?<\/p>\n<h2>Axe 4 \u2013 La presse culturelle pens\u00e9e dans un \u00ab&#160;champ \u00e9largi<sup>4<\/sup>&#160;\u00bb<\/h2>\n<p>La presse culturelle semble tiraill\u00e9e entre d\u2019une part, une d\u00e9mocratisation de ses contenus et une hybridation de ses formes (avec notamment le magazine d\u2019informations, le magazine de mode, le bulletin d\u2019actualit\u00e9&#8230;) et d\u2019autre part, une parcellisation croissante, comme en t\u00e9moigne la multiplication de p\u00e9riodiques de plus en plus sp\u00e9cialis\u00e9s, consacr\u00e9s \u00e0 des domaines sp\u00e9cifiques comme par exemple le dessin contemporain (<em>Roven<\/em>), les pratiques amateures (<em>Profane<\/em>) ou la jeunesse des artistes (<em>L\u2019incroyable<\/em>).<\/p>\n<p>Des contraintes de plus en plus fortes p\u00e8sent sur l\u2019exercice de la critique culturelle, et par cons\u00e9quent, sur la production \u00e9ditoriale des revues. Actualit\u00e9 de plus en plus foisonnante, internationalisation des trajectoires artistiques, pression financi\u00e8re, manque de moyens des institutions publiques, partenariat des institutions culturelles avec les titres de presse&#160;: autant d\u2019\u00e9l\u00e9ments qui viennent complexifier la t\u00e2che des critiques d\u2019art, confront\u00e9s \u00e0 d\u2019importants probl\u00e8mes de r\u00e9mun\u00e9ration et d\u2019ind\u00e9pendance.<\/p>\n<p>La critique, dans son ensemble, est menac\u00e9e par l\u2019\u00e9cueil de la \u00ab&#160;promotion culturelle<sup>5<\/sup>&#160;\u00bb&#160;: lorsque les annonceurs (galeries, fondations, etc.) financent une publication par l\u2019achat d\u2019un espace publicitaire, le\/la critique comme la revue dans laquelle il\/elle publie peut ressentir une contrainte \u00e0 valoriser l\u2019annonceur en question.<\/p>\n<p>En outre, avec des revue port\u00e9es par des institutions comme <em>Palais <\/em>(\u00e9dit\u00e9e par le Palais de Tokyo) ou <em>Les<\/em><em> Cahiers du MNAM <\/em>(\u00e9dit\u00e9e par le Centre Georges Pompidou)<em>,<\/em> la revue d\u2019art appara\u00eet comme essentielle pour mettre au jour les m\u00e9canismes qui structurent le r\u00e9seau artistique et les valeurs qui d\u00e9terminent son organisation.<\/p>\n<p>Pourtant, en d\u00e9pit de ces diff\u00e9rents \u00e9cueils, le secteur de la presse culturelle est dynamique et diversifi\u00e9, constitue un p\u00f4le attractif pour les journalistes et suscite souvent des aspirations professionnelles. La vitalit\u00e9 des revues gratuites, comme <em>Z\u00e9rodeux <\/em>ou <em>Le Ch\u00e2ssis<\/em>, en t\u00e9moignent d\u2019une fa\u00e7on exemplaire.<\/p>\n<p>Les communications pourront ici porter sur les mod\u00e8les \u00e9conomiques de la presse artistique et les strat\u00e9gies d\u00e9ploy\u00e9es pour assurer leur p\u00e9rennit\u00e9, ainsi que les diff\u00e9rents facteurs permettant \u00e0 la presse culturelle de lutter contre la concurrence, celle de la presse g\u00e9n\u00e9raliste en particulier. Les propositions pourront \u00e9galement s\u2019int\u00e9resser aux relations de collaboration, de comp\u00e9tition, voire de coop\u00e9tition<sup>6<\/sup> des revues d\u2019art les unes avec les autres, ainsi qu\u2019\u00e0 leur \u00e9toilement autour d\u2019autres acteurs des mondes de l\u2019art comme les mus\u00e9es, les fondations ou les galeries, ou des acteurs m\u00e9diatiques (t\u00e9l\u00e9visuels, radiophoniques\u2026), ainsi que des protagonistes des industries cr\u00e9atives.<\/p>\n<p>Enfin, la r\u00e9cente crise sanitaire invite \u00e0 interroger la mani\u00e8re dont les critiques du secteur culturel ont adapt\u00e9 leur activit\u00e9 face \u00e0 la reconfiguration de la vie culturelle durant les confinements.<\/p>\n<h2>Modalit\u00e9s de soumission<\/h2>\n<p>Nous vous remercions de pr\u00e9senter votre proposition de communication de la mani\u00e8re suivante&#160;:<\/p>\n<ul>\n<li>Sur la 1<sup>\u00e8re<\/sup> page, indiquez le titre de votre communication, une courte note bio- bibliographique (500 signes maximum, en pr\u00e9cisant votre nom, pr\u00e9nom et appartenance institutionnelle) et votre adresse de courrier \u00e9lectronique.<\/li>\n<li>Les pages suivantes veilleront \u00e0 \u00eatre anonymis\u00e9es et comporteront&#160;: le titre de la communication, la proposition de communication de 2 000 signes maximum espaces compris, bibliographie indicative non<\/li>\n<\/ul>\n<p>Votre proposition est \u00e0 envoyer en format .doc ou .odt \u00e0&#160;: <a href=\"mailto:presseculturelle2022@gmail.com\">presseculturelle2022@gmail.com<\/a><\/p>\n<p>Les propositions feront l\u2019objet d\u2019une \u00e9valuation en double aveugle par les membres du comit\u00e9 scientifique du colloque.<br \/>\nLa date limite de soumission des propositions est fix\u00e9e au <strong>20 d\u00e9cembre 2021.<\/strong><\/p>\n<p>Le colloque donnera lieu \u00e0 un projet \u00e9ditorial s\u2019appuyant sur une s\u00e9lection de communications.<\/p>\n<h2>Bibliographie indicative<\/h2>\n<p>ALLEN Gwen (dir.), <em>The Magazine<\/em>, London, MIT Press \u00ab&#160;Documents for Contemporary Art&#160;\u00bb,2016<\/p>\n<p>BAUDOIN Jean et HOURMANT Fran\u00e7ois (dir.), <em>Les Revues et la dynamique des ruptures<\/em>, Rennes, Presses universitaires de Rennes, 2007<\/p>\n<p>BOIVENT Marie, <em>La Revue d\u2019artiste, enjeu et sp\u00e9cificit\u00e9 d\u2019une pratique artistique<\/em>, Rennes, Incertain sens, 2015<\/p>\n<p>BONACORSI Julia et CROISSANT Val\u00e9rie, \u00ab&#160;\u00ab&#160;Votre m\u00e9moire culturelle&#160;\u00bb&#160;: entre logistique num\u00e9rique de la recommandation et m\u00e9diation patrimoniale. Le cas de <em>Sens Critique <\/em>&#160;\u00bb, <em>\u00c9tudes de communication<\/em>, 2015\/2, n\u00b0 45, p. 129-148<\/p>\n<p>BOURE Robert, \u00ab&#160;Sociologie des revues de sciences sociales et humaines&#160;\u00bb, <em>R\u00e9seaux, <\/em>n\u00b0 58, 1993, p. 91-105<\/p>\n<p>BOURGATTE Micha\u00ebl, \u00ab&#160;Pour une analyse informatis\u00e9e de la critique de cin\u00e9ma. Ce que dit la critique de la structure du champ cin\u00e9matographique&#160;\u00bb, <em>Questions de communication<\/em>, 2017\/1, n\u00b0 31, p. 315-333<\/p>\n<p>CH\u00c8VREFILS-DESBIOLLES Yves et FROISSART-PEZONE Rossella (dir.), <em>Les revues d\u2019art<\/em>, Rennes, Presses universitaires de Rennes, 2011<\/p>\n<p>COLOMINA Beatriz, <em>Clip, Stamp, Fold&#160;: The Radical Architecture of Little Magazines, 196X to 197X<\/em>, Barcelone, Actar, 2010<\/p>\n<p>CORPET Olivier, FRANCK Thomas et GLORIE Caroline, \u00ab&#160;La revue comme discours d\u2019intervention&#160;\u00bb, <em>Cahiers du GRM<\/em>, 12\/2017 [En ligne], \u00a0<a href=\"https:\/\/journals.openedition.org\/grm\/1055\">URL&#160;:<\/a> <a href=\"https:\/\/journals.openedition.org\/grm\/1055\">https:\/\/journals.openedition.org\/grm\/1055<\/a><\/p>\n<p>CROISSANT Val\u00e9rie (dir.), <em>L\u2019avis des autres. Prescription et recommandation culturelle \u00e0 l\u2019\u00e8re num\u00e9riqu<\/em>e, \u00c9ditions des archives contemporaines, 2019<\/p>\n<p>CROISSANT Val\u00e9rie et SPANO William, <em>Le journalisme en miroir dans la presse culturelle lyonnaise au XIX<sup>e<\/sup> si\u00e8cle<\/em>, <em>Le Temps des m\u00e9dias. Revue d\u2019histoire<\/em>, vol 23, n\u00b0 2, 2014, p. 165\u2011181<\/p>\n<p>DA COSTA KAUFMANN Thomas, DOSSIN Catherine et JOYEUX-PRUNEL B\u00e9atrice (dir.), <em>Circulations in the Global History of a Art<\/em>, Londres, Routledge, 2015<\/p>\n<p>HEIN Fabien, \u00ab&#160;Le critique rock, le fanzine et le magazine&#160;; \u00e7a s\u2019en va et \u00e7a revient&#160;\u00bb, <em>Volume<\/em>, n\u00b05 , 2006, p. 83-106<\/p>\n<p>JOYEUX-PRUNEL B\u00e9atrice, <em>Les avant-gardes artistiques. Une histoire transnationale. Volume 1 (1848- 1918)&#160;; Volume 2 (1918-1945)<\/em>, Paris, Gallimard, 2016 et 2017<\/p>\n<p>LEENAERTS Danielle, <em>Petite<\/em> <em>histoire<\/em> <em>du<\/em> <em>magazine<\/em> <em>VU<\/em> <em>(1928-1940).<\/em> <em>Entre<\/em> <em>photographie<\/em> <em>d\u2019information<\/em> <em>et<\/em> <em>photographie<\/em><em> d\u2019art<\/em>, Bruxelles, PIE Peter Lang, 2010<\/p>\n<p>NEWMAN Amy, <em>Challenging Art&#160;: Artforum 1962-1974<\/em>, New York, Soho Press, 2000<\/p>\n<p>REGIMBEAU G\u00e9rard, \u00ab&#160;Les index des revues d\u2019art contemporain&#160;: outils documentaires et documents&#160;\u00bb. Actes du s\u00e9minaire annuel \u00ab&#160;Les revues de sciences humaines et sociales&#160;: \u00e9volutions et figures&#160;\u00bb, 1996, p. 37-50, [En ligne], URL&#160;: <a href=\"https:\/\/halshs.archives-ouvertes.fr\/hal-00605217v2\">https:\/\/halshs.archives-ouvertes.fr\/hal-00605217v2<\/a><\/p>\n<p>STEAD Evanghelia et V\u00c9DRINE H\u00e9l\u00e8ne (dirs.), <em>L\u2019Europe des revues (1880-1920). Estampes, photographies, illustrations<\/em>, Paris, Presses Universitaires Paris Sorbonne, 2008<\/p>\n<p>STEAD Evanghelia, <em>Sisyphe heureux. Les revues artistiques et litt\u00e9raires&#160;: approches et figures, <\/em>Rennes,Presses Universitaires de Rennes, 2020<\/p>\n<p>TRIGGS Teal, <em>Fanzines<\/em>, Londres, Thames &amp; Hudson, 2010<\/p>\n<p>WEBB Sheila, \u00ab&#160;Magazines and the visual arts&#160;: the ideal showcase&#160;\u00bb, in ABRAHAMSON David et PRIOR-MILLER Maria R., <em>The Routledge Handbook of Magazine ResearchThe Future of the Magazine Form<\/em>, New York, Routledge, 2015, p. 347-361<\/p>\n<h2>Notes<\/h2>\n<p>[1] Outre son site, la revue tire aussi une version \u00e9dit\u00e9e, mais \u00e0 un tirage limit\u00e9 \u00e0 500 exemplaires.<\/p>\n<p>[2] Mentionnons les s\u00e9minaires \u00ab&#160;<a href=\"http:\/\/msh-paris-saclay.fr\/event\/seminaire-pelias-periodiques-litterature-arts-sciences-les-periodiques-comme-mediateurs-culturels\/\">P\u00e9lias&#160;: Les p\u00e9riodiques comme m\u00e9diateurs culturels (Litt\u00e9rature, arts, sciences<\/a><u>) <\/u>&#160;\u00bb, organis\u00e9 par Alexia Kalantzis, Norbert Verdier et H\u00e9l\u00e8ne V\u00e9drine, et \u00ab&#160;<a href=\"https:\/\/www.uvsq.fr\/quinzieme-seminaire-du-tigre-texte-image-groupe-de-recherche-a-lecole-2020-2021\">TIGRE (Texte-Image, groupe de recherche \u00e0<\/a> <a href=\"https:\/\/www.uvsq.fr\/quinzieme-seminaire-du-tigre-texte-image-groupe-de-recherche-a-lecole-2020-2021\">l\u2019\u00c9cole) <\/a>&#160;\u00bb, anim\u00e9 par Evanghelia Stead, les projets num\u00e9riques en ligne comme le \u00ab&#160;<a href=\"https:\/\/modjourn.org\/\">Modernist Journals Project <\/a>&#160;\u00bb, et les soci\u00e9t\u00e9s savantes comme \u00ab&#160;<a href=\"https:\/\/rs4vp.org\/\">Research Society for Victorian Periodicals <\/a>&#160;\u00bb ou \u00ab&#160;<a href=\"https:\/\/www.espr-it.eu\/\">ESPRit \u2013 European Society for Periodical<\/a> <a href=\"https:\/\/www.espr-it.eu\/\">Research <\/a>&#160;\u00bb.<\/p>\n<p>[3] Voir \u00e0 ce sujet l\u2019enqu\u00eate d\u2019\u00c9l\u00e9onore Th\u00e9ry <a href=\"https:\/\/www.lequotidiendelart.com\/articles\/20034-les-influenceurs-nouveaux-chouchous-du-monde-de-l-art.html\">&#160;:<\/a> <a href=\"https:\/\/www.lequotidiendelart.com\/articles\/20034-les-influenceurs-nouveaux-chouchous-du-monde-de-l-art.html\">https:\/\/www.lequotidiendelart.com\/articles\/20034-les-influenceurs-<\/a> <a href=\"https:\/\/www.lequotidiendelart.com\/articles\/20034-les-influenceurs-nouveaux-chouchous-du-monde-de-l-art.html\">nouveaux-chouchous-du-monde-de-l-art.html<\/a><\/p>\n<p>[4] Cette notion de \u00ab&#160;champ \u00e9largi&#160;\u00bb est un double emprunt&#160;: \u00e0 Rosalind Krauss qui semble \u00eatre la premi\u00e8re \u00e0 l\u2019avoir mobilis\u00e9e dans son texte \u00ab&#160;Sculpture in the Expanded Field&#160;\u00bb (\u00ab&#160;La sculpture dans le champ \u00e9largi&#160;\u00bb), p. 277-290 <em>in <\/em>Rosalind Krauss<em>, The Originality of the Avant-Garde and <\/em><em>Other Modernist Myths<\/em>, Cambridge, MIT Press, 1984. Notons aussi son usage par des critiques d\u2019art comme ceux de la revue allemande <em>Texte zur Kunst. <\/em>Voir \u00e0 ce sujet&#160;: Catherine Chevalier, Andreas Fohr (dir.), <em>Une anthologie de la revue Texte zur Kunst de 1990 \u00e0 1998<\/em>, Dijon, Les Presses du r\u00e9el, 2010.<\/p>\n<p>[5] Matthieu B\u00e9ra, \u00ab&#160;Critique d\u2019art ou promotion culturelle&#160;?&#160;\u00bb, <em>R\u00e9seaux<\/em>, n\u00b0 117, 2003\/1, p. 153-187.<\/p>\n<p>[6] Ce n\u00e9ologisme combinant \u00ab&#160;comp\u00e9tition&#160;\u00bb et \u00ab&#160;coop\u00e9ration&#160;\u00bb est utilis\u00e9 pour la premi\u00e8re fois par l\u2019entrepreneur Ray Noorda, puis popularis\u00e9 \u00e0 la fin des ann\u00e9es 1990 par Nalebuff &amp; Brandeburger dans leur ouvrage <em>Coopetition<\/em>. <em>A Revolution Mindset that Combines Competition and Cooperation<\/em>, New York, Crown Businness, 1996.<\/p>\n<h2>Calendrier pr\u00e9visionnel<\/h2>\n<p><strong>\u00a0<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"327\"><strong>Envoi de l\u2019AAC<\/strong><\/td>\n<td width=\"116\"><strong>20 \/10\/2021<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"327\"><strong>Date limite d\u2019envoi des propositions<\/strong><\/td>\n<td width=\"116\"><strong>20 \/12\/ 2021<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"327\"><strong>Communication de la d\u00e9cision du Comit\u00e9 Scientifique<\/strong><\/td>\n<td width=\"116\"><strong>20 \/01\/2022<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"327\"><strong>Journ\u00e9es du colloque<\/strong><\/td>\n<td width=\"116\"><strong>9<\/strong><strong>&#8211;<\/strong><strong>10\/05\/2022<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><strong>\u00a0<\/strong><strong>Comit\u00e9 d\u2019organisation<\/strong><\/h2>\n<ul>\n<li>Lucie ALEXIS, Ma\u00eetresse de conf\u00e9rences, Universit\u00e9 Grenoble Alpes, Institut de la Communication et des M\u00e9dias, GRESEC, chercheuse associ\u00e9e au CARISM et \u00e0 l\u2019Institut national de l\u2019audiovisuel<\/li>\n<li>Flore DI SCIULLO, Docteure en Sciences de l\u2019information et de la communication, ATER, Universit\u00e9 Paris 2 Panth\u00e9on-Assas, Institut Fran\u00e7ais de Presse, chercheuse associ\u00e9e au CARISM<\/li>\n<\/ul>\n<h2>Comit\u00e9 scientifique<\/h2>\n<ul>\n<li>BLANDIN Claire (Professeure, Universit\u00e9 Sorbonne Paris Nord, LabSIC)<\/li>\n<li>BOIVENT Marie (MCF, Universit\u00e9 Rennes 2, laboratoire PTAC)<\/li>\n<li>BULLICH Vincent (MCF HDR, Universit\u00e9 Grenoble Alpes, GRESEC)<\/li>\n<li>CROISSANT Val\u00e9rie (MCF, Universit\u00e9 Lyon 2, ELICO)<\/li>\n<li>DESEILLIGNY Oriane (MCF, Universit\u00e9 Sorbonne Paris Nord, GRIPIC)<\/li>\n<li>DESMET Nathalie (Commissaire, MCF, Universit\u00e9 Paris 8, AIAC)<\/li>\n<li>DEVILLARD Val\u00e9rie (Professeure, Universit\u00e9 Paris 2 Panth\u00e9on-Assas, CARISM)<\/li>\n<li>LAFON Beno\u00eet (Professeur, Universit\u00e9 Grenoble Alpes, GRESEC)<\/li>\n<li>LAMBERT Fr\u00e9d\u00e9ric (Professeur, Universit\u00e9 Paris 2, CARISM)<\/li>\n<li>MOURATIDOU Eleni (MCF HDR, Universit\u00e9 Sorbonne Paris Nord, LabSIC)<\/li>\n<li>STEAD Evanghelia (Professeure, USVQ, CHCSC)<\/li>\n<li>RIEFFEL R\u00e9my (Professeur, Universit\u00e9 Paris 2 Panth\u00e9on-Assas, CARISM)<\/li>\n<li>RINGOOT Roselyne (Professeure, Universit\u00e9 Grenoble Alpes, GRESEC)<\/li>\n<li>SAEMMER Alexandra, (Professeure, Universit\u00e9 Paris 8, CEMTI)<\/li>\n<li>WRONA Adeline (Professeure, Universit\u00e9 Paris 4, GRIPIC)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-attachedfiles\">\n<h3 class=\"zn-singledetail-section-title\">Fichier(s) attach\u00e9(s)<\/h3>\n<ul class=\"zn-singledetail-attachedfiles-list\">\n<li class=\"zn-singledetail-attachedfiles-item\">\n\t\t\t\t\t\t\t<a class=\"zn-singledetail-attachedfiles-link button outline for-download\" href=\"https:\/\/www.sfsic.org\/wp-inside\/uploads\/skp-membership\/demande_adh\/aac_la-presse-culturelle-aujourdhui_2021.pdf\" title=\"T\u00e9l\u00e9charger : \u00ab aac_la-presse-culturelle-aujourdhui_2021.pdf \u00bb\" target=\"_blank\" rel=\"noopener\"><br \/>\n\t\t\t\t\t\t\t\t<span class=\"button-txt\"><span class=\"button-txt-type\"> (pdf)<\/span><\/span><br \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-culture\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/culture-en\/\" title=\"Culture\"><span class=\"termslist-itemname\">Culture<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-medias\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/medias-en\/\" title=\"M\u00e9dias\"><span class=\"termslist-itemname\">M\u00e9dias<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-presse\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/presse-en\/\" title=\"Presse\"><span class=\"termslist-itemname\">Presse<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 20 octobre 2021 Th\u00e9matiques M\u00e9dias et journalisme M\u00e9diations m\u00e9morielles, culturelles et patrimoniales R\u00e9ponse attendue pour le 20\/12\/2021 Type de r\u00e9ponse R\u00e9sum\u00e9 Type d\u2019\u00e9v\u00e9nement Colloque Coordinateurs Lucie [&hellip;]<\/p>\n","protected":false},"author":781,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29,57],"tags":[382,390,378],"thematique":[34,38],"sfsic":[],"class_list":["post-19906","post","type-post","status-publish","format-standard","hentry","category-aac-evenement","category-colloque","tag-culture","tag-medias","tag-presse","thematique-medias-et-journalisme","thematique-mediations-memorielles-culturelles-et-patrimoniales","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?<\/title>\n<meta name=\"description\" content=\"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu&#039;ils organisent et qui traite de la th\u00e9matique &quot;La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\" \/>\n<meta property=\"og:description\" content=\"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu&#039;ils organisent et qui traite de la th\u00e9matique &quot;La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T07:40:41+00:00\" \/>\n<meta name=\"author\" content=\"Axelle Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/\"},\"author\":{\"name\":\"Axelle Martin\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\"},\"headline\":\"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\",\"datePublished\":\"2021-10-21T07:40:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/\"},\"wordCount\":2848,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Culture\",\"M\u00e9dias\",\"Presse\"],\"articleSection\":[\"AAC \u00c9v\u00e9nement\",\"Colloque\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/\",\"name\":\"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2021-10-21T07:40:41+00:00\",\"description\":\"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu'ils organisent et qui traite de la th\u00e9matique \\\"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-evenement\\\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Contributions\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfc-event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conference\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfc-event\\\/conference\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\",\"name\":\"Axelle Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"caption\":\"Axelle Martin\"},\"sameAs\":[\"@antropocominside\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?","description":"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu'ils organisent et qui traite de la th\u00e9matique \"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/","og_locale":"en_US","og_type":"article","og_title":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?","og_description":"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu'ils organisent et qui traite de la th\u00e9matique \"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\".","og_url":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/","og_site_name":"SFSIC","article_published_time":"2021-10-21T07:40:41+00:00","author":"Axelle Martin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/"},"author":{"name":"Axelle Martin","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b"},"headline":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?","datePublished":"2021-10-21T07:40:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/"},"wordCount":2848,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Culture","M\u00e9dias","Presse"],"articleSection":["AAC \u00c9v\u00e9nement","Colloque"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/","url":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/","name":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2021-10-21T07:40:41+00:00","description":"Les laboratoires CARISM et GRESEC lancent un appel \u00e0 contribution pour un colloque qu'ils organisent et qui traite de la th\u00e9matique \"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?\".","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-evenement\/la-presse-culturelle-aujourdhui-un-genre-mediatique-en-reconfiguration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Contributions","item":"https:\/\/www.sfsic.org\/en\/cfc-event\/"},{"@type":"ListItem","position":3,"name":"Conference","item":"https:\/\/www.sfsic.org\/en\/cfc-event\/conference\/"},{"@type":"ListItem","position":4,"name":"La presse culturelle aujourd\u2019hui, un genre m\u00e9diatique en reconfiguration ?"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b","name":"Axelle Martin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","caption":"Axelle Martin"},"sameAs":["@antropocominside"]}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/19906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/781"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=19906"}],"version-history":[{"count":4,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/19906\/revisions"}],"predecessor-version":[{"id":19912,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/19906\/revisions\/19912"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=19906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=19906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=19906"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=19906"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=19906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}