{"id":18324,"date":"2021-06-01T21:23:20","date_gmt":"2021-06-01T19:23:20","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=18324"},"modified":"2021-06-01T21:23:20","modified_gmt":"2021-06-01T19:23:20","slug":"organisations-communications-et-sante-au-travail","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/","title":{"rendered":"Organisations, communications et sant\u00e9 au travail"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> 1 juin 2021\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-communication-organisations\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/thematiques\/communication-organisations\/\" title=\"Communication et organisations\"><span class=\"termslist-itemname\">Communication et organisations<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type d\u2019\u00e9v\u00e9nement<\/span><span class=\"doubledot\"><\/span> <strong>Journ\u00e9e d\u2019\u00e9tude<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-coordinators\">\n<h3 class=\"zn-singledetail-section-title\">Coordinateurs<\/h3>\n<ul class=\"zn-singledetail-coordinators-list\">\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Val\u00e9rie<\/span> <span>L\u00e9pine<\/span>, <span>Universit\u00e9 Paul Val\u00e9ry &#8211; Montpellier 3<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:valerie.lepine@univ-montp3.fr\">valerie.lepine@univ-montp3.fr <\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-coordinators-item\">\n\t\t\t\t\t\t\t<span>Dorsaf<\/span> <span>Omrane<\/span>, <span>IUT Toulouse<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t, <a class=\"zn-singledetail-coordinators-mail prettylink\" href=\"mailto:dorsaf.omrane@iut-tlse.fr\">dorsaf.omrane@iut-tlse.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-eventinfo\">\n<div class=\"zn-singledetail-eventinfo-inner\">\n<div class=\"zn-singledetail-eventdates\">\n\t\t\t\t\t\t<span class=\"zn-singledetail-label\">Dates de l\u2019\u00e9v\u00e9nement<span class=\"doubledot\"><\/span><\/span><\/p>\n<ul class=\"zn-singledetail-eventdates-list\">\n<li class=\"zn-singledetail-eventdates-item\">\n\t\t\t\t\t\t\t\tDu 03\/06\/2021 au 03\/06\/2021, <span class=\"event-schedule\">9h30-17h<\/span>\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<p class=\"zn-singledetail-eventplace\">\n\t\t\t\t\t\t<span class=\"zn-singledetail-label\">Lieu de l\u2019\u00e9v\u00e9nement<span class=\"doubledot\"><\/span><\/span><br \/>\n\t\t\t\t\t\t<span class=\"zn-singledetail-eventplace-adr\"><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"adr-place\">En ligne, sur inscription aupr\u00e8s des organisatrices<\/span>,<\/p>\n<p>\t\t\t\t\t\t<\/span>\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"zn-singledetail-annonce wig-content\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: center\">La journ\u00e9e est ouverte \u00e0 tou.te.s les enseignant.e.s chercheur.e.s int\u00e9ress\u00e9.e.s par la th\u00e9matique sur simple inscription par retour de mail \u00e0 valerie.lepine@univ-montp3.fr ou dorsaf.omrane@iut-tlse.fr<\/p>\n<p style=\"text-align: center\">Journ\u00e9e d\u2019\u00e9tude LERASS \u00ab&#160;Organisations, communications et sant\u00e9 au travail&#160;\u00bb<br \/>\nmodalit\u00e9 visioconf\u00e9rence zoom \u2013 le 3 juin 2021 de 9h30 \u00e0 17h.<\/p>\n<p style=\"text-align: center\">Participer \u00e0 la r\u00e9union Zoom&#160;: <a href=\"http:\/\/fr.zoom.us\/j\/96506371297?pwd=aXl0V3Y0WlBvT2NjKyt0YW1QM2FCdz09\">fr.zoom.us\/j\/96506371297?pwd=aXl0V3Y0WlBvT2NjKyt0YW1QM2FCdz09<\/a><\/p>\n<p style=\"text-align: center\">ID de r\u00e9union&#160;: 965 0637 1297 \u2013 Code secret&#160;: 259502<\/p>\n<h2>Programme<\/h2>\n<p><strong>Matin \u2013 9h30-12h30<\/strong> \u2013 \u00c9changes et propositions pour f\u00e9d\u00e9rer les recherches \u00ab&#160;SIC &amp; sant\u00e9&#160;\u00bb<\/p>\n<p>De nombreux travaux sont men\u00e9s en France par les chercheurs en SIC s\u2019int\u00e9ressant aux questions de sant\u00e9 avec des angles divers&#160;: pratiques d\u2019information-communication en sant\u00e9 des professionnels et \/ou usagers&#160;; mod\u00e8les, dispositifs, techniques d\u2019information-communication dans les organisations de sant\u00e9&#160;; communication de crise et\/ou de pr\u00e9vention des risques sanitaires&#160;; publicisation des questions de sant\u00e9 dans l\u2019espace public et\/ou m\u00e9diatique&#160;; sant\u00e9 au travail et communication&#160;; etc.<\/p>\n<p>Ces travaux conduits dans diff\u00e9rents laboratoires \u2013 parfois mais pas syst\u00e9matiquement dans le cadre d\u2019un axe Sant\u00e9 identifi\u00e9 \u2013 gagneraient-ils en visibilit\u00e9 et pourraient-ils \u00eatre davantage partag\u00e9s, valoris\u00e9s et avec quelles modalit\u00e9s&#160;? Nous proposons d\u2019initier une r\u00e9flexion collective pour tracer des propositions qui permettront d\u2019engager un travail d\u2019identification, de structuration, de valorisation des recherches en \u00ab&#160;communication &amp; sant\u00e9&#160;\u00bb afin que la contribution des SIC soient mieux identifi\u00e9es au sein des SHS \u2013 tout particuli\u00e8rement dans la p\u00e9riode de pand\u00e9mie mondiale actuelle dont chacun sait que les cons\u00e9quences se prolongeront sur le long terme.<\/p>\n<p><strong>Pause 11h30-11h40<\/strong><\/p>\n<p><strong>11h40-12h20&#160;:<\/strong> Fabienne Martin-Juchat (PU, Universit\u00e9 Grenoble Alpes, Gresec) \u2013 Une ouverture m\u00e9thodologique&#160;: \u00ab&#160;Le co-design bas\u00e9 sur les r\u00e9cits d\u2019affects&#160;: une m\u00e9thode issue de l\u2019anthropologie par la communication \u00e9motionnelle&#160;\u00bb.<\/p>\n<p><strong>13h30- 16h30<\/strong>&#160;: \u00ab&#160;Sant\u00e9 au travail et communications&#160;\u00bb \u2013 JE labellis\u00e9e Org&amp;Co<\/p>\n<p><strong>13h30-14h10<\/strong>&#160;: Marine Aznar, (doctorante Universit\u00e9 Grenoble Alpes, Gresec), Val\u00e9rie L\u00e9pine (PU, Univ. Paul Val\u00e9ry-Montpellier3, Lerass), Fabienne Martin-Juchat (PU, Universit\u00e9 Grenoble Alpes, Gresec)&#160;: \u00ab&#160;NMP et h\u00f4pital en tension \u2013 Quelle place pour les \u00e9motions au travail&#160;?&#160;\u00bb.<\/p>\n<p><strong>14h10-14h50<\/strong>&#160;: Sylvie Alemanno (PU, Cnam, Dicen) &amp; Salma El Bourkadi (doctorante Cnam, Dicen)&#160;: \u00ab&#160;La sant\u00e9 au travail (re)consid\u00e9rations \u00e0 partir du cas d\u2019Uber&#160;\u00bb.<\/p>\n<p><strong>Pause 14h50-15h<\/strong><\/p>\n<p><strong>15h00 \u2013 15h40<\/strong>&#160;: Isabelle Bazet (MCF, IUT Tarbes, UPS Toulouse 3, Certop) et Philippe Marrast (MCF, IUT Tarbes, UPS Toulouse 3, Certop)&#160;: \u00ab&#160;Territoires de la sant\u00e9&#160;: de l\u2019aporie des prises en charge et du travail de l\u2019\u00eatre en sant\u00e9&#160;\u00bb.<\/p>\n<p><strong>15h40 \u2013 16h20&#160;:<\/strong> Laurent Morillon ((PU, D\u00e9l\u00e9gu\u00e9 r\u00e9gional acad\u00e9mique \u00e0 la recherche et \u00e0 l\u2019innovation pour la Martinique)&#160;: \u00ab&#160;Une Approche communicationnelle de la sant\u00e9 au travail&#160;\u00bb, Pr\u00e9sentation du num\u00e9ro th\u00e9matique de la revue Sciences de la soci\u00e9t\u00e9 \u2013 Coord. L., Morillon, V. Carayol, S. Grosjean.<\/p>\n<p><strong>16h20 \u2013 17h<\/strong>&#160;: \u00e9changes et conclusion. Val\u00e9rie L\u00e9pine (PU, Universit\u00e9 Paul Val\u00e9ry \u2013 Montpellier 3, Lerass), Dorsaf Omrane (MCF, IUT, Universit\u00e9 Paul Sabatier -Toulouse3, Lerass)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>La sant\u00e9 est d\u00e9finie par l\u2019OMS comme un \u00e9tat de complet bien-\u00eatre physique, mental et social et ne consiste pas seulement en une absence de maladie ou d\u2019infirmit\u00e9. Diff\u00e9rents contextes particuli\u00e8rement mouvants l\u2019influencent&#160;: politiques de sant\u00e9 publique (dont celles de pr\u00e9vention, de vaccination, de traitement des maladies, de protection sociale\u2026), choix strat\u00e9giques et lobbying de l\u2019industrie pharmaceutique, syst\u00e8me de sant\u00e9 et \u00e9volution des offres et demandes de soins, \u00e9mergence de nouvelles pathologies\u2026 La sant\u00e9 est r\u00e9v\u00e9latrice d\u2019enjeux forts que ce soit au niveau soci\u00e9tal, r\u00e9glementaire, institutionnel ou individuel.<\/p>\n<p>La sant\u00e9 est un axe de recherche strat\u00e9gique des trois \u00e9tablissements de tutelle du LERASS, les universit\u00e9s Paul Sabatier, Toulouse Jean-Jaur\u00e8s et Paul Val\u00e9ry Montpellier 3. Dans ce contexte pluridisciplinaire, le champ de la sant\u00e9 peut \u00eatre appr\u00e9hend\u00e9 comme un contexte, un sujet, un objet, un secteur, une organisation, etc. Les prismes informationnels, communicationnels, langagiers, psycho- sociaux ou encore gestionnaires apportent des cadres de r\u00e9flexions ainsi que des approches sp\u00e9cifiques pour questionner une diversit\u00e9 de ph\u00e9nom\u00e8nes&#160;: enjeux, logiques d\u2019usage et pratiques associ\u00e9es, r\u00f4les et influences de dispositifs, strat\u00e9gies organisationnelles, r\u00e9ception m\u00e9diatique, interactions, m\u00e9diations et repr\u00e9sentations \u00e0 l\u2019\u0153uvre, co-construction du sens en contexte, etc.<\/p>\n<p>Que ce soit sur la sc\u00e8ne socio-professionnelle, celle des m\u00e9dias ou encore de la recherche scientifique, les questions de \u00ab&#160;sant\u00e9 au travail&#160;\u00bb sont d\u2019actualit\u00e9 dans les pays occidentaux depuis les ann\u00e9es 1990. En France, de nombreuses mesures visant \u00e0 r\u00e9duire les risques et \u00e0 am\u00e9liorer les conditions concr\u00e8tes de l\u2019exercice de l\u2019activit\u00e9 professionnelle ont \u00e9t\u00e9 prises par les pouvoirs publics. R\u00e9cemment, la crise sanitaire li\u00e9e \u00e0 la Covid 19 a fortement influenc\u00e9 les conditions du travail et amplifi\u00e9 les risques psychosociaux&#160;: planification d\u2019urgence, t\u00e9l\u00e9travail, gestion de crise, risque de pr\u00e9carit\u00e9 et de perte d\u2019emploi, etc. A ces injonctions organisationnelles et sanitaires dans un environnement socio\u00e9conomique anxiog\u00e8ne s\u2019ajoutent les perceptions et craintes individuelles pour sa propre sant\u00e9 et celle de ses proches .<\/p>\n<p>Au sein des organisations, si les dirigeants proclament que le bien-\u00eatre des personnels est une composante essentielle de la r\u00e9ussite, face \u00e0 des environnements incertains, les r\u00e9organisations et les nouveaux modes de management peuvent s\u2019av\u00e9rer stressants. La question de la \u00ab&#160;souffrance au travail&#160;\u00bb popularis\u00e9e par les travaux de Christophe Dejours (1998) a \u00e9t\u00e9 reformul\u00e9e en \u00ab&#160;souffrance du travail&#160;\u00bb par Yves Clot (2020) pour insister sur les dysfonctionnements de l\u2019organisation du travail. L\u2019imposition d\u2019un t\u00e9l\u00e9travail quasi g\u00e9n\u00e9ralis\u00e9 dans le secteur des services a mis au jour de nouveaux risques psychosociaux li\u00e9s \u00e0 l\u2019isolement et une certaine prise de conscience de l\u2019importance des interactions sociales au travail.<\/p>\n<p>Encore peu explor\u00e9es, les analyses des ph\u00e9nom\u00e8nes info-communicationnels sont susceptibles d\u2019apporter un \u00e9clairage original et pertinent sur ces questions. La journ\u00e9e d\u2019\u00e9tude organis\u00e9e par l\u2019axe sant\u00e9 du Lerass marque la volont\u00e9 de r\u00e9unir les chercheur.e.s qui abordent les enjeux de la sant\u00e9 au travail dans une perspective ancr\u00e9e en sciences de l\u2019information et de la communication.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Il s\u2019agira, par exemple, d\u2019interroger l\u2019\u00e9volution des mod\u00e8les de pens\u00e9e et des discours publics ou manag\u00e9riaux \u00e0 partir des glissements s\u00e9mantiques qui ont jalonn\u00e9 la construction des questions de sant\u00e9 au travail depuis les premi\u00e8res d\u00e9finitions des \u00ab&#160;risques psychosociaux&#160;\u00bb (RPS) jusqu\u2019\u00e0 la formulation du projet de \u00ab&#160;bien-\u00eatre&#160;\u00bb (BET) voire de \u00ab&#160;bonheur&#160;\u00bb au travail, prolongeant les recommandations pour l\u2019am\u00e9lioration de la \u00ab&#160;qualit\u00e9 de vie au travail&#160;\u00bb (QVT). Que peut-on dire des injonctions \u00e0 vivre le travail avec bonheur, des chartes d\u2019engagement \u00e0 une responsabilit\u00e9 sociale respectueuse de la sant\u00e9 (des salari\u00e9s mais aussi de l\u2019environnement, des territoires, etc.)&#160;? Ces pr\u00e9occupations, d\u00e9sormais int\u00e9gr\u00e9es dans l\u2019ordre juridique ou r\u00e9glementaire, ont-elles permis une am\u00e9lioration de la qualit\u00e9 des relations de et au travail&#160;? Ont-elles fait \u00e9voluer les missions et les pratiques de la communication interne et manag\u00e9riale&#160;?<\/p>\n<p>La place grandissante des technologies d\u2019information et de communication, les effets d\u2019acc\u00e9l\u00e9ration et de morcellement des activit\u00e9s, ou encore d\u2019empi\u00e8tement sur le temps de vie priv\u00e9e ont conduit les pouvoirs publics \u00e0 imposer une n\u00e9gociation relative au \u00ab&#160;droit \u00e0 la d\u00e9connexion&#160;\u00bb (loi Travail 2017). Qu\u2019en est-il en r\u00e9alit\u00e9 des pratiques actuelles et de quelles mani\u00e8res les usages des TIC affectent-ils la sant\u00e9 des travailleurs \u2013 tout particuli\u00e8rement dans le contexte de crise pand\u00e9mique actuel&#160;?<\/p>\n<p>Plus largement, la sant\u00e9 au travail est un enjeu qui concerne aussi les situations d\u2019exclusion, d\u2019in\u00e9galit\u00e9s d\u2019acc\u00e8s au travail en raison de situations particuli\u00e8res \u2013 handicap, retour de cong\u00e9 pour maladie, p\u00e9nibilit\u00e9, etc. Elle croise ainsi les probl\u00e9matiques de la communication sociale (promotion de la diversit\u00e9, respect de l\u2019\u00e9galit\u00e9 femmes-hommes, des \u00e9quilibres vie priv\u00e9e-vie professionnelle) et de la pr\u00e9vention.<\/p>\n<p>Dans quelle mesure les recherches en SIC peuvent-elles apporter un \u00e9clairage pertinent sur ces sujets d\u2019une importance sociale amplifi\u00e9e par la crise sanitaire et socio\u00e9conomique en cours et avec quelles approches m\u00e9thodologiques sp\u00e9cifiques&#160;?<\/p>\n<p>La journ\u00e9e d\u2019\u00e9tudes, labellis\u00e9e Org&amp;Co, propose la pr\u00e9sentation de recherches r\u00e9alis\u00e9es ou en cours portant sur la th\u00e9matique \u00ab&#160;Organisations, communications et sant\u00e9 au travail&#160;\u00bb.<\/p>\n<p>Au-del\u00e0 du domaine des communications organisationnelles, un temps d\u2019\u00e9changes permettra de mettre en commun diff\u00e9rentes probl\u00e9matiques abord\u00e9es au sein des recherches men\u00e9es plus largement en \u00ab&#160;SIC &amp; sant\u00e9&#160;\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-communication\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/communication\/\" title=\"Communication\"><span class=\"termslist-itemname\">Communication<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-organisation\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/organisation\/\" title=\"Organisation\"><span class=\"termslist-itemname\">Organisation<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-sante\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/sante\/\" title=\"Sant\u00e9\"><span class=\"termslist-itemname\">Sant\u00e9<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-travail\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/tag\/travail\/\" title=\"Travail\"><span class=\"termslist-itemname\">Travail<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 1 juin 2021 Th\u00e9matiques Communication et organisations Type d\u2019\u00e9v\u00e9nement Journ\u00e9e d\u2019\u00e9tude Coordinateurs Val\u00e9rie L\u00e9pine, Universit\u00e9 Paul Val\u00e9ry &#8211; Montpellier 3 , valerie.lepine@univ-montp3.fr Dorsaf Omrane, IUT Toulouse [&hellip;]<\/p>\n","protected":false},"author":781,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30,68],"tags":[363,74,98,109],"thematique":[37],"sfsic":[],"class_list":["post-18324","post","type-post","status-publish","format-standard","hentry","category-evenement","category-journee-etude-2","tag-communication","tag-organisation","tag-sante","tag-travail","thematique-communication-organisations","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Organisations, communications et sant\u00e9 au travail<\/title>\n<meta name=\"description\" content=\"Le programme de la journ\u00e9e d&#039;\u00e9tude LERASS sur la th\u00e9matique &quot;Organisations, communications et sant\u00e9 au travail&quot; qui se d\u00e9roulera le 3 juin, est en ligne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organisations, communications et sant\u00e9 au travail\" \/>\n<meta property=\"og:description\" content=\"Le programme de la journ\u00e9e d&#039;\u00e9tude LERASS sur la th\u00e9matique &quot;Organisations, communications et sant\u00e9 au travail&quot; qui se d\u00e9roulera le 3 juin, est en ligne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T19:23:20+00:00\" \/>\n<meta name=\"author\" content=\"Axelle Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/\"},\"author\":{\"name\":\"Axelle Martin\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\"},\"headline\":\"Organisations, communications et sant\u00e9 au travail\",\"datePublished\":\"2021-06-01T19:23:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/\"},\"wordCount\":1552,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Communication\",\"Organisation\",\"Sant\u00e9\",\"Travail\"],\"articleSection\":[\"\u00c9v\u00e9nements\",\"Journ\u00e9e d\u2019\u00e9tude\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/\",\"name\":\"Organisations, communications et sant\u00e9 au travail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2021-06-01T19:23:20+00:00\",\"description\":\"Le programme de la journ\u00e9e d'\u00e9tude LERASS sur la th\u00e9matique \\\"Organisations, communications et sant\u00e9 au travail\\\" qui se d\u00e9roulera le 3 juin, est en ligne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/evenement\\\/organisations-communications-et-sante-au-travail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Study Day\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/events\\\/study-day-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Organisations, communications et sant\u00e9 au travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\",\"name\":\"Axelle Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"caption\":\"Axelle Martin\"},\"sameAs\":[\"@antropocominside\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organisations, communications et sant\u00e9 au travail","description":"Le programme de la journ\u00e9e d'\u00e9tude LERASS sur la th\u00e9matique \"Organisations, communications et sant\u00e9 au travail\" qui se d\u00e9roulera le 3 juin, est en ligne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/","og_locale":"en_US","og_type":"article","og_title":"Organisations, communications et sant\u00e9 au travail","og_description":"Le programme de la journ\u00e9e d'\u00e9tude LERASS sur la th\u00e9matique \"Organisations, communications et sant\u00e9 au travail\" qui se d\u00e9roulera le 3 juin, est en ligne.","og_url":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/","og_site_name":"SFSIC","article_published_time":"2021-06-01T19:23:20+00:00","author":"Axelle Martin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/"},"author":{"name":"Axelle Martin","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b"},"headline":"Organisations, communications et sant\u00e9 au travail","datePublished":"2021-06-01T19:23:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/"},"wordCount":1552,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Communication","Organisation","Sant\u00e9","Travail"],"articleSection":["\u00c9v\u00e9nements","Journ\u00e9e d\u2019\u00e9tude"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/","url":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/","name":"Organisations, communications et sant\u00e9 au travail","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2021-06-01T19:23:20+00:00","description":"Le programme de la journ\u00e9e d'\u00e9tude LERASS sur la th\u00e9matique \"Organisations, communications et sant\u00e9 au travail\" qui se d\u00e9roulera le 3 juin, est en ligne.","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/evenement\/organisations-communications-et-sante-au-travail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.sfsic.org\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Study Day","item":"https:\/\/www.sfsic.org\/en\/events\/study-day-2\/"},{"@type":"ListItem","position":4,"name":"Organisations, communications et sant\u00e9 au travail"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b","name":"Axelle Martin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","caption":"Axelle Martin"},"sameAs":["@antropocominside"]}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/18324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/781"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=18324"}],"version-history":[{"count":2,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/18324\/revisions"}],"predecessor-version":[{"id":18326,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/18324\/revisions\/18326"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=18324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=18324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=18324"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=18324"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=18324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}