{"id":16105,"date":"2021-03-15T12:24:27","date_gmt":"2021-03-15T11:24:27","guid":{"rendered":"https:\/\/www.sfsic.org\/?p=16105"},"modified":"2021-03-09T11:24:45","modified_gmt":"2021-03-09T10:24:45","slug":"bd-et-romans-graphiques-au-travail","status":"publish","type":"post","link":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/","title":{"rendered":"BD et romans graphiques au travail"},"content":{"rendered":"<p><!-- fxzn:singledetail --><\/p>\n<div class=\"zone zn-singledetail\" id=\"fxzn-singledetail-1\">\n<div class=\"zone-block zn-singledetail-block alignwide va-top\">\n<div class=\"row\">\n<div class=\"columns large-8 large-push-4\">\n<div class=\"zn-singledetail-metabox\">\n<div class=\"zn-singledetail-pubdate pubdate\">\n\t\t\t\t\t<span class=\"pubdate-txt\">Mis en ligne le<\/span><span class=\"doubledot\"><\/span> 9 mars 2021\t\t\t\t<\/div>\n<div class=\"zn-singledetail-thematiques with-sep-comma\">\n<ul class=\"termslist termslist-thematique\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Th\u00e9matiques<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-thematique term-images-cinema-medias-audiovisuels-et-industries-culturelles\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/thematiques\/images-cinema-audiovisual-media-and-cultural-industries\/\" title=\"Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles\"><span class=\"termslist-itemname\">Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles<\/span><\/a><\/li>\n<li class=\"termslist-item tax-thematique term-mediations-memorielles-culturelles-patrimoniales\"><a class=\"termslist-itemlink\" href=\"\/?thematique=mediations-memorielles-culturelles-patrimoniales\" title=\"M\u00e9diations m\u00e9morielles, culturelles et patrimoniales\"><span class=\"termslist-itemname\">M\u00e9diations m\u00e9morielles, culturelles et patrimoniales<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"columns large-4\">\n<div class=\"zn-singledetail-sidebar bg-cornersquares\">\n<div class=\"zn-singledetail-infos\">\n<p class=\"zn-singledetail-reponse-date\">\n\t\t\t\t\t\t<span>R\u00e9ponse attendue pour le<\/span><span class=\"doubledot\"><\/span> <strong>31\/05\/2021<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-reponse-type\">\n\t\t\t\t\t<span>Type de r\u00e9ponse<\/span><span class=\"doubledot\"><\/span> <strong>R\u00e9sum\u00e9<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-type\">\n\t\t\t\t\t\t\t<span>Type de contribution attendue<\/span><span class=\"doubledot\"><\/span> <strong>Article<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"zn-singledetail-name\">\n\t\t\t\t\t\t\t<span>Nom de la publication<\/span><span class=\"doubledot\"><\/span> <strong>Revue Images du travail, travail des images<\/strong>\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-contacts\">\n<h3 class=\"zn-singledetail-section-title\">Contacts<\/h3>\n<ul class=\"zn-singledetail-contacts-list\">\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">Jean-Paul G\u00e9hin, universit\u00e9 de Poitiers, GRESCO <\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:jpgehin@gmail.com\">jpgehin@gmail.com<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">Fran\u00e7oise F. Laot, universit\u00e9 Paris 8 Vincennes-Saint-Denis, EXPERICE<\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:francoise.laot@univ-paris8.fr\">francoise.laot@univ-paris8.fr<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">Pierre Noc\u00e9rino, EHESS, LIER-FYT <\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:pierre.nocerino@gmail.com\">pierre.nocerino@gmail.com<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<li class=\"zn-singledetail-contact\">\n\t\t\t\t\t\t\t<span class=\"zn-singledetail-contact-name\">La revue Image du travail, Travail des images <\/span><span class=\"doubledot\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"zn-singledetail-contact-mail prettylink\" href=\"mailto:imagesdutravail@gmail.com\">imagesdutravail@gmail.com<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div class=\"zn-singledetail-weblinks\">\n<h3 class=\"zn-singledetail-section-title\">Sites internet de r\u00e9f\u00e9rence<\/h3>\n<ul class=\"zn-singledetail-weblinks-list\">\n<li>\n\t\t\t\t\t\t\t<a class=\"prettylink chainlink\" href=\"https:\/\/itti.hypotheses.org\/1460\" title=\"Site de l'appel \u00e0 article\" target=\"_blank\" rel=\"noopener\">Site de l&#8217;appel \u00e0 article<\/a>\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"columns large-8\">\n<div class=\"zn-singledetail-contentbox\">\n<div class=\"zn-singledetail-annonce wig-content\">\n<p>Bien culturel particuli\u00e8rement appr\u00e9ci\u00e9, la bande dessin\u00e9e conduit \u00e0 interroger le travail de multiples fa\u00e7ons.<\/p>\n<p>Elle permet tout d\u2019abord de mettre le travail en image&#160;: nombre de publications d\u00e9crivent aujourd\u2019hui diverses r\u00e9alit\u00e9s sociales, parmi lesquelles de multiples pratiques professionnelles (G\u00e9hin, 2018-2019). Ce ph\u00e9nom\u00e8ne est accentu\u00e9 par l\u2019\u00e9mergence de la bande dessin\u00e9e documentaire, appel\u00e9e aussi \u00ab&#160;bande dessin\u00e9e reportage&#160;\u00bb ou encore \u00ab&#160;bande dessin\u00e9e du r\u00e9el&#160;\u00bb, soit un genre visant \u00e0 rendre compte du r\u00e9el pour t\u00e9moigner (Lesage, 2017). La bande dessin\u00e9e documentaire conna\u00eet la notori\u00e9t\u00e9 avec l\u2019obtention par Art Spiegelman du prix Pulitzer en 1992 ou plus tard le succ\u00e8s des albums de Joe Sacco. Au point que certaines structures \u00e9ditoriales se d\u00e9dient \u00e0 ce type de production&#160;: outre les collections cr\u00e9\u00e9es au sein de multiples maisons d\u2019\u00e9dition, on peut citer les journaux <em>La revue dessin\u00e9e, The nib<\/em> et <em>Topo<\/em>.<\/p>\n<p>Mais si la bande dessin\u00e9e interroge le travail, c\u2019est aussi et surtout en tant qu\u2019activit\u00e9 sociale \u00e0 part enti\u00e8re. En effet, la production de ces r\u00e9cits dessin\u00e9s n\u00e9cessite tout un ensemble d\u2019acteurs et d\u2019actrices impliqu\u00e9\u00b7es \u00e0 diff\u00e9rents niveaux de cr\u00e9ation et\/ou d\u2019ex\u00e9cution dans le process d\u2019\u00e9dition. Si les auteurs et autrices comme les \u00e9diteurs et \u00e9ditrices peuvent mettre en avant le plaisir qu\u2019ils et elles ont dans leur activit\u00e9, ils et elles soulignent parall\u00e8lement les nombreuses difficult\u00e9s du milieu&#160;: pr\u00e9carit\u00e9 \u00e9conomique, pression pour tenir les d\u00e9lais, sexisme omnipr\u00e9sent et invisibilisation du travail des femmes, manque de reconnaissance de la part du public ou de l\u2019\u00c9tat, etc. Ces plaisirs et souffrances au travail des professionnel\u00b7les ont conduit \u00e0 des mobilisations et \u00e0 la cr\u00e9ation de collectifs<a href=\"https:\/\/itti.hypotheses.org\/1460#_ftn1\">[1]<\/a>. Ils sont parfois aussi des sources d\u2019inspiration, qu\u2019ils soient trait\u00e9s frontalement (<em>D\u00e9s\u0153uvr\u00e9<\/em> de Lewis Trondheim, <em>Une vie dans les marges<\/em> de Yoshihiro Tatsumi, <em>Cases Blanches<\/em> d\u2019Olivier Martin et Sylvain Runberg\u2026) ou indirectement (<em>Les Ignorants<\/em> d\u2019\u00c9tienne Davodeau, <em>Le roi des bourdons<\/em> de David de Thuin, la s\u00e9rie l\u2019Atelier Mastodonte publi\u00e9e dans <em>le Journal de Spirou<\/em>\u2026).<\/p>\n<p>Une fois encore, l\u2019\u00e9volution du m\u00e9dium renforce ce ph\u00e9nom\u00e8ne. En effet, s\u2019est d\u00e9velopp\u00e9e une bande dessin\u00e9e autobiographique permettant \u00e0 l\u2019auteur ou \u00e0 l\u2019autrice de mettre sa vie au c\u0153ur du r\u00e9cit, activant ainsi <em>l\u2019imagination sociologique <\/em>que Charles Wright Mills (1961) appelait de ses v\u0153ux, et rendant l\u2019individu capable de situer sa biographie dans la grande histoire. N\u00e9e dans les ann\u00e9es\u00a01960 au Japon et aux \u00c9tats-Unis, la bande dessin\u00e9e autobiographique s\u2019est fortement d\u00e9velopp\u00e9e d\u00e8s la fin du XX<sup>e<\/sup> si\u00e8cle, que ce soit dans les fanzines ou l\u2019\u00e9dition traditionnelle en passant par les blogs BD. Ce courant a donn\u00e9 lieu \u00e0 de nombreuses productions remarquables, notamment en Europe, comme celles de Marguerite Abouet, Antonio Altarriba, Manu Larcenet, Catherine Meurisse, Marjane Satrapi ou Riad Sattouf, parmi bien d\u2019autres.<\/p>\n<p>Ces deux tendances lourdes observ\u00e9es dans le secteur de la bande dessin\u00e9e \u2013 souci documentaire et inspiration autobiographique \u2013 se r\u00e9unissent au sein d\u2019un genre plus large&#160;: le roman graphique. Si cette expression n\u2019est pas sans poser probl\u00e8me du fait d\u2019une d\u00e9finition vague et allusive<a href=\"https:\/\/itti.hypotheses.org\/1460#_ftn2\">[2]<\/a>, elle permet d\u2019insister sur la forte r\u00e9flexivit\u00e9 d\u00e9velopp\u00e9e lors de la production de ces \u0153uvres. En effet, qu\u2019elles soient engag\u00e9es ou non, ces publications s\u2019accompagnent souvent d\u2019une r\u00e9flexion sur la d\u00e9marche et les possibilit\u00e9s du m\u00e9dium, renvoyant au d\u00e9veloppement de la litt\u00e9rature dite de \u00ab&#160;non-fiction&#160;\u00bb (Groensteen, 2016). Une telle d\u00e9marche s\u2019alimente \u00e0 trois sources importantes&#160;: les techniques d\u2019investigation des sciences sociales, le r\u00e9cit de soi, la d\u00e9marche journalistique.<\/p>\n<p>Se pose d\u00e8s lors la question\u00a0suivante&#160;: En quoi le travail mis en images est-il affect\u00e9 et orient\u00e9 par l\u2019organisation et les modalit\u00e9s du travail de l\u2019ombre&#160;?<\/p>\n<p>Pour r\u00e9pondre, ce num\u00e9ro th\u00e9matique d\u2019ITTI interrogera l\u2019articulation entre deux dimensions compl\u00e9mentaires&#160;:<\/p>\n<ul>\n<li>La premi\u00e8re concerne les acteurs et les actrices du secteur, leurs caract\u00e9ristiques sociales, leurs parcours professionnels, la division du travail, les rapports sociaux de production, les modalit\u00e9s d\u2019apprentissage et d\u2019insertion, les difficult\u00e9s rencontr\u00e9es pour faire sa place, l\u2019existence de plafonds de verre selon l\u2019origine sociale, culturelle ou socio-sexuelle\u2026<\/li>\n<li>La seconde renvoie au contenu m\u00eame des productions&#160;: quelle place y tient le travail&#160;? Quels aspects du travail contemporain et de son \u00e9volution y sont retenus, montr\u00e9s et de quelle mani\u00e8re&#160;? En quoi peut-on y lire la marque de celui des acteurs et des actrices du secteur&#160;?<\/li>\n<\/ul>\n<p>L\u2019articulation entre ces deux p\u00f4les servira de fil rouge \u00e0 la construction du num\u00e9ro, mais devrait pouvoir \u00e9galement \u00eatre trait\u00e9e en soi, de mani\u00e8re centrale ou p\u00e9riph\u00e9rique, au sein de chaque contribution.<\/p>\n<p>Le num\u00e9ro vise \u00e0 poursuivre la r\u00e9flexion en\u00a0laissant la possibilit\u00e9\u00a0aux\u00a0contributeurs et contributrices\u00a0qui le souhaitent\u00a0de faire des propositions\u00a0d\u2019articles\u00a0sous forme de bande dessin\u00e9e, notamment dans la rubrique \u00ab&#160;Images en\u00a0chantier&#160;\u00bb de la revue, qui a pour\u00a0vocation de publier des travaux\u00a0mobilisant de mani\u00e8re innovante les images. L\u2019\u00e9criture en bande dessin\u00e9e des sciences sociales est effectivement un r\u00e9v\u00e9lateur des \u00e9preuves et routines du travail des recherches, que ce soit lors du recueil, de l\u2019analyse ou de la restitution des donn\u00e9es (Noc\u00e9rino, 2016&#160;; Kuttner, Sousanis et Weaver-Hightower, 2017). Outre des propositions dessin\u00e9es, les chercheurs et chercheuses peuvent aussi proposer des articles revenant sur les modalit\u00e9s d\u2019organisation du travail qui permettent ou, au contraire, limitent la mise en image de leur propre travail.<\/p>\n<p>Les propositions de contributions peuvent \u00eatre issues des diff\u00e9rentes sciences sociales. Elles reposent sur l\u2019analyse et\/ou la production d\u2019un corpus d\u2019images (y compris, bien s\u00fbr, de bandes dessin\u00e9es). Ces images doivent \u00eatre reproduites dans l\u2019article. Rappelons que\u00a0<em>Images du travail, Travail des images<\/em>\u00a0est une revue scientifique enti\u00e8rement num\u00e9rique, gratuite et ouverte. L\u2019auteur doit \u00e0 ce titre s\u2019assurer de la disposition des droits d\u2019utilisation et de diffusion. Les articles sont d\u2019un format de 30\u2009000 \u00e0 50\u2009000 signes maximum. <strong>Dans un premier temps, sont attendues des propositions d\u2019articles soit un texte d\u2019intention de 2000 \u00e0 3000 signes<\/strong> en tenant compte du <strong>calendrier<\/strong> suivant&#160;:<\/p>\n<ul>\n<li><strong>31 mai 2021<\/strong>&#160;: date limite de r\u00e9ception des propositions par courriel aux adresses suivantes\u00a0 (ces propositions peuvent \u00eatre r\u00e9dig\u00e9e en fran\u00e7ais comme en anglais).<\/li>\n<li><strong>15 d\u00e9cembre 2021<\/strong>&#160;: envoi des articles en vue de leur soumission au comit\u00e9 de r\u00e9daction de la revue (les publications devront imp\u00e9rativement \u00eatre r\u00e9dig\u00e9e en fran\u00e7ais).<\/li>\n<\/ul>\n<h2>Contacts pour toutes informations compl\u00e9mentaires et pour l\u2019envoi des documents&#160;:<\/h2>\n<ul>\n<li>Jean-Paul G\u00e9hin, universit\u00e9 de Poitiers, GRESCO&#160;: <a href=\"mailto:jpgehin@gmail.com\">jpgehin@gmail.com<\/a><\/li>\n<li>Fran\u00e7oise F. Laot, universit\u00e9 Paris\u00a08 Vincennes-Saint-Denis, EXPERICE, <a href=\"mailto:francoise.laot@univ-paris8.fr\">francoise.laot@univ-paris8.fr<\/a><\/li>\n<li>Pierre Noc\u00e9rino, EHESS, LIER-FYT&#160;: <a href=\"mailto:pierre.nocerino@gmail.com\">pierre.nocerino@gmail.com<\/a><\/li>\n<li>La revue\u00a0<em>Image du travail, Travail des images&#160;: <\/em><a href=\"mailto:imagesdutravail@gmail.com\">imagesdutravail@gmail.com<\/a><\/li>\n<\/ul>\n<h2><strong>Bibliographie\u00a0<\/strong><\/h2>\n<p>Baetens J. (2012), \u00ab&#160;Le roman graphique&#160;\u00bb, dans \u00c9. Maigret et M. Stefanelli\u00a0(eds.), <em>La bande dessin\u00e9e&#160;: une m\u00e9diaculture<\/em>, Paris, A.\u00a0Colin, p.\u00a0200\u2011216.<\/p>\n<p>G\u00e9hin J.-P. (2018-2019), \u00ab&#160;La bande dessin\u00e9e montre le travail de l\u2019int\u00e9rieur. 1. Un regard \u00e0 la fois document\u00e9 et intimiste. 2.\u00a0 Le point de vue des domin\u00e9s 3. Un point de vue renouvel\u00e9 sur le travail et les professions.&#160;\u00bb, <em>Images du travail [En ligne]<\/em> (url&#160;: <a href=\"https:\/\/itti.hypotheses.org\/818\">https:\/\/itti.hypotheses.org\/818<\/a> &#160;; <a href=\"https:\/\/itti.Hypotheses.org\/1169\">https:\/\/itti.Hypotheses.org\/1169<\/a>&#160;; <a href=\"https:\/\/itti.hypotheses.org\/1218\">https:\/\/itti.hypotheses.org\/1218<\/a> )<\/p>\n<p>Groensteen T. (2016), \u00ab&#160;Extension du domaine de la non-fiction&#160;\u00bb, <em>neuvi\u00e8me art 2.0 [En ligne]<\/em> (url&#160;: <a href=\"http:\/\/neuviemeart.citebd.org\/spip.php?article1091\">http:\/\/neuviemeart.citebd.org\/spip.php?article1091<\/a>).<\/p>\n<p>Kuttner, P.\u00a0J., Sousanis N. et Weaver-Hightower M.\u00a0B. (2017), \u00ab&#160;How to Draw Comics the Scholarly Way&#160;: Creating Comics-Based Research in the Academy&#160;\u00bb dans P. Leavy\u00a0(ed.), <em>Handbook of Arts-Based Research<\/em>, New York, The Guilford Press, p.\u00a0398\u2011422.<\/p>\n<p>Lesage S. (2017), \u00ab&#160;La bande dessin\u00e9e, une nouvelle \u00e9criture de l\u2019info&#160;\u00bb, <em>La revue des m\u00e9dias [En ligne]<\/em> (url&#160;: <a href=\"https:\/\/larevuedesmedias.ina.fr\/la-bande-dessinee-une-nouvelle-ecriture-de-linfo\">https:\/\/larevuedesmedias.ina.fr\/la-bande-dessinee-une-nouvelle-ecriture-de-linfo<\/a>).<\/p>\n<p>Mills C.\u00a0W. (2006 [1961]), <em>L\u2019imagination sociologique<\/em>, Paris, La D\u00e9couverte.<\/p>\n<p>Noc\u00e9rino P. (2016), \u00ab&#160;Ce que la bande dessin\u00e9e nous apprend de l\u2019\u00e9criture sociologique&#160;\u00bb, <em>Sociologie et soci\u00e9t\u00e9s<\/em>, vol.\u00a048, n\u00b02, p. 169\u2011193.<\/p>\n<p>Noc\u00e9rino P. (2020), <em>Les auteurs et autrices de bande dessin\u00e9e. La formation contrari\u00e9e d\u2019un groupe social<\/em>, Th\u00e8se de sociologie, sous la direction de C. Lemieux, Paris, ehess.<\/p>\n<hr class=\"wp-block-separator\" \/>\n<p><a href=\"https:\/\/itti.hypotheses.org\/1460#_ftnref1\">[1]<\/a> Ces collectifs peuvent prendre la forme de syndicats (\u00e0 l\u2019image du SNAC-BD cr\u00e9\u00e9 en 2007), d\u2019association (l\u2019association Art\u00e9misia fond\u00e9e en 2007 par Jeanne Puchol et Chantal Montellier pour promouvoir la visibilit\u00e9 du travail des femmes dans la bande dessin\u00e9e) mais \u00e9galement de groupes informels (comme le Collectif des cr\u00e9atrices de bande dessin\u00e9e contre le sexisme cr\u00e9\u00e9 en 2016 ou le collectif Auteurs et Autrices en Action cr\u00e9\u00e9 en 2019). La constitution et les actions de certains de ces collectifs a fait l\u2019objet d\u2019une analyse dans la th\u00e8se de Pierre Noc\u00e9rino (2020).<\/p>\n<p><a href=\"https:\/\/itti.hypotheses.org\/1460#_ftnref2\">[2]<\/a> Selon Jan Baetens (2012), le roman graphique se distingue par sa production (il r\u00e9sulte d\u2019un auteur ou une autrice, et pas d\u2019un \u00e9diteur ou d\u2019un producteur ext\u00e9rieur), son contenu (il aborde des th\u00e8mes destin\u00e9s \u00e0 un public adulte, avec un graphisme souvent distinct des publications destin\u00e9es \u00e0 la jeunesse), sa mat\u00e9rialit\u00e9 (des <em>one-shot<\/em> en noir et blanc aux paginations importantes) et sa r\u00e9ception (notamment via une diffusion dans le circuit traditionnel du livre litt\u00e9raire).<\/p>\n<hr \/>\n<p>Comics is a cultural asset that is particularly appreciated all around the world. Moreover, it also leads its readers to question the work in many ways.<\/p>\n<p>First, comics are used to propose a visual representation of work&#160;: today, numerous publications describe various social realities, including many professional practices (G\u00e9hin, 2018-2019). This phenomenon is accentuated by the emergence of a specific genre&#160;: <a>non-fiction comics<\/a><a href=\"https:\/\/itti.hypotheses.org\/1460#_msocom_1\">[k1]<\/a>\u00a0. This genre, also called \u00ab&#160;comics journalism&#160;\u00bb or \u00ab&#160;<em>bande dessin\u00e9e du r\u00e9el<\/em> [comics about reality]&#160;\u00bb, aims to report various facts in order to make a testimony about any kind of experiences (Lesage, 2017). Non-fiction comics became popular when Art Spiegelman won the Pulitzer Prize in 1992, and later in the wake of the success of Joe Sacco\u2019s books. The popularity of the genre has grown so much that several publishers dedicated specific collections to this type of production, or even created magazines of comics journalism (i.e. <a><em>The Nib<\/em><\/a><a href=\"https:\/\/itti.hypotheses.org\/1460#_msocom_2\">[k2]<\/a>\u00a0, <em>La revue dessin\u00e9e<\/em> and <em>Topo).<\/em><\/p>\n<p>However, if comics question work by picturing it, it also \u2013 and above all \u2013 does it as a social activity. Indeed, the production of these comic books requires a whole set of actors involved in different steps of creation and\/or execution in the publishing process. While authors or publishers can highlight the pleasure they derive from their activity, they also point out the many difficulties in the field&#160;: economic precariousness, pressure to meet deadlines, omnipresent gender discrimination and invisibility of women\u2019s work, lack of recognition from the public or the government, etc. These pleasures and sufferings in the work of professionals have led to social movements and the creation of collectives<a href=\"https:\/\/itti.hypotheses.org\/1460#_ftn1\">[1]<\/a>. But they also are a source of inspiration, whether they are treated head-on (<em>D\u00e9s\u0153uvr\u00e9<\/em> by Lewis Trondheim, <em>A drifting life <\/em>by Yoshihiro Tatsumi, <em>Cases Blanches <\/em>by Olivier Martin and Sylvain Runberg\u2026) or indirectly (<em>The initiates<\/em> by \u00c9tienne Davodeau, <em>Le roi des bourdons <\/em>by David de Thuin, the series <em>l\u2019Atelier Mastodonte <\/em>published in <em>Le Journal de Spirou<\/em>\u2026).<\/p>\n<p>Once again, the evolution of the medium reinforces this phenomenon. Indeed, there has been a growing interest in autobiographical comics, allowing the <a>a<\/a><a>utho<\/a><a href=\"https:\/\/itti.hypotheses.org\/1460#_msocom_3\">[FL3]<\/a>\u00a0r <a href=\"https:\/\/itti.hypotheses.org\/1460#_msocom_4\">[k4]<\/a>\u00a0to put his or her life at the heart of the story. This way, authors activate what Charles Wright Mills (1961) called a sociological information, allowing themselves to situate their biography in the great history. Born in the 1960s in Japan and the United States, autobiographical comics is a genre which strongly increased from the end of the 20th century, whether in fanzines, traditional publishing or webcomics. From this ongoing rise resulted many remarkable productions, especially in Europe, such as books from Marguerite Abouet, Antonio Altarriba, Manu Larcenet, Catherine Meurisse, Marjane Satrapi or Riad Sattouf, among many others.<\/p>\n<p>These two heavy tendencies observed in the comic books market \u2013 documentary concern and autobiographical inspiration \u2013 come together within a broader genre&#160;: the graphic novel. Although this expression may appear problematic due to a vague and allusive definition<a href=\"https:\/\/itti.hypotheses.org\/1460#_ftn2\">[2]<\/a>, it allows us to insist on the deep reflexivity developed along the production of these works. Indeed, whether they are political or not, these publications often relied on thoughts about the approach and the possibilities of the medium, referring to the development of so-called \u00ab&#160;non-fiction&#160;\u00bb literature (Groensteen, 2016). Such an approach thrives on three major sources&#160;: the investigative techniques of the social sciences, the narrative of the self, and the journalistic approach.<\/p>\n<p>This raises the following question&#160;: In what way is the work put into images affected and oriented by the organization and modalities of the comics work&#160;?<\/p>\n<p>This thematic issue of ITTI will examine the articulation between two complementary dimensions&#160;:<\/p>\n<p>\u2013 The first addresses the actors of the sector, their social characteristics, their professional paths, the division of labor, the social relations of production, the modalities of learning and vocational integration, the difficulties encountered to make one\u2019s place, the existence of glass ceilings according to social groups, cultural origins or gender\u2026<\/p>\n<p>\u2013 The second refers to the very content of the productions&#160;: what place does the work takes in it&#160;? What aspects of contemporary work and its evolution are retained\/shown and in what way&#160;? How does the representation of work in comics mirror the way work is organized in the publishing world&#160;?<\/p>\n<p>The articulation between these two poles will serve as a common thread in the construction of the issue of the journal, but it could also, centrally or peripherally, be treated in itself in each contribution.<\/p>\n<p>The issue aims to continue the analysis by offering contributors the opportunity to make proposals for articles in comic forms, particularly in the \u00ab&#160;<em>Images en chantier<\/em> [Images under construction]&#160;\u00bb section of the journal, which aims to publish works that mobilize images in an innovative way. Writing social science in comics indeed reveals the troubles and routines of research work, whether during the collection, the analysis or the restitution of data (Noc\u00e9rino, 2016&#160;; Kuttner, Sousanis and Weaver-Hightower, 2017). In addition to graphic proposals, researchers can also question how the ways in which work is organized allows or, on the contrary, limits the presentation of their own work.<\/p>\n<p>Proposals may come from the various social sciences. They are based on the analysis and\/or production of a corpus of images (including, of course, comics). These images must be reproduced in the article. Please notice that <em>Images du travail, Travail des images<\/em> is an entirely digital, free and open scientific journal. As such, the author must ensure that the rights of image use and distribution are available. The full text will be 30,000 to 50,000 characters maximum. At a first stage, are expected proposals of 2000 to 3000 characters, taking into account the following schedule ,&#160;:<\/p>\n<p>\u2013 <strong>May 31, 2021<\/strong>&#160;: deadline for receipt of proposals by e-mail to the following addresses (proposals may be written in French or English).<\/p>\n<p>\u2013 <strong>December 15, 2021<\/strong>&#160;: sending of articles for submission to the journal\u2019s editorial board (publications must be written in French).<\/p>\n<h2><strong>Contacts for any further information and for the sending of documents&#160;:<\/strong><\/h2>\n<p>\u2013 Jean-Paul G\u00e9hin, University of Poitiers, GRESCO&#160;: jpgehin@gmail.com<\/p>\n<p>\u2013 Fran\u00e7oise F. Laot, University Paris 8 Vincennes-Saint-Denis, EXPERICE, francoise.laot@univ-paris8.fr<\/p>\n<p>\u2013 Pierre Noc\u00e9rino, EHESS, LIER-FYT&#160;: pierre.nocerino@gmail.com<\/p>\n<p>\u2013 La revue Image du travail, travail des images&#160;: imagesdutravail@gmail.com<\/p>\n<hr class=\"wp-block-separator\" \/>\n<p><a href=\"https:\/\/itti.hypotheses.org\/1460#_ftnref1\">[1]<\/a> These collectives can take the form of unions (such as the SNAC-BD created in 2007), associations (Art\u00e9misia founded in 2007 by Jeanne Puchol and Chantal Montellier to promote the visibility of women\u2019s work in comics) but also informal groups (such as the Collective of Comic Book Creators Against Sexism created in 2016 or the collective Auteurs et Autrices en Action created in 2019). The constitution and actions of some of these collectives were analyzed in Pierre Noc\u00e9rino\u2019s thesis (2020).<\/p>\n<p><a href=\"https:\/\/itti.hypotheses.org\/1460#_ftnref2\">[2]<\/a> According to Jan Baetens (2012), the graphic novel is distinguished by its production (it is the work of an author, not of an external publisher or producer), its content (it deals with themes intended for an adult audience, with a graphic design often distinct from publications intended for young people), its materiality (black and white one-shot with extensive paginations) and its reception (it is usually distributed in the in the traditional literary book circuit).<\/p>\n<\/p><\/div>\n<div class=\"zn-singledetail-keywords\">\n<h3 class=\"zn-singledetail-section-title\">Mots-cl\u00e9s<\/h3>\n<ul class=\"termslist termslist-post_tag\">\n<li class=\"termslist-item termslist-title\"><span class=\"termslist-titletxt\">Mots-cl\u00e9s<\/span><span class=\"doubledot\"><\/span><\/li>\n<li class=\"termslist-item tax-post_tag term-bande-dessinee\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/comics\/\" title=\"Bande dessin\u00e9e\"><span class=\"termslist-itemname\">Bande dessin\u00e9e<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-image\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/image-en\/\" title=\"Image\"><span class=\"termslist-itemname\">Image<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-mediation\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/mediation-en\/\" title=\"M\u00e9diation\"><span class=\"termslist-itemname\">M\u00e9diation<\/span><\/a><\/li>\n<li class=\"termslist-item tax-post_tag term-travail\"><a class=\"termslist-itemlink\" href=\"https:\/\/www.sfsic.org\/en\/tag\/work\/\" title=\"Travail\"><span class=\"termslist-itemname\">Travail<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- \/fxzn:singledetail --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis en ligne le 9 mars 2021 Th\u00e9matiques Images, cin\u00e9ma, m\u00e9dias audiovisuels et industries culturelles M\u00e9diations m\u00e9morielles, culturelles et patrimoniales R\u00e9ponse attendue pour le 31\/05\/2021 Type de r\u00e9ponse R\u00e9sum\u00e9 Type [&hellip;]<\/p>\n","protected":false},"author":781,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,60],"tags":[377,165,129,109],"thematique":[35,38],"sfsic":[],"class_list":["post-16105","post","type-post","status-publish","format-standard","hentry","category-aac-publication","category-article","tag-bande-dessinee","tag-image","tag-mediation","tag-travail","thematique-images-cinema-medias-audiovisuels-et-industries-culturelles","thematique-mediations-memorielles-culturelles-et-patrimoniales","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BD et romans graphiques au travail<\/title>\n<meta name=\"description\" content=\"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me &quot;BD et romans graphiques au travail&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BD et romans graphiques au travail\" \/>\n<meta property=\"og:description\" content=\"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me &quot;BD et romans graphiques au travail&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/\" \/>\n<meta property=\"og:site_name\" content=\"SFSIC\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T11:24:27+00:00\" \/>\n<meta name=\"author\" content=\"Axelle Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/\"},\"author\":{\"name\":\"Axelle Martin\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\"},\"headline\":\"BD et romans graphiques au travail\",\"datePublished\":\"2021-03-15T11:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/\"},\"wordCount\":2913,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"keywords\":[\"Bande dessin\u00e9e\",\"Image\",\"M\u00e9diation\",\"Travail\"],\"articleSection\":[\"AAC Publications\",\"Article\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/\",\"name\":\"BD et romans graphiques au travail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\"},\"datePublished\":\"2021-03-15T11:24:27+00:00\",\"description\":\"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me \\\"BD et romans graphiques au travail\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/aac-publication\\\/bd-et-romans-graphiques-au-travail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calls for Papers\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article\",\"item\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/cfp-publication\\\/article-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"BD et romans graphiques au travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"name\":\"SFSIC\",\"description\":\"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#organization\",\"name\":\"SFSIC\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sfsic.org\\\/wp-inside\\\/uploads\\\/2020\\\/05\\\/logo-sfsic.jpg\",\"width\":1085,\"height\":1080,\"caption\":\"SFSIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sfsic.org\\\/en\\\/#\\\/schema\\\/person\\\/d3606993477708f4359fb9aeda58df3b\",\"name\":\"Axelle Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g\",\"caption\":\"Axelle Martin\"},\"sameAs\":[\"@antropocominside\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BD et romans graphiques au travail","description":"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me \"BD et romans graphiques au travail\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/","og_locale":"en_US","og_type":"article","og_title":"BD et romans graphiques au travail","og_description":"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me \"BD et romans graphiques au travail\".","og_url":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/","og_site_name":"SFSIC","article_published_time":"2021-03-15T11:24:27+00:00","author":"Axelle Martin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/#article","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/"},"author":{"name":"Axelle Martin","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b"},"headline":"BD et romans graphiques au travail","datePublished":"2021-03-15T11:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/"},"wordCount":2913,"publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"keywords":["Bande dessin\u00e9e","Image","M\u00e9diation","Travail"],"articleSection":["AAC Publications","Article"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/","url":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/","name":"BD et romans graphiques au travail","isPartOf":{"@id":"https:\/\/www.sfsic.org\/en\/#website"},"datePublished":"2021-03-15T11:24:27+00:00","description":"La revue Images du travail, travail des images lance un appel \u00e0 article pour un dossier coordonn\u00e9 par Jean-Paul G\u00e9hin, Fran\u00e7oise F. Laot et Pierre Noc\u00e9rino sur le th\u00e8me \"BD et romans graphiques au travail\".","breadcrumb":{"@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sfsic.org\/en\/aac-publication\/bd-et-romans-graphiques-au-travail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sfsic.org\/en\/"},{"@type":"ListItem","position":2,"name":"Calls for Papers","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/"},{"@type":"ListItem","position":3,"name":"Article","item":"https:\/\/www.sfsic.org\/en\/cfp-publication\/article-en\/"},{"@type":"ListItem","position":4,"name":"BD et romans graphiques au travail"}]},{"@type":"WebSite","@id":"https:\/\/www.sfsic.org\/en\/#website","url":"https:\/\/www.sfsic.org\/en\/","name":"SFSIC","description":"Soci\u00e9t\u00e9 Fran\u00e7aise des Sciences de l&#039;Information &amp; de la Communication","publisher":{"@id":"https:\/\/www.sfsic.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sfsic.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sfsic.org\/en\/#organization","name":"SFSIC","url":"https:\/\/www.sfsic.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","contentUrl":"https:\/\/www.sfsic.org\/wp-inside\/uploads\/2020\/05\/logo-sfsic.jpg","width":1085,"height":1080,"caption":"SFSIC"},"image":{"@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.sfsic.org\/en\/#\/schema\/person\/d3606993477708f4359fb9aeda58df3b","name":"Axelle Martin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1065035eb5e480668fbf77e163c2e86f81ac342eaad4c8783acdf4a63f3c917b?s=96&d=mm&r=g","caption":"Axelle Martin"},"sameAs":["@antropocominside"]}]}},"_links":{"self":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/16105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/users\/781"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/comments?post=16105"}],"version-history":[{"count":4,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/16105\/revisions"}],"predecessor-version":[{"id":16109,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/posts\/16105\/revisions\/16109"}],"wp:attachment":[{"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/media?parent=16105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/categories?post=16105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/tags?post=16105"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/thematique?post=16105"},{"taxonomy":"sfsic","embeddable":true,"href":"https:\/\/www.sfsic.org\/en\/wp-json\/wp\/v2\/sfsic?post=16105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}